{"id":2697,"date":"2021-12-23T12:00:43","date_gmt":"2021-12-23T11:00:43","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=2697"},"modified":"2021-12-23T12:00:43","modified_gmt":"2021-12-23T11:00:43","slug":"il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/","title":{"rendered":"IL PRESIDENTE DELLA REGIONE FIRMA L&#8217;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12"},"content":{"rendered":"<p>L\u2019ordinanza entra in vigore\u00a0<strong>gioved\u00ec 23 dicembre sul tutto il territorio della Regione Lazio<\/strong>\u00a0e nello specifico prevede:<\/p>\n<p>1.\u00a0<strong>A decorrere dalle ore 00:00 del 23 dicembre 2021 e fino alle 24:00 del 23 gennaio 2022 \u00e8 disposto l\u2019obbligo, su tutto il territorio regionale, di indossare la mascherina di protezione<\/strong>\u00a0individuale nei luoghi all\u2019aperto, durante l\u2019intera giornata, ferme restando le disposizioni vigenti in materia di Certificazione Verde Covid-19;<\/p>\n<p>2. Per tutta la durata della presente ordinanza, \u00e8 disposto l\u2019aumento della frequenza dello screening del personale sanitario e sociosanitario operante nelle strutture sanitarie, pubbliche e private prevedendo l\u2019esecuzione di un test con periodicit\u00e0 non superiore ai 10 giorni, al fine di intercettare tempestivamente eventuali casi positivi, fermi restando gli ulteriori obblighi previsti dalla stratificazione del rischio in capo all&#8217;Azienda Sanitaria o Struttura sanitaria.<\/p>\n<p>3. L\u2019esenzione dall\u2019obbligo di cui al punto 1. \u00e8 prevista per i bambini con et\u00e0 inferiore a sei anni, per i portatori di patologie incompatibili con l\u2019uso della mascherina e nel corso dell\u2019esercizio all\u2019aperto di attivit\u00e0 motorie e\/o sportive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ordinanza entra in vigore\u00a0gioved\u00ec 23 dicembre sul tutto il territorio della Regione Lazio\u00a0e nello specifico prevede: 1.\u00a0A decorrere dalle ore 00:00 del 23 dicembre 2021 e fino alle 24:00 del [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":2698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL PRESIDENTE DELLA REGIONE FIRMA L&#039;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL PRESIDENTE DELLA REGIONE FIRMA L&#039;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"L\u2019ordinanza entra in vigore\u00a0gioved\u00ec 23 dicembre sul tutto il territorio della Regione Lazio\u00a0e nello specifico prevede: 1.\u00a0A decorrere dalle ore 00:00 del 23 dicembre 2021 e fino alle 24:00 del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T11:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"IL PRESIDENTE DELLA REGIONE FIRMA L&#8217;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\\\/12\",\"datePublished\":\"2021-12-23T11:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/\"},\"wordCount\":186,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/\",\"name\":\"IL PRESIDENTE DELLA REGIONE FIRMA L'ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\\\/12 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg\",\"datePublished\":\"2021-12-23T11:00:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg\",\"width\":720,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/12\\\/23\\\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL PRESIDENTE DELLA REGIONE FIRMA L&#8217;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\\\/12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL PRESIDENTE DELLA REGIONE FIRMA L'ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/","og_locale":"it_IT","og_type":"article","og_title":"IL PRESIDENTE DELLA REGIONE FIRMA L'ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12 - Marcellina","og_description":"L\u2019ordinanza entra in vigore\u00a0gioved\u00ec 23 dicembre sul tutto il territorio della Regione Lazio\u00a0e nello specifico prevede: 1.\u00a0A decorrere dalle ore 00:00 del 23 dicembre 2021 e fino alle 24:00 del [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-12-23T11:00:43+00:00","og_image":[{"width":720,"height":718,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"IL PRESIDENTE DELLA REGIONE FIRMA L&#8217;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12","datePublished":"2021-12-23T11:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/"},"wordCount":186,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/","url":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/","name":"IL PRESIDENTE DELLA REGIONE FIRMA L'ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg","datePublished":"2021-12-23T11:00:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/12\/WhatsApp-Image-2021-12-22-at-14.39.19.jpeg","width":720,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/12\/23\/il-presidente-della-regione-firma-lordinanza-per-mascherine-all-aperto-in-tutto-il-lazio-in-vigore-da-giovedi-23-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"IL PRESIDENTE DELLA REGIONE FIRMA L&#8217;ORDINANZA PER MASCHERINE ALL\u2019 APERTO IN TUTTO IL LAZIO. IN VIGORE DA GIOVED\u00cc 23\/12"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=2697"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2697\/revisions"}],"predecessor-version":[{"id":2699,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2697\/revisions\/2699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/2698"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=2697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=2697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=2697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}