{"id":289,"date":"2019-01-28T11:44:17","date_gmt":"2019-01-28T10:44:17","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=289"},"modified":"2019-01-28T11:44:17","modified_gmt":"2019-01-28T10:44:17","slug":"servizi-sociali-avviso-pubblico-home-care-alzheimer-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/","title":{"rendered":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019"},"content":{"rendered":"<p>Programma Integrato Sovradistrettuale per i malati di Alzheimer e altre demenze e loro familiari, denominato:\u00a0<strong>HOME CARE ALZHEIMER<\/strong><br \/>\nnell\u2019ambito degli interventi di cui alla D.G.R. del 17 ottobre 2012, n. 504, e della Determinazione Dirigenziale della\u00a0Regione Lazio n. B08785 del 12 novembre 2012.<\/p>\n<p>Possono inoltrare domanda di concessione del beneficio le persone affette dalla malattia di\u00a0<strong>Alzheimer e malati con\u00a0deterioramento cognitivo<\/strong>\u00a0dovuto alle diverse forme di demenza Alzheimer e non Alzheimer secondo anche quanto\u00a0riporta la legge sulle demenze (esclusa la demenza senile) residenti nei Comuni dei Distretti RM 5.1 e RM 5.2; a tal fine\u00a0<strong>saranno erogate prestazioni economiche con specifico riferimento ad interventi domiciliari gestiti in forma indiretta<\/strong>\u00a0con la formulazione di un P.A.I. (Piano Assistenziale Individualizzato).<\/p>\n<p>Il beneficio economico ha la durata di un anno presumibilmente da Aprile 2019 a Marzo 2020.<\/p>\n<p>La richiesta di contributo economico potr\u00e0 essere presentata su apposita modulistica e consegnata a mano o a mezzo posta con R\/R o via PEC all\u2019ufficio protocollo del proprio comune di residenza,<strong>\u00a0entro e non oltre le\u00a0ore 12,00 del giorno 28 febbraio 2019<\/strong>.<\/p>\n<p>Avviso integrale e modulistica in allegato.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_290\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/AVVISO-PUBBLICO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/AVVISO-PUBBLICO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO PUBBLICO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_291\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/Home-Care-Alzheimer.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/Home-Care-Alzheimer.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Home Care Alzheimer<\/a><\/li>\n<li><a id=\"wpba_attachment_list_292\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/Modulistica.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/Modulistica.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulistica<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Programma Integrato Sovradistrettuale per i malati di Alzheimer e altre demenze e loro familiari, denominato:\u00a0HOME CARE ALZHEIMER nell\u2019ambito degli interventi di cui alla D.G.R. del 17 ottobre 2012, n. 504, [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Programma Integrato Sovradistrettuale per i malati di Alzheimer e altre demenze e loro familiari, denominato:\u00a0HOME CARE ALZHEIMER nell\u2019ambito degli interventi di cui alla D.G.R. del 17 ottobre 2012, n. 504, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-28T10:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png\" \/>\n\t<meta property=\"og:image:width\" content=\"401\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019\",\"datePublished\":\"2019-01-28T10:44:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/\"},\"wordCount\":188,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/01\\\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/\",\"name\":\"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/01\\\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png\",\"datePublished\":\"2019-01-28T10:44:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/01\\\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/01\\\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png\",\"width\":401,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/01\\\/28\\\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina","og_description":"Programma Integrato Sovradistrettuale per i malati di Alzheimer e altre demenze e loro familiari, denominato:\u00a0HOME CARE ALZHEIMER nell\u2019ambito degli interventi di cui alla D.G.R. del 17 ottobre 2012, n. 504, [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-28T10:44:17+00:00","og_image":[{"width":401,"height":400,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019","datePublished":"2019-01-28T10:44:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/"},"wordCount":188,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/","name":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png","datePublished":"2019-01-28T10:44:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/01\/SPLASH2_NEWS_SERSOC_alzheimer_CC.png","width":401,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/01\/28\/servizi-sociali-avviso-pubblico-home-care-alzheimer-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"SERVIZI SOCIALI: avviso pubblico, Home Care Alzheimer 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/289\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/289\/revisions\/294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/293"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}