{"id":2892,"date":"2022-06-01T17:25:39","date_gmt":"2022-06-01T15:25:39","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=2892"},"modified":"2022-06-01T17:25:39","modified_gmt":"2022-06-01T15:25:39","slug":"ambiente-variazione-della-raccolta-differenziata-per-le-festivita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/","title":{"rendered":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0"},"content":{"rendered":"<p>\u274c\u00a0<strong>GIOVED\u00cc 02 GIUGNO 2022: NESSUNA RACCOLTA<\/strong><br \/>\n\u2705\u00a0<strong>VENERD\u00cc 03 GIUGNO 2022:<\/strong><strong>RIFIUTO UMIDO<\/strong>\u00a0(Scarti alimentari e organici)<br \/>\n\u2705\u00a0<strong>SABATO 04 GIUGNO 2022: \u00a0INDIFFERENZIATO<\/strong><\/p>\n<p>Dal giorno 06.05.2022 il servizio di raccolta rifiuti riprender\u00e0 regolarmente secondo il calendario usuale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u274c\u00a0GIOVED\u00cc 02 GIUGNO 2022: NESSUNA RACCOLTA \u2705\u00a0VENERD\u00cc 03 GIUGNO 2022:RIFIUTO UMIDO\u00a0(Scarti alimentari e organici) \u2705\u00a0SABATO 04 GIUGNO 2022: \u00a0INDIFFERENZIATO Dal giorno 06.05.2022 il servizio di raccolta rifiuti riprender\u00e0 regolarmente secondo [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":2606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"\u274c\u00a0GIOVED\u00cc 02 GIUGNO 2022: NESSUNA RACCOLTA \u2705\u00a0VENERD\u00cc 03 GIUGNO 2022:RIFIUTO UMIDO\u00a0(Scarti alimentari e organici) \u2705\u00a0SABATO 04 GIUGNO 2022: \u00a0INDIFFERENZIATO Dal giorno 06.05.2022 il servizio di raccolta rifiuti riprender\u00e0 regolarmente secondo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T15:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0\",\"datePublished\":\"2022-06-01T15:25:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/\"},\"wordCount\":36,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/10\\\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/\",\"name\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/10\\\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png\",\"datePublished\":\"2022-06-01T15:25:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/10\\\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/10\\\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2022\\\/06\\\/01\\\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/","og_locale":"it_IT","og_type":"article","og_title":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina","og_description":"\u274c\u00a0GIOVED\u00cc 02 GIUGNO 2022: NESSUNA RACCOLTA \u2705\u00a0VENERD\u00cc 03 GIUGNO 2022:RIFIUTO UMIDO\u00a0(Scarti alimentari e organici) \u2705\u00a0SABATO 04 GIUGNO 2022: \u00a0INDIFFERENZIATO Dal giorno 06.05.2022 il servizio di raccolta rifiuti riprender\u00e0 regolarmente secondo [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-06-01T15:25:39+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0","datePublished":"2022-06-01T15:25:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/"},"wordCount":36,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/","url":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/","name":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png","datePublished":"2022-06-01T15:25:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/10\/SPLASH_NEWS_ambiente_variaRaccolta.10.2021_TW.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2022\/06\/01\/ambiente-variazione-della-raccolta-differenziata-per-le-festivita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA PER LE FESTIVIT\u00c0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=2892"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2892\/revisions"}],"predecessor-version":[{"id":2894,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2892\/revisions\/2894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/2606"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=2892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=2892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=2892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}