{"id":3183,"date":"2023-10-31T18:02:15","date_gmt":"2023-10-31T17:02:15","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3183"},"modified":"2023-10-31T18:02:15","modified_gmt":"2023-10-31T17:02:15","slug":"ambiente-variazione-della-raccolta-differenziata-del-1-novembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/","title":{"rendered":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE"},"content":{"rendered":"<p>Si comunica la variazione della Raccolta differenziata porta a porta per la festivit\u00e0 del 1\u00b0 novembre:<\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/274c.svg\" alt=\"\u274c\" \/><strong>\u00a0MERCOLED\u00cd 1\u00b0 NOVEMBRE 2023: N<\/strong><strong>ESSUNA RACCOLTA<\/strong><br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/2705.svg\" alt=\"\u2705\" \/><strong>\u00a0GIOVED\u00cd<\/strong><strong>\u00a02 NOVEMBRE 2023: RIFIUTO UMIDO + PLASTICA (<\/strong><strong>RECUPERO)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica la variazione della Raccolta differenziata porta a porta per la festivit\u00e0 del 1\u00b0 novembre: \u00a0MERCOLED\u00cd 1\u00b0 NOVEMBRE 2023: NESSUNA RACCOLTA \u00a0GIOVED\u00cd\u00a02 NOVEMBRE 2023: RIFIUTO UMIDO + PLASTICA (RECUPERO)<\/p>\n","protected":false},"author":283,"featured_media":3135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica la variazione della Raccolta differenziata porta a porta per la festivit\u00e0 del 1\u00b0 novembre: \u00a0MERCOLED\u00cd 1\u00b0 NOVEMBRE 2023: NESSUNA RACCOLTA \u00a0GIOVED\u00cd\u00a02 NOVEMBRE 2023: RIFIUTO UMIDO + PLASTICA (RECUPERO)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-31T17:02:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE\",\"datePublished\":\"2023-10-31T17:02:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2023\\\/06\\\/NEWS_AMB_variaRaccolta_TW.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/\",\"name\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2023\\\/06\\\/NEWS_AMB_variaRaccolta_TW.png\",\"datePublished\":\"2023-10-31T17:02:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2023\\\/06\\\/NEWS_AMB_variaRaccolta_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2023\\\/06\\\/NEWS_AMB_variaRaccolta_TW.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2023\\\/10\\\/31\\\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/","og_locale":"it_IT","og_type":"article","og_title":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina","og_description":"Si comunica la variazione della Raccolta differenziata porta a porta per la festivit\u00e0 del 1\u00b0 novembre: \u00a0MERCOLED\u00cd 1\u00b0 NOVEMBRE 2023: NESSUNA RACCOLTA \u00a0GIOVED\u00cd\u00a02 NOVEMBRE 2023: RIFIUTO UMIDO + PLASTICA (RECUPERO)","og_url":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-10-31T17:02:15+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE","datePublished":"2023-10-31T17:02:15+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/"},"wordCount":33,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/","url":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/","name":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png","datePublished":"2023-10-31T17:02:15+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2023\/06\/NEWS_AMB_variaRaccolta_TW.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2023\/10\/31\/ambiente-variazione-della-raccolta-differenziata-del-1-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AMBIENTE: VARIAZIONE DELLA RACCOLTA DIFFERENZIATA DEL 1\u00b0 NOVEMBRE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3183"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3183\/revisions"}],"predecessor-version":[{"id":3184,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3183\/revisions\/3184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3135"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}