{"id":3223,"date":"2024-02-09T12:56:47","date_gmt":"2024-02-09T11:56:47","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3223"},"modified":"2024-02-09T12:56:47","modified_gmt":"2024-02-09T11:56:47","slug":"avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/","title":{"rendered":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA"},"content":{"rendered":"<p>Si comunica, con Ordinanza n\u00b0 4 del R.D.S., che da giorno luned\u00ec\u00a0<strong>12 febbraio 2024<\/strong>, verranno apportate delle modifiche sul senso di marcia come da segnaletica apposta nelle seguenti strade:<\/p>\n<ul>\n<li><strong>VIA ALESSANDRO MANZONI<\/strong><\/li>\n<li><strong>PIAZZA BADEN POWELL\u00a0<\/strong><\/li>\n<li><strong>VIA INDIPENDENZA\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica, con Ordinanza n\u00b0 4 del R.D.S., che da giorno luned\u00ec\u00a012 febbraio 2024, verranno apportate delle modifiche sul senso di marcia come da segnaletica apposta nelle seguenti strade: VIA [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-3223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica, con Ordinanza n\u00b0 4 del R.D.S., che da giorno luned\u00ec\u00a012 febbraio 2024, verranno apportate delle modifiche sul senso di marcia come da segnaletica apposta nelle seguenti strade: VIA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T11:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA\",\"datePublished\":\"2024-02-09T11:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/\"},\"wordCount\":54,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/02\\\/NEWS_avviso_sensodimarcia_TW.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/\",\"name\":\"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/02\\\/NEWS_avviso_sensodimarcia_TW.png\",\"datePublished\":\"2024-02-09T11:56:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/02\\\/NEWS_avviso_sensodimarcia_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/02\\\/NEWS_avviso_sensodimarcia_TW.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/02\\\/09\\\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina","og_description":"Si comunica, con Ordinanza n\u00b0 4 del R.D.S., che da giorno luned\u00ec\u00a012 febbraio 2024, verranno apportate delle modifiche sul senso di marcia come da segnaletica apposta nelle seguenti strade: VIA [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-02-09T11:56:47+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA","datePublished":"2024-02-09T11:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/"},"wordCount":54,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/","url":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/","name":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png","datePublished":"2024-02-09T11:56:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/02\/NEWS_avviso_sensodimarcia_TW.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/02\/09\/avviso-dal-12-febbraio-2024-modifica-del-senso-di-marcia-in-via-manzoni-piazza-b-powell-e-via-indipendenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AVVISO: DAL 12 FEBBRAIO 2024 MODIFICA DEL SENSO DI MARCIA IN VIA MANZONI, PIAZZA B. POWELL E VIA INDIPENDENZA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"12"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3223"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3223\/revisions"}],"predecessor-version":[{"id":3225,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3223\/revisions\/3225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3224"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}