{"id":3397,"date":"2024-09-26T15:20:05","date_gmt":"2024-09-26T13:20:05","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3397"},"modified":"2024-09-26T15:20:05","modified_gmt":"2024-09-26T13:20:05","slug":"avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/","title":{"rendered":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024"},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p>In relazione al fenomeno acustico (boato) percepito a\u00a0<strong>Marcellina (Roma)<\/strong>\u00a0il giorno\u00a0<strong>gioved\u00ec 12 settembre<\/strong>\u00a0<strong>2024<\/strong>\u00a0alle\u00a0<strong>ore 12<\/strong>\u00a0circa, l&#8217;Amministrazione Comunale si \u00e8 adoperata immediatamente per avere approfondimenti in merito attraverso gli esperti degli organi deputati al controllo geologico, richiedendo anche supporto alla Citt\u00e0 metropolitana di Roma Capitale, che ha attiva una collaborazione sul tema con l&#8217;Istituto Nazionale di Geofisica e Vulcanologia- INGV, allo scopo di accertare la natura del fenomeno, che ad oggi non risulta aver prodotto alcun effetto permanente al suolo o agli edifici.<\/p>\n<p>A tal fine si richiede la collaborazione della cittadinanza alle attivit\u00e0 conoscitive, compilando il\u00a0<strong>questionario anonimo online &#8220;<\/strong><i><strong>Hai sentito il terremoto?<\/strong><\/i><strong>&#8221;\u00a0<\/strong>sul sito dell&#8217;Istituto Nazionale di Geofisica e Vulcanologia- INGV, tramite il link\u00a0<a href=\"https:\/\/www.hsit.it\/compile.html\">https:\/\/www.hsit.it\/compile.html<\/a><\/p>\n<p>L&#8217;operazione pu\u00f2 essere effettuata facilmente dal proprio computer in poco tempo, ed un numero elevato di informazioni pu\u00f2 essere di aiuto nello studio del fenomeno.<\/p>\n<p>Si specifica al riguardo che il fenomeno locale non \u00e8 stato registrato dalla rete sismica nazionale e pertanto il questionario andr\u00e0 compilato nel modo seguente:<\/p>\n<ul>\n<li>nel primo campo \u201cSeleziona il terremoto dalla lista\u201d dovr\u00e0 essere scelta l\u2019opzione \u201cTerremoto non in lista\u201d<\/li>\n<li>nel campo \u201cData del terremoto\u201d si deve utilizzare il formato dd-mm-aaaa inserendo la data\u00a0<strong>12-09-2024<\/strong><\/li>\n<li>nel campo \u201cOrario del terremoto\u201d, non disponendo di misure strumentali o dati precisi, andr\u00e0 indicato convenzionalmente nel formato hh:mm l\u2019orario\u00a0<strong>11:00<\/strong><\/li>\n<li>nei campi all\u2019interno di \u201cDove ti trovavi\u201d si dovranno inserire l\u2019indirizzo completo e le altre informazioni circa il luogo in cui ci si trovava al momento in cui il rumore \u00e8 stato percepito<\/li>\n<li>alla domanda \u201cHai avvertito il terremoto o osservato i suoi effetti?\u201d rispondere \u201c<strong>S\u00ec<\/strong>\u201d<\/li>\n<li>successivamente, nel campo \u201cDescrivi la tua esperienza\u201d sar\u00e0 necessario selezionare una risposta (in caso, anche negativa) nel primo campo \u201cVibrazione o scuotimento\u201d e compilare il sottocampo \u201cRUMORE\u201d, inserendo in caso positivo l\u2019opzione \u201csentito\u201d, che consente di fornire dettagli in un ulteriore campo dedicato \u201cDescrizione del rumore del terremoto\u201d<\/li>\n<\/ul>\n<p>Si auspica la massima partecipazione, con preghiera di attenersi alle indicazioni suddette, trattandosi di un fenomeno in cui l\u2019effetto acustico (boato) appare essere l\u2019unica manifestazione rilevata.<\/p>\n<p>Grazie per la collaborazione<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>In relazione al fenomeno acustico (boato) percepito a\u00a0Marcellina (Roma)\u00a0il giorno\u00a0gioved\u00ec 12 settembre\u00a02024\u00a0alle\u00a0ore 12\u00a0circa, l&#8217;Amministrazione Comunale si \u00e8 adoperata immediatamente per avere approfondimenti in merito attraverso gli esperti degli organi deputati [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"In relazione al fenomeno acustico (boato) percepito a\u00a0Marcellina (Roma)\u00a0il giorno\u00a0gioved\u00ec 12 settembre\u00a02024\u00a0alle\u00a0ore 12\u00a0circa, l&#8217;Amministrazione Comunale si \u00e8 adoperata immediatamente per avere approfondimenti in merito attraverso gli esperti degli organi deputati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T13:20:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024\",\"datePublished\":\"2024-09-26T13:20:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/\"},\"wordCount\":362,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/09\\\/NEWS_AMM_Comunicazioni.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/\",\"name\":\"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/09\\\/NEWS_AMM_Comunicazioni.jpg\",\"datePublished\":\"2024-09-26T13:20:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/09\\\/NEWS_AMM_Comunicazioni.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2024\\\/09\\\/NEWS_AMM_Comunicazioni.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2024\\\/09\\\/26\\\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina","og_description":"In relazione al fenomeno acustico (boato) percepito a\u00a0Marcellina (Roma)\u00a0il giorno\u00a0gioved\u00ec 12 settembre\u00a02024\u00a0alle\u00a0ore 12\u00a0circa, l&#8217;Amministrazione Comunale si \u00e8 adoperata immediatamente per avere approfondimenti in merito attraverso gli esperti degli organi deputati [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-26T13:20:05+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024","datePublished":"2024-09-26T13:20:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/"},"wordCount":362,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/","url":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/","name":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg","datePublished":"2024-09-26T13:20:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2024\/09\/NEWS_AMM_Comunicazioni.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2024\/09\/26\/avviso-alla-cittadinanza-riguardo-il-boato-del-12-settembre-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Avviso alla Cittadinanza riguardo il boato del 12 settembre 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"12"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3397"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3397\/revisions"}],"predecessor-version":[{"id":3398,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3397\/revisions\/3398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}