{"id":3508,"date":"2025-01-27T08:13:54","date_gmt":"2025-01-27T07:13:54","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3508"},"modified":"2025-01-27T08:13:54","modified_gmt":"2025-01-27T07:13:54","slug":"giorno-della-memoria-per-non-dimenticare-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/","title":{"rendered":"Giorno della Memoria &#8211; Per non dimenticare."},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p>Nell\u2019anniversario dell\u2019abbattimento dei cancelli del campo di concentramento di Auschwitz-Birkenau (27 gennaio 1945), il Comune di Marcellina commemora la Shoah del popolo ebraico e tutte le vittime dei campi di sterminio nazisti.<\/p>\n<p>Quest\u2019anno, recependo le disposizioni della Presidenza del Consiglio dei Ministri, luned\u00ec 27 gennaio le bandiere della sede comunale saranno esposte a mezz\u2019asta.<\/p>\n<p>L\u2019Amministrazione comunale, in collaborazione con l\u2019Istituto Comprensivo Marcellina, <strong>nella mattinata di luned\u00ec 27 gennaio presso la biblioteca comunale<\/strong>, ha organizzato per gli studenti delle classi terze della Scuola Secondaria di primo grado la presentazione del libro \u201cLo spirito nel pero\u201d del nostro concittadino Olimpio Giosi. Il lavoro \u00e8 frutto della traduzione del diario di alcuni prigionieri di guerra sudafricani che si nascosero nelle nostre zone montane dal settembre 1943 al giugno 1944 e racconta le difficolt\u00e0, gli escamotage per la sopravvivenza adottati dai fuggitivi e la solidariet\u00e0 della popolazione di Marcellina.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Il Sindaco<\/strong><br \/>\n<i>Alessandro Lundini<\/i><\/p>\n<p><strong>L&#8217;Assessore alla Cultura e alla Pubblica Istruzione<\/strong><br \/>\n<i>Alessandra Danieli<\/i><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019anniversario dell\u2019abbattimento dei cancelli del campo di concentramento di Auschwitz-Birkenau (27 gennaio 1945), il Comune di Marcellina commemora la Shoah del popolo ebraico e tutte le vittime dei campi di [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giorno della Memoria - Per non dimenticare. - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giorno della Memoria - Per non dimenticare. - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Nell\u2019anniversario dell\u2019abbattimento dei cancelli del campo di concentramento di Auschwitz-Birkenau (27 gennaio 1945), il Comune di Marcellina commemora la Shoah del popolo ebraico e tutte le vittime dei campi di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T07:13:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Giorno della Memoria &#8211; Per non dimenticare.\",\"datePublished\":\"2025-01-27T07:13:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/01\\\/NEWS_BANDI_giorno.della_.memoria.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/\",\"name\":\"Giorno della Memoria - Per non dimenticare. - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/01\\\/NEWS_BANDI_giorno.della_.memoria.jpg\",\"datePublished\":\"2025-01-27T07:13:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/01\\\/NEWS_BANDI_giorno.della_.memoria.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/01\\\/NEWS_BANDI_giorno.della_.memoria.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-per-non-dimenticare-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giorno della Memoria &#8211; Per non dimenticare.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giorno della Memoria - Per non dimenticare. - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/","og_locale":"it_IT","og_type":"article","og_title":"Giorno della Memoria - Per non dimenticare. - Marcellina","og_description":"Nell\u2019anniversario dell\u2019abbattimento dei cancelli del campo di concentramento di Auschwitz-Birkenau (27 gennaio 1945), il Comune di Marcellina commemora la Shoah del popolo ebraico e tutte le vittime dei campi di [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-01-27T07:13:54+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Giorno della Memoria &#8211; Per non dimenticare.","datePublished":"2025-01-27T07:13:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/"},"wordCount":165,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/","name":"Giorno della Memoria - Per non dimenticare. - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg","datePublished":"2025-01-27T07:13:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/01\/NEWS_BANDI_giorno.della_.memoria.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/01\/27\/giorno-della-memoria-per-non-dimenticare-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Giorno della Memoria &#8211; Per non dimenticare."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"12"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3508"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3508\/revisions"}],"predecessor-version":[{"id":3510,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3508\/revisions\/3510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3509"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}