{"id":3532,"date":"2025-02-14T12:50:07","date_gmt":"2025-02-14T11:50:07","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3532"},"modified":"2025-02-14T12:50:07","modified_gmt":"2025-02-14T11:50:07","slug":"carnevale-marcellinese-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/","title":{"rendered":"CARNEVALE MARCELLINESE 2025"},"content":{"rendered":"<p>In occasione della festa di Carnevale, il Comune di Marcellina ha organizzato una \u201c<strong>SFILATA IN MASCHERA<\/strong>\u201d <strong>nelle giornate di gioved\u00ec 27 Febbraio e domenica 2 Marzo 2025<\/strong>.<\/p>\n<p>Il corteo di Carnevale che coinvolger\u00e0 carri allegorici e gruppi mascherati partir\u00e0 alle ore 15.00 da Piazza Martiri delle Foibe (Piazza Mercato) e sfiler\u00e0 per le vie principali del paese per poi tornare a Piazza Martiri delle Foibe (Piazza Mercato).<\/p>\n<p>L\u2019Amministrazione Comunale ringrazia per la partecipazione alla sfilata la Scuola dell\u2019Infanzia, la Scuola Primaria dell\u2019ISTITUTO COMPRENSIVO MARCELLINA e l\u2019Asilo nido Operazione Biberon, la Pro Loco APS per aver offerto i coriandoli, l\u2019Associazione \u201cIMPEGNO COMUNE ONLUS\u201d, i GENITORI e i CITTADINI che hanno realizzato i carri allegorici, la CONFRATERNITA di Sant&#8217;Antonio Abate per la PUPAZZA, il Centro Sociale Anziani APS, le Majorettes della Banda musicale di Marcellina, All event animazione e, per il supporto operativo e organizzativo, le Associazioni ANC Sezione Marcellina, A.R.F.I Delegazione di Marcellina, RANGER ETS-ODV Nucleo di Marcellina e l\u2019Associazione Nazionale Bersaglieri &#8211; Sezione Marcellina.<\/p>\n<p><strong>Il Sindaco<br \/>\n<\/strong><i>Alessandro Lundini<\/i><\/p>\n<p><strong>L&#8217;Assessore alla Cultura e alla Pubblica Istruzione<br \/>\n<\/strong><i>Alessandra Danieli<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3534\" src=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download-724x1024.jpeg\" alt=\"\" width=\"640\" height=\"905\" srcset=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download-724x1024.jpeg 724w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download-212x300.jpeg 212w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download-768x1086.jpeg 768w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download-1086x1536.jpeg 1086w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/download.jpeg 1240w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della festa di Carnevale, il Comune di Marcellina ha organizzato una \u201cSFILATA IN MASCHERA\u201d nelle giornate di gioved\u00ec 27 Febbraio e domenica 2 Marzo 2025. Il corteo di [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CARNEVALE MARCELLINESE 2025 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CARNEVALE MARCELLINESE 2025 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"In occasione della festa di Carnevale, il Comune di Marcellina ha organizzato una \u201cSFILATA IN MASCHERA\u201d nelle giornate di gioved\u00ec 27 Febbraio e domenica 2 Marzo 2025. Il corteo di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T11:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"804\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"CARNEVALE MARCELLINESE 2025\",\"datePublished\":\"2025-02-14T11:50:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/\"},\"wordCount\":184,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/02\\\/Locandina-CARNEVALE-2025-2.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/\",\"name\":\"CARNEVALE MARCELLINESE 2025 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/02\\\/Locandina-CARNEVALE-2025-2.jpg\",\"datePublished\":\"2025-02-14T11:50:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/02\\\/Locandina-CARNEVALE-2025-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/02\\\/Locandina-CARNEVALE-2025-2.jpg\",\"width\":1240,\"height\":804},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/02\\\/14\\\/carnevale-marcellinese-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CARNEVALE MARCELLINESE 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CARNEVALE MARCELLINESE 2025 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/","og_locale":"it_IT","og_type":"article","og_title":"CARNEVALE MARCELLINESE 2025 - Marcellina","og_description":"In occasione della festa di Carnevale, il Comune di Marcellina ha organizzato una \u201cSFILATA IN MASCHERA\u201d nelle giornate di gioved\u00ec 27 Febbraio e domenica 2 Marzo 2025. Il corteo di [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-14T11:50:07+00:00","og_image":[{"width":1240,"height":804,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"CARNEVALE MARCELLINESE 2025","datePublished":"2025-02-14T11:50:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/"},"wordCount":184,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/","name":"CARNEVALE MARCELLINESE 2025 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg","datePublished":"2025-02-14T11:50:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/02\/Locandina-CARNEVALE-2025-2.jpg","width":1240,"height":804},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/02\/14\/carnevale-marcellinese-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"CARNEVALE MARCELLINESE 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"42.0216832","longitude":"12.7991808","zoom":"12"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3532"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3532\/revisions"}],"predecessor-version":[{"id":3535,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3532\/revisions\/3535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3533"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}