{"id":3555,"date":"2025-03-27T16:28:43","date_gmt":"2025-03-27T15:28:43","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3555"},"modified":"2025-03-27T16:31:14","modified_gmt":"2025-03-27T15:31:14","slug":"dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/","title":{"rendered":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione"},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p>S\u00ec comunica alla cittadinanza che a partire dal giorno\u00a0<strong>venerd\u00ec 28 marzo 2025<\/strong>\u00a0il giardino di piazza Martiri delle Foibe \u00a0(Piazza Mercato) <strong>rimarr\u00e0 chiuso per lavori di riqualificazione<\/strong>.<\/p>\n<p>L&#8217;intervento riguarder\u00e0 la realizzazione di un&#8217;area ludica con giochi inclusivi cos\u00ec descritti:<\/p>\n<p>1. Installazione di un percorso inclusivo;<br \/>\n2. Gioco Bilico per 4 posti;<br \/>\n3. Altalena inclusiva 2 posti;<br \/>\n4. Giostra.<\/p>\n<p>Saranno realizzati inoltre aree di protezione dei giochi con tappeto antitrauma nel rispetto della normativa vigente.<\/p>\n<p>E&#8217; stato possibile realizzare questo progetto grazie al finanziamento concesso dalla Regione Lazio per l&#8217;acquisto di giochi inclusivi al quale si somma quello concesso dalla Comunit\u00e0 Montana per la posa e installazione del tappeto antitrauma.<\/p>\n<p><strong>L&#8217;amministrazione Comunale\u00a0<\/strong><\/p>\n<p><strong>Il\u00a0Sindaco<\/strong><br \/>\n<i>Alessandro Lundini<\/i><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>S\u00ec comunica alla cittadinanza che a partire dal giorno\u00a0venerd\u00ec 28 marzo 2025\u00a0il giardino di piazza Martiri delle Foibe \u00a0(Piazza Mercato) rimarr\u00e0 chiuso per lavori di riqualificazione. L&#8217;intervento riguarder\u00e0 la realizzazione [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina\" \/>\n<meta property=\"og:description\" content=\"S\u00ec comunica alla cittadinanza che a partire dal giorno\u00a0venerd\u00ec 28 marzo 2025\u00a0il giardino di piazza Martiri delle Foibe \u00a0(Piazza Mercato) rimarr\u00e0 chiuso per lavori di riqualificazione. L&#8217;intervento riguarder\u00e0 la realizzazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-27T15:28:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T15:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione\",\"datePublished\":\"2025-03-27T15:28:43+00:00\",\"dateModified\":\"2025-03-27T15:31:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/\"},\"wordCount\":122,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/03\\\/NEWS_AVVISO_lavori.parcogiochi.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/\",\"name\":\"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/03\\\/NEWS_AVVISO_lavori.parcogiochi.jpg\",\"datePublished\":\"2025-03-27T15:28:43+00:00\",\"dateModified\":\"2025-03-27T15:31:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/03\\\/NEWS_AVVISO_lavori.parcogiochi.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/03\\\/NEWS_AVVISO_lavori.parcogiochi.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/03\\\/27\\\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina","og_description":"S\u00ec comunica alla cittadinanza che a partire dal giorno\u00a0venerd\u00ec 28 marzo 2025\u00a0il giardino di piazza Martiri delle Foibe \u00a0(Piazza Mercato) rimarr\u00e0 chiuso per lavori di riqualificazione. L&#8217;intervento riguarder\u00e0 la realizzazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-27T15:28:43+00:00","article_modified_time":"2025-03-27T15:31:14+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione","datePublished":"2025-03-27T15:28:43+00:00","dateModified":"2025-03-27T15:31:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/"},"wordCount":122,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/","name":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg","datePublished":"2025-03-27T15:28:43+00:00","dateModified":"2025-03-27T15:31:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/03\/NEWS_AVVISO_lavori.parcogiochi.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/03\/27\/dl-28-marzo-2025-chiusura-del-giardino-di-piazza-martiri-delle-foibe-per-lavori-di-riqualificazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Dal 28 marzo 2025 chiusura del Giardino di Piazza Martiri delle Foibe per lavori di riqualificazione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"12"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3555"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3555\/revisions"}],"predecessor-version":[{"id":3557,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3555\/revisions\/3557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3556"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}