{"id":3631,"date":"2025-06-17T18:05:20","date_gmt":"2025-06-17T16:05:20","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3631"},"modified":"2025-06-19T18:01:22","modified_gmt":"2025-06-19T16:01:22","slug":"riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/","title":{"rendered":"Riapertura Termini &#8211; Manifestazione di interesse per l&#8217;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale"},"content":{"rendered":"<p style=\"font-weight: 400\"><strong>Avviso riapertura termini per la presentazione della Manifestazione di interesse per l\u2019individuazione di Operatori del terzo settore interessati alla gestione di locali e di spazi di propriet\u00e0 comunale da destinarsi alla organizzazione e realizzazione dei Centri Diurni ricreativi estivi per l\u2019anno 2025, per i minori nella fascia di et\u00e0 6 \u00a0&#8211; 11 anni.<\/strong><\/p>\n<p style=\"font-weight: 400\"><u>Si Porta a Conoscenza<\/u><br \/>\nDi tutti i soggetti pubblici e privati che operano nel terzo settore con finalit\u00e0 ludico-ricreative presenti nel territorio comunale, che \u00e8 prorogato il termine della data di scadenza della manifestazione di interesse sopra citata alla data del\u00a0<b><strong>20\/06\/2025 ORE 12.00\u00a0<\/strong><\/b><\/p>\n<p><u>Modalit\u00e0 di Presentazione della Manifestazione di Interesse\u00a0<\/u><br \/>\nI soggetti interessati potranno presentare la propria manifestazione di interesse per aderire all&#8217;iniziativa, mediante apposita domanda, utilizzando il Modello B, dovranno far pervenire la propria candidatura, esclusivamente tramite PEC al seguente indirizzo\u00a0<b><strong>protocollo@pec.comune.marcellina.rm.it<\/strong><\/b><br \/>\nLa domanda dovr\u00e0 contenere copia del documento di identit\u00e0 del\/della legale rappresentante. Nell&#8217;oggetto dovr\u00e0 essere indicato obbligatoriamente &#8220;AVVISO DI MANIFESTAZIONE DI INTERESSE CENTRI ESTIVI 2025&#8221;.<\/p>\n<p>PUBBLICIT\u00c0 Il presente avviso viene pubblicato sul sito istituzionale del Comune di Marcellina ed \u00e8 finalizzato esclusivamente alla ricezione di manifestazioni di interesse per favorire la partecipazione di tutti i soggetti interessati. Non ha valore vincolante per l&#8217;Amministrazione Comunale n\u00e9 valore precontrattuale. L&#8217;Amministrazione Comunale si riserva di interrompere in qualsiasi momento, per ragioni di interesse pubblico, la presente procedura senza che gli operatori economici istanti possano vantare alcuna pretesa. Per ulteriori informazioni gli interessati potranno rivolgersi all\u2019indirizzo \u00a0<strong>amministrativa@comune.marcellina.rm.it<\/strong>.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3638\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/AVVISO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/AVVISO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_3634\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/All.B_IstanzadiPartecipazioneETS_C.R.E.2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/All.B_IstanzadiPartecipazioneETS_C.R.E.2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>All.B_IstanzadiPartecipazioneETS_C.R.E.2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso riapertura termini per la presentazione della Manifestazione di interesse per l\u2019individuazione di Operatori del terzo settore interessati alla gestione di locali e di spazi di propriet\u00e0 comunale da destinarsi [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riapertura Termini - Manifestazione di interesse per l&#039;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riapertura Termini - Manifestazione di interesse per l&#039;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Avviso riapertura termini per la presentazione della Manifestazione di interesse per l\u2019individuazione di Operatori del terzo settore interessati alla gestione di locali e di spazi di propriet\u00e0 comunale da destinarsi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-17T16:05:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T16:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Riapertura Termini &#8211; Manifestazione di interesse per l&#8217;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale\",\"datePublished\":\"2025-06-17T16:05:20+00:00\",\"dateModified\":\"2025-06-19T16:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/\"},\"wordCount\":268,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/06\\\/NEWS_BANDI_centroestivo.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/\",\"name\":\"Riapertura Termini - Manifestazione di interesse per l'individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/06\\\/NEWS_BANDI_centroestivo.jpg\",\"datePublished\":\"2025-06-17T16:05:20+00:00\",\"dateModified\":\"2025-06-19T16:01:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/06\\\/NEWS_BANDI_centroestivo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/06\\\/NEWS_BANDI_centroestivo.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/06\\\/17\\\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riapertura Termini &#8211; Manifestazione di interesse per l&#8217;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riapertura Termini - Manifestazione di interesse per l'individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Riapertura Termini - Manifestazione di interesse per l'individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina","og_description":"Avviso riapertura termini per la presentazione della Manifestazione di interesse per l\u2019individuazione di Operatori del terzo settore interessati alla gestione di locali e di spazi di propriet\u00e0 comunale da destinarsi [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-06-17T16:05:20+00:00","article_modified_time":"2025-06-19T16:01:22+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Riapertura Termini &#8211; Manifestazione di interesse per l&#8217;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale","datePublished":"2025-06-17T16:05:20+00:00","dateModified":"2025-06-19T16:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/"},"wordCount":268,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/","name":"Riapertura Termini - Manifestazione di interesse per l'individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg","datePublished":"2025-06-17T16:05:20+00:00","dateModified":"2025-06-19T16:01:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/06\/NEWS_BANDI_centroestivo.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/06\/17\/riapertura-termini-manifestazione-di-interesse-per-lindividuazione-di-soggetti-del-terzo-settore-per-la-gestione-di-centri-estivi-diurni-nel-territorio-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Riapertura Termini &#8211; Manifestazione di interesse per l&#8217;individuazione di soggetti del terzo settore per la gestione di Centri Estivi Diurni nel territorio comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3631"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3631\/revisions"}],"predecessor-version":[{"id":3637,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3631\/revisions\/3637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3632"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}