{"id":3734,"date":"2025-09-10T13:37:06","date_gmt":"2025-09-10T11:37:06","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3734"},"modified":"2025-09-10T13:37:06","modified_gmt":"2025-09-10T11:37:06","slug":"avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/","title":{"rendered":"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto per il servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio"},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p>Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto ai sensi dell&#8221;Art. 50 del D.Lgs 36\/2023 per il Servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio di refezione scolastica A.S. 2025\/2026<\/p>\n<p>Stazione appaltante Comune di Marcellina. &#8211; <strong>RIAPERTURA TERMINI<\/strong><\/p>\n<\/div>\n<p>Le manifestazioni di interesse devono pervenire\u00a0<strong>entro il giorno 19 settembre 2025<\/strong>\u00a0esclusivamente tramite posta elettronica certificata, al seguente recapito:\u00a0<strong>protocollo@pec.comune.marcellina.rm.it<\/strong><\/p>\n<p>\u25ba <a href=\"https:\/\/www.comune.marcellina.rm.it\/novita\/avvisi\/novita_136.html\"><strong>BANDO<\/strong><\/a><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto ai sensi dell&#8221;Art. 50 del D.Lgs 36\/2023 per il Servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio di refezione scolastica A.S. 2025\/2026 [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso esplorativo manifestazione d&#039;interesse per affidamento diretto per il servizio di Direttore dell&#039;Esecuzione del contratto relativo al servizio - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso esplorativo manifestazione d&#039;interesse per affidamento diretto per il servizio di Direttore dell&#039;Esecuzione del contratto relativo al servizio - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto ai sensi dell&#8221;Art. 50 del D.Lgs 36\/2023 per il Servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio di refezione scolastica A.S. 2025\/2026 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T11:37:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto per il servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio\",\"datePublished\":\"2025-09-10T11:37:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/\"},\"wordCount\":80,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/08\\\/NEWS_BANDI_direttore.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/\",\"name\":\"Avviso esplorativo manifestazione d'interesse per affidamento diretto per il servizio di Direttore dell'Esecuzione del contratto relativo al servizio - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/08\\\/NEWS_BANDI_direttore.jpg\",\"datePublished\":\"2025-09-10T11:37:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/08\\\/NEWS_BANDI_direttore.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/08\\\/NEWS_BANDI_direttore.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/09\\\/10\\\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto per il servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso esplorativo manifestazione d'interesse per affidamento diretto per il servizio di Direttore dell'Esecuzione del contratto relativo al servizio - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso esplorativo manifestazione d'interesse per affidamento diretto per il servizio di Direttore dell'Esecuzione del contratto relativo al servizio - Marcellina","og_description":"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto ai sensi dell&#8221;Art. 50 del D.Lgs 36\/2023 per il Servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio di refezione scolastica A.S. 2025\/2026 [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-10T11:37:06+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto per il servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio","datePublished":"2025-09-10T11:37:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/"},"wordCount":80,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/","name":"Avviso esplorativo manifestazione d'interesse per affidamento diretto per il servizio di Direttore dell'Esecuzione del contratto relativo al servizio - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg","datePublished":"2025-09-10T11:37:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/08\/NEWS_BANDI_direttore.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/09\/10\/avviso-esplorativo-manifestazione-dinteresse-per-affidamento-diretto-per-il-servizio-di-direttore-dellesecuzione-del-contratto-relativo-al-servizio-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Avviso esplorativo manifestazione d&#8217;interesse per affidamento diretto per il servizio di Direttore dell&#8217;Esecuzione del contratto relativo al servizio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3734"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3734\/revisions"}],"predecessor-version":[{"id":3735,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3734\/revisions\/3735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3699"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}