{"id":3768,"date":"2025-10-29T13:15:45","date_gmt":"2025-10-29T12:15:45","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3768"},"modified":"2025-10-29T13:15:45","modified_gmt":"2025-10-29T12:15:45","slug":"certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/","title":{"rendered":"Certificazione Europea del Turismo Sostenibile CETS  Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16"},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p>Il 19 novembre 2025 l\u2019ente Parco Regionale dei Monti Lucretili ricever\u00e0, presso il Parlamento Europeo di Bruxelles, il conferimento della Certificazione Europea del Turismo Sostenibile (CETS).<\/p>\n<p><strong>GIOVEDI\u2019 30 OTTOBRE 2025 alle ore 16<\/strong>, presso la sala consiliare del Comune di Marcellina (sito scelto per tutti gli attori interessati facenti parte del Comuni di Marcellina e dei comuni limitrofi) si terr\u00e0 l&#8217;incontro per effettuare il monitoraggio del piano d\u2019azione della CETS.<\/p>\n<p>Tutti gli interessati sono invitati a partecipare.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Il 19 novembre 2025 l\u2019ente Parco Regionale dei Monti Lucretili ricever\u00e0, presso il Parlamento Europeo di Bruxelles, il conferimento della Certificazione Europea del Turismo Sostenibile (CETS). GIOVEDI\u2019 30 OTTOBRE 2025 [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Il 19 novembre 2025 l\u2019ente Parco Regionale dei Monti Lucretili ricever\u00e0, presso il Parlamento Europeo di Bruxelles, il conferimento della Certificazione Europea del Turismo Sostenibile (CETS). GIOVEDI\u2019 30 OTTOBRE 2025 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T12:15:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16\",\"datePublished\":\"2025-10-29T12:15:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/\"},\"wordCount\":90,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/10\\\/NEWS_AVVISO_CETS.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/\",\"name\":\"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/10\\\/NEWS_AVVISO_CETS.jpg\",\"datePublished\":\"2025-10-29T12:15:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/10\\\/NEWS_AVVISO_CETS.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/10\\\/NEWS_AVVISO_CETS.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/10\\\/29\\\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/","og_locale":"it_IT","og_type":"article","og_title":"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina","og_description":"Il 19 novembre 2025 l\u2019ente Parco Regionale dei Monti Lucretili ricever\u00e0, presso il Parlamento Europeo di Bruxelles, il conferimento della Certificazione Europea del Turismo Sostenibile (CETS). GIOVEDI\u2019 30 OTTOBRE 2025 [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-29T12:15:45+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16","datePublished":"2025-10-29T12:15:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/"},"wordCount":90,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/","name":"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg","datePublished":"2025-10-29T12:15:45+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/10\/NEWS_AVVISO_CETS.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/10\/29\/certificazione-europea-del-turismo-sostenibile-cets-rafforzamento-operativo-tavolo-tecnico-a-marcellina-giovedi-30-ottobre-2025-alle-ore-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Certificazione Europea del Turismo Sostenibile CETS Rafforzamento operativo, tavolo tecnico a Marcellina gioved\u00ec 30 ottobre 2025 alle ore 16"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"13"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3768"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3768\/revisions"}],"predecessor-version":[{"id":3770,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3768\/revisions\/3770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3769"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}