{"id":3780,"date":"2025-11-05T12:59:54","date_gmt":"2025-11-05T11:59:54","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3780"},"modified":"2025-11-05T12:59:54","modified_gmt":"2025-11-05T11:59:54","slug":"il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/","title":{"rendered":"IL NASTRO ROSA &#8211; Quarta Edizione &#8211; 8 novembre 2025 Aula Consiliare del Comune di Marcellina"},"content":{"rendered":"<p>Si comunica che il giorno 8 novembre 2025 alle ore 16:30 presso l&#8217;Aula Consiliare del Comune di Marcellina, si terr\u00e0 un incontro per la Campagna di sensibilizzazione e prevenzione del tumore al seno nell&#8217;ambito dell&#8217;Ottobre Rosa, &#8220;<strong>Il Nastro Rosa &#8221; quarta edizione &#8211; Il tumore alla mammella informazione e prevenzione<\/strong>.<\/p>\n<p>Presentano e moderano l&#8217;evento:<\/p>\n<p><i>Simona Lucci<\/i>\u00a0&#8211; Assessore con delega ai Servizi Sociali, Pari opportunit\u00e0, Sport<br \/>\n<i>Alessandra Danieli<\/i>: Vice Sindaco e Assessore alla Cultura e Pubblica Istruzione<\/p>\n<p>Interverr\u00e0:<\/p>\n<p><i>Alessandro Lundini\u00a0<\/i>&#8211; Sindaco del Comune di Marcellina<\/p>\n<p>Ospiti:<\/p>\n<ul>\n<li><i>Dr.ssa Giovanna Rizzitiello<\/i>\u00a0&#8211; Medico di medicina generale e Referente delle Associazioni di volontariato presso la ASL Roma 5 &#8211; &#8220;Partecipazione attiva delle Associazioni nella Rete Oncologica ASL Roma 5: Stato dell&#8217;Arte&#8221;<\/li>\n<li><i>Dr.ssa Laura Rossetti<\/i>: titolare della sede farmaceutica di Marcellina e Villanova &#8211; &#8220;Ruolo della farmacia nella prevenzione oncologica e nell&#8217;assistenza al malato oncologico&#8221;<\/li>\n<li><i>Valentina Zatti<\/i>: dermopigmentista medicale<\/li>\n<li><i>Dr. Angeloluca De Quarto<\/i>\u00a0&#8211; UPC multi presidio ASL Roma 2 ospedale Sandro Pertini S. Eugenio &#8211; &#8220;Tumore mammario: l&#8217;importanza della diagnosi precoce&#8221;<\/li>\n<li>Dr.ssa Rosa Saltarelli &#8211; Responsabile UOC oncologia ospedale San Giovanni Evangelista di Tivoli e referente del coordinamento Oncologico Aziendale Territoriale ASL Roma 5 &#8211; Rete Oncologica Regione Lazio &#8211; &#8220;Implementazione della Rete Oncologica della ASL Roma 5 nell&#8217;Ultimo Anno&#8221;<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3782\" src=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore-724x1024.jpeg\" alt=\"\" width=\"640\" height=\"905\" srcset=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore-724x1024.jpeg 724w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore-212x300.jpeg 212w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore-768x1086.jpeg 768w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore-1086x1536.jpeg 1086w, https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore.jpeg 1414w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che il giorno 8 novembre 2025 alle ore 16:30 presso l&#8217;Aula Consiliare del Comune di Marcellina, si terr\u00e0 un incontro per la Campagna di sensibilizzazione e prevenzione del [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che il giorno 8 novembre 2025 alle ore 16:30 presso l&#8217;Aula Consiliare del Comune di Marcellina, si terr\u00e0 un incontro per la Campagna di sensibilizzazione e prevenzione del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T11:59:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"839\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"IL NASTRO ROSA &#8211; Quarta Edizione &#8211; 8 novembre 2025 Aula Consiliare del Comune di Marcellina\",\"datePublished\":\"2025-11-05T11:59:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/\"},\"wordCount\":216,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/11\\\/Tumore_cov.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/\",\"name\":\"IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/11\\\/Tumore_cov.jpeg\",\"datePublished\":\"2025-11-05T11:59:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/11\\\/Tumore_cov.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2025\\\/11\\\/Tumore_cov.jpeg\",\"width\":1414,\"height\":839},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2025\\\/11\\\/05\\\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL NASTRO ROSA &#8211; Quarta Edizione &#8211; 8 novembre 2025 Aula Consiliare del Comune di Marcellina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/","og_locale":"it_IT","og_type":"article","og_title":"IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina","og_description":"Si comunica che il giorno 8 novembre 2025 alle ore 16:30 presso l&#8217;Aula Consiliare del Comune di Marcellina, si terr\u00e0 un incontro per la Campagna di sensibilizzazione e prevenzione del [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-05T11:59:54+00:00","og_image":[{"width":1414,"height":839,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"IL NASTRO ROSA &#8211; Quarta Edizione &#8211; 8 novembre 2025 Aula Consiliare del Comune di Marcellina","datePublished":"2025-11-05T11:59:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/"},"wordCount":216,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/","url":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/","name":"IL NASTRO ROSA - Quarta Edizione - 8 novembre 2025 Aula Consiliare del Comune di Marcellina - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg","datePublished":"2025-11-05T11:59:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2025\/11\/Tumore_cov.jpeg","width":1414,"height":839},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2025\/11\/05\/il-nastro-rosa-quarta-edizione-8-novembre-2025-aula-consiliare-del-comune-di-marcellina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"IL NASTRO ROSA &#8211; Quarta Edizione &#8211; 8 novembre 2025 Aula Consiliare del Comune di Marcellina"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"13"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3780"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3780\/revisions"}],"predecessor-version":[{"id":3783,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3780\/revisions\/3783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3781"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}