{"id":3834,"date":"2026-02-16T13:18:01","date_gmt":"2026-02-16T12:18:01","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3834"},"modified":"2026-02-16T13:18:01","modified_gmt":"2026-02-16T12:18:01","slug":"riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/","title":{"rendered":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026"},"content":{"rendered":"<p>Si comunica che la riconsegna dei <strong>tesserini venatori della stagione 2025\/2026<\/strong> deve essere effettuata <strong>entro il 31 marzo 2026<\/strong> presso l&#8217;Ufficio Protocollo\/Demografici del Comune di Marcellina, Piazza Cesare Battisti, 14, piano terra, nei seguenti orari:<\/p>\n<ul>\n<li><strong>Luned\u00ec dalle ore 9,00 alle ore 11,00<\/strong><\/li>\n<li><strong>Mercoled\u00ec dalle ore 9,00 alle ore 12,00<\/strong><\/li>\n<li><strong>Gioved\u00ec dalle ore 15,30 alle ore 17,30<\/strong><\/li>\n<\/ul>\n<p>Info:<br \/>\nUfficio Protocollo<br \/>\nTel. 0774.427033<br \/>\nE-mail: protocollo@comune.marcellina.rm.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che la riconsegna dei tesserini venatori della stagione 2025\/2026 deve essere effettuata entro il 31 marzo 2026 presso l&#8217;Ufficio Protocollo\/Demografici del Comune di Marcellina, Piazza Cesare Battisti, 14, [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che la riconsegna dei tesserini venatori della stagione 2025\/2026 deve essere effettuata entro il 31 marzo 2026 presso l&#8217;Ufficio Protocollo\/Demografici del Comune di Marcellina, Piazza Cesare Battisti, 14, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-16T12:18:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\\\/2026\",\"datePublished\":\"2026-02-16T12:18:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_tesserini2026_.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/\",\"name\":\"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\\\/2026 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_tesserini2026_.jpg\",\"datePublished\":\"2026-02-16T12:18:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_tesserini2026_.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_tesserini2026_.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/16\\\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\\\/2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/","og_locale":"it_IT","og_type":"article","og_title":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026 - Marcellina","og_description":"Si comunica che la riconsegna dei tesserini venatori della stagione 2025\/2026 deve essere effettuata entro il 31 marzo 2026 presso l&#8217;Ufficio Protocollo\/Demografici del Comune di Marcellina, Piazza Cesare Battisti, 14, [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-16T12:18:01+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026","datePublished":"2026-02-16T12:18:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/","url":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/","name":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg","datePublished":"2026-02-16T12:18:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_tesserini2026_.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/16\/riconsegna-tesserini-venatori-stagione-di-caccia-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"RICONSEGNA TESSERINI VENATORI STAGIONE DI CACCIA 2025\/2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"17"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3834"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3834\/revisions"}],"predecessor-version":[{"id":3836,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3834\/revisions\/3836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3835"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}