{"id":3837,"date":"2026-02-17T13:14:16","date_gmt":"2026-02-17T12:14:16","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=3837"},"modified":"2026-02-17T13:15:33","modified_gmt":"2026-02-17T12:15:33","slug":"manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/","title":{"rendered":"MANIFESTAZIONE D&#8217;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026"},"content":{"rendered":"<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper\">\n<p><strong>IL SINDACO<\/strong><\/p>\n<p>Considerato che:<br \/>\n\u2013 con decreto del Presidente della Repubblica 13 gennaio 2026 (Gazzetta Ufficiale n. 10 del 14 gennaio 2026) con cui sono stati convocati i comizi per lo svolgimento del Referendum Costituzionale per i giorni 22 e 23 marzo 2026;<\/p>\n<p><strong><br \/>\nRENDE NOTO CHE<\/strong><\/p>\n<p>si intende procedere alla nomina degli scrutatori mediante sorteggio tra coloro che, <strong>essendo gi\u00e0 iscritti nell\u2019Albo delle persone idonee all\u2019ufficio di scrutatore di seggio elettorale<\/strong>, si trovino nelle condizioni di disoccupati, inoccupati o studenti non lavoratori.<br \/>\n\u00c8 pertanto possibile inviare una manifestazione di interesse finalizzata alla nomina di scrutatore elettorale tramite sorteggio compilando il modello di domanda (allegato al presente avviso e disponibile sul sito istituzionale del Comune) e allegando una copia di un documento di identit\u00e0 valido.<\/p>\n<p>\u25ba <strong>La domanda (reperibile sul sito istituzionale del Comune di Marcellina), dovr\u00e0 essere inviata alla mail: protocollo@comune.marcellina.rm.it entro il 25 febbraio 2026 alle ore 12,00<\/strong>.<\/p>\n<p>Nel caso in cui il numero di richieste dovesse risultare inferiore a quello necessario, si proceder\u00e0 alla nomina dei rimanenti scrutatori mediante sorteggio tra gli altri iscritti al medesimo Albo.<\/p>\n<p><strong><br \/>\nIL SINDACO<\/strong><br \/>\n<strong><em>Alessandro Lundini<\/em><\/strong><\/p>\n<p>Info:<\/p>\n<article id=\"ulteriori-informazioni\" class=\"it-page-section anchor-offset mt-5\">\n<div class=\"richtext-wrapper\">\n<p>Ufficio Elettorale<br \/>\ntel: 0774.42701<br \/>\nE-mail: protocollo@comune.marcellina.rm.it<br \/>\nsito web: comune.marcellina.rm.it<\/p>\n<\/div>\n<\/article>\n<article id=\"documenti\" class=\"it-page-section anchor-offset mt-5\"><\/article>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>IL SINDACO Considerato che: \u2013 con decreto del Presidente della Repubblica 13 gennaio 2026 (Gazzetta Ufficiale n. 10 del 14 gennaio 2026) con cui sono stati convocati i comizi per [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":3838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANIFESTAZIONE D&#039;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANIFESTAZIONE D&#039;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"IL SINDACO Considerato che: \u2013 con decreto del Presidente della Repubblica 13 gennaio 2026 (Gazzetta Ufficiale n. 10 del 14 gennaio 2026) con cui sono stati convocati i comizi per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T12:14:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T12:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"MANIFESTAZIONE D&#8217;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026\",\"datePublished\":\"2026-02-17T12:14:16+00:00\",\"dateModified\":\"2026-02-17T12:15:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/\"},\"wordCount\":204,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_referendum2026_scrutatori.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/\",\"name\":\"MANIFESTAZIONE D'INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_referendum2026_scrutatori.jpg\",\"datePublished\":\"2026-02-17T12:14:16+00:00\",\"dateModified\":\"2026-02-17T12:15:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_referendum2026_scrutatori.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2026\\\/02\\\/NEWS_referendum2026_scrutatori.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2026\\\/02\\\/17\\\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANIFESTAZIONE D&#8217;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANIFESTAZIONE D'INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/","og_locale":"it_IT","og_type":"article","og_title":"MANIFESTAZIONE D'INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina","og_description":"IL SINDACO Considerato che: \u2013 con decreto del Presidente della Repubblica 13 gennaio 2026 (Gazzetta Ufficiale n. 10 del 14 gennaio 2026) con cui sono stati convocati i comizi per [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-17T12:14:16+00:00","article_modified_time":"2026-02-17T12:15:33+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"MANIFESTAZIONE D&#8217;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026","datePublished":"2026-02-17T12:14:16+00:00","dateModified":"2026-02-17T12:15:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/"},"wordCount":204,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/","url":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/","name":"MANIFESTAZIONE D'INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg","datePublished":"2026-02-17T12:14:16+00:00","dateModified":"2026-02-17T12:15:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2026\/02\/NEWS_referendum2026_scrutatori.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2026\/02\/17\/manifestazione-dinteresse-per-la-nomina-di-scrutatore-elettorale-referendum-costituzionale-del-22-e-23-marzo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"MANIFESTAZIONE D&#8217;INTERESSE PER LA NOMINA DI SCRUTATORE ELETTORALE REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"17"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=3837"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3837\/revisions"}],"predecessor-version":[{"id":3839,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/3837\/revisions\/3839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/3838"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=3837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=3837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=3837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}