{"id":522,"date":"2019-05-06T13:43:26","date_gmt":"2019-05-06T11:43:26","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=522"},"modified":"2019-05-06T13:43:26","modified_gmt":"2019-05-06T11:43:26","slug":"eventi-gran-premio-della-montagna-di-roma-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/","title":{"rendered":"EVENTI, Gran Premio della Montagna di Roma 2019"},"content":{"rendered":"<p><strong>Domenica 26 Maggio 2019<\/strong>,\u00a0l\u2019A.S.D. TiburEcotrail, sotto l\u2019egida della\u00a0UISP\u00a0provinciale di ROMA,\u00a0 promuovono la X edizione del <em><strong>\u201cGran premio della montagna di Roma<\/strong><\/em>\u201d. Corsa a piedi in ambiente naturale, che percorre i boschi del\u00a0parco dei Lucretili\u00a0e i sentieri del\u00a0monte Gennaro,\u00a0la\u00a0Montagna di Roma. Dislivello positivo di ca\u00a01000mt.<\/p>\n<p>\u25ba Ritrovo, iscrizioni e pettorali dalle ore 7,30 alle ore 9,00 presso il campo sportivo di Marcellina.<\/p>\n<p>info:\u00a0<a href=\"http:\/\/www.tiburecotrail.it\/events\/gran-premio-della-montagna-di-roma\/\" target=\"_blank\" rel=\"noopener\"><strong>www.tiburecotrail.it<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 26 Maggio 2019,\u00a0l\u2019A.S.D. TiburEcotrail, sotto l\u2019egida della\u00a0UISP\u00a0provinciale di ROMA,\u00a0 promuovono la X edizione del \u201cGran premio della montagna di Roma\u201d. Corsa a piedi in ambiente naturale, che percorre i [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Domenica 26 Maggio 2019,\u00a0l\u2019A.S.D. TiburEcotrail, sotto l\u2019egida della\u00a0UISP\u00a0provinciale di ROMA,\u00a0 promuovono la X edizione del \u201cGran premio della montagna di Roma\u201d. Corsa a piedi in ambiente naturale, che percorre i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T11:43:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1273\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"EVENTI, Gran Premio della Montagna di Roma 2019\",\"datePublished\":\"2019-05-06T11:43:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/\"},\"wordCount\":80,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/05\\\/gran-premio-della-montagna-A3_v4.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/\",\"name\":\"EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/05\\\/gran-premio-della-montagna-A3_v4.jpg\",\"datePublished\":\"2019-05-06T11:43:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/05\\\/gran-premio-della-montagna-A3_v4.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/05\\\/gran-premio-della-montagna-A3_v4.jpg\",\"width\":1273,\"height\":1800,\"caption\":\"Created with GIMP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/05\\\/06\\\/eventi-gran-premio-della-montagna-di-roma-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EVENTI, Gran Premio della Montagna di Roma 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/","og_locale":"it_IT","og_type":"article","og_title":"EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina","og_description":"Domenica 26 Maggio 2019,\u00a0l\u2019A.S.D. TiburEcotrail, sotto l\u2019egida della\u00a0UISP\u00a0provinciale di ROMA,\u00a0 promuovono la X edizione del \u201cGran premio della montagna di Roma\u201d. Corsa a piedi in ambiente naturale, che percorre i [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-06T11:43:26+00:00","og_image":[{"width":1273,"height":1800,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"EVENTI, Gran Premio della Montagna di Roma 2019","datePublished":"2019-05-06T11:43:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/"},"wordCount":80,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/","name":"EVENTI, Gran Premio della Montagna di Roma 2019 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg","datePublished":"2019-05-06T11:43:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/05\/gran-premio-della-montagna-A3_v4.jpg","width":1273,"height":1800,"caption":"Created with GIMP"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/05\/06\/eventi-gran-premio-della-montagna-di-roma-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"EVENTI, Gran Premio della Montagna di Roma 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=522"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/522\/revisions"}],"predecessor-version":[{"id":524,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/522\/revisions\/524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}