{"id":612,"date":"2019-06-21T10:24:04","date_gmt":"2019-06-21T08:24:04","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=612"},"modified":"2019-06-21T10:24:04","modified_gmt":"2019-06-21T08:24:04","slug":"viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/","title":{"rendered":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe"},"content":{"rendered":"<div>Con Ordinanza n\u00b0 22 del Responsabile del Servizio, si comunica la temporanea chiusura e divieto di sosta in Piazza Martire delle Foibe per il regolare svolgimento della manifestazione\u00a0<em><strong>&#8220;Festa della Madonna della Ginestra e dei Butteri&#8221;<\/strong><\/em>\u00a0con le seguenti modalit\u00e0:<br \/>\n<strong>divieto di accesso e sosta dalle ore 15,00 di venerd\u00ec 21 giugno 2019 fino alle ore 24,00 di domenica 23 giugno 2019<\/strong>\u00a0nelle aree:<\/div>\n<div><\/div>\n<ul>\n<li><strong>Piazza Martiri delle Foibe;<\/strong><\/li>\n<li><strong>Via Tevere fino intersezione via Liri;<\/strong><\/li>\n<li><strong>Via Gen. Carlo Alberto Dalla Chiesa limitatamente al tratto compreso tra il civico 30 e l&#8217;incrocio con via Adige;<\/strong><\/li>\n<li><strong>Via Arno.<\/strong><\/li>\n<\/ul>\n<div>Dai predetti divieti sono esclusi i veicoli impegnati per i festeggiamenti e quelli ad uso degli operatori commerciali.<br \/>\nLa sosta in divieto di quanto sopra sar\u00e0 considerata di grave intralcio ai fini dell&#8217;applicazione della sanzione accessoria della rimozione dei veicoli ai sensi dell&#8217;articolo 159 del Codice della Strada.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con Ordinanza n\u00b0 22 del Responsabile del Servizio, si comunica la temporanea chiusura e divieto di sosta in Piazza Martire delle Foibe per il regolare svolgimento della manifestazione\u00a0&#8220;Festa della Madonna [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Con Ordinanza n\u00b0 22 del Responsabile del Servizio, si comunica la temporanea chiusura e divieto di sosta in Piazza Martire delle Foibe per il regolare svolgimento della manifestazione\u00a0&#8220;Festa della Madonna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-21T08:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe\",\"datePublished\":\"2019-06-21T08:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/\"},\"wordCount\":148,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/06\\\/ODINANZA_Traffico.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/\",\"name\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/06\\\/ODINANZA_Traffico.jpg\",\"datePublished\":\"2019-06-21T08:24:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/06\\\/ODINANZA_Traffico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/06\\\/ODINANZA_Traffico.jpg\",\"width\":960,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/06\\\/21\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/","og_locale":"it_IT","og_type":"article","og_title":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina","og_description":"Con Ordinanza n\u00b0 22 del Responsabile del Servizio, si comunica la temporanea chiusura e divieto di sosta in Piazza Martire delle Foibe per il regolare svolgimento della manifestazione\u00a0&#8220;Festa della Madonna [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-06-21T08:24:04+00:00","og_image":[{"width":960,"height":719,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe","datePublished":"2019-06-21T08:24:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/"},"wordCount":148,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/","name":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg","datePublished":"2019-06-21T08:24:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/06\/ODINANZA_Traffico.jpg","width":960,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/06\/21\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-in-piazza-martiri-delle-foibe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta in Piazza Martiri delle Foibe"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/612\/revisions"}],"predecessor-version":[{"id":613,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/612\/revisions\/613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}