{"id":738,"date":"2019-07-26T13:35:10","date_gmt":"2019-07-26T11:35:10","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=738"},"modified":"2019-07-26T13:35:10","modified_gmt":"2019-07-26T11:35:10","slug":"trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/","title":{"rendered":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019"},"content":{"rendered":"<p>Si comunicano, in allegato, gli orari delle <strong>Autolinee SAP<\/strong> aggiornati con gli attuali orari di trasporto ferroviario che entreranno in vigore dal giorno <strong>luned\u00ec 29 luglio 2019<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_739\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/Orari_SAP.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/Orari_SAP.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Orari_SAP<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunicano, in allegato, gli orari delle Autolinee SAP aggiornati con gli attuali orari di trasporto ferroviario che entreranno in vigore dal giorno luned\u00ec 29 luglio 2019 \ud83d\udcce AllegatiOrari_SAP<\/p>\n","protected":false},"author":283,"featured_media":740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunicano, in allegato, gli orari delle Autolinee SAP aggiornati con gli attuali orari di trasporto ferroviario che entreranno in vigore dal giorno luned\u00ec 29 luglio 2019 \ud83d\udcce AllegatiOrari_SAP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T11:35:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW-768x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019\",\"datePublished\":\"2019-07-26T11:35:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/07\\\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/\",\"name\":\"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/07\\\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png\",\"datePublished\":\"2019-07-26T11:35:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/07\\\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/07\\\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/07\\\/26\\\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/","og_locale":"it_IT","og_type":"article","og_title":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina","og_description":"Si comunicano, in allegato, gli orari delle Autolinee SAP aggiornati con gli attuali orari di trasporto ferroviario che entreranno in vigore dal giorno luned\u00ec 29 luglio 2019 \ud83d\udcce AllegatiOrari_SAP","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-26T11:35:10+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW-768x576.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019","datePublished":"2019-07-26T11:35:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/"},"wordCount":33,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/","name":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png","datePublished":"2019-07-26T11:35:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/07\/SPLASH_NEWS_trasporti_OrarioSAP_03_TW.png","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/07\/26\/trasporti-autolinee-sap-orari-in-vigore-dal-29-luglio-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"TRASPORTI: Autolinee SAP, orari in vigore dal 29 luglio 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/738\/revisions"}],"predecessor-version":[{"id":741,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/738\/revisions\/741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/740"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}