{"id":766,"date":"2019-08-09T14:17:46","date_gmt":"2019-08-09T12:17:46","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=766"},"modified":"2019-08-09T14:17:46","modified_gmt":"2019-08-09T12:17:46","slug":"ambiente-diodoro-ecologia-gestione-servizi-ecologici","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/","title":{"rendered":"AMBIENTE: Diodoro Ecologia &#8211; Gestione Servizi Ecologici"},"content":{"rendered":"<div>\n<div>Si rende noto che per eventuali comunicazioni e\/o disservizi sulla raccolta differenziata porta a porta, il cittadino pu\u00f2 effettuare segnalazioni alla ditta <strong>Diodoro Ecologia<\/strong> tramite i seguenti contatti:<\/div>\n<div><\/div>\n<ul>\n<li><strong>800 959 579<\/strong>\u00a0 &#8211; Solo su rete fissa<\/li>\n<li><strong>0765.422580<\/strong> &#8211; dal Luned\u00ec al sabato dalle ore 8,00 alle ore 13,00<\/li>\n<li>E-mail: <strong>lazio@diodoroecologia.it<\/strong> &#8211; <strong>info@diodoroecologia.it<\/strong><\/li>\n<li>Sito web: <strong>www.diodoroecologia.it<\/strong><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si rende noto che per eventuali comunicazioni e\/o disservizi sulla raccolta differenziata porta a porta, il cittadino pu\u00f2 effettuare segnalazioni alla ditta Diodoro Ecologia tramite i seguenti contatti: 800 959 [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si rende noto che per eventuali comunicazioni e\/o disservizi sulla raccolta differenziata porta a porta, il cittadino pu\u00f2 effettuare segnalazioni alla ditta Diodoro Ecologia tramite i seguenti contatti: 800 959 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-09T12:17:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW-768x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AMBIENTE: Diodoro Ecologia &#8211; Gestione Servizi Ecologici\",\"datePublished\":\"2019-08-09T12:17:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_ambiente_Diodoro_TW.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/\",\"name\":\"AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_ambiente_Diodoro_TW.png\",\"datePublished\":\"2019-08-09T12:17:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_ambiente_Diodoro_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_ambiente_Diodoro_TW.png\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/09\\\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMBIENTE: Diodoro Ecologia &#8211; Gestione Servizi Ecologici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/","og_locale":"it_IT","og_type":"article","og_title":"AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina","og_description":"Si rende noto che per eventuali comunicazioni e\/o disservizi sulla raccolta differenziata porta a porta, il cittadino pu\u00f2 effettuare segnalazioni alla ditta Diodoro Ecologia tramite i seguenti contatti: 800 959 [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-09T12:17:46+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW-768x576.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AMBIENTE: Diodoro Ecologia &#8211; Gestione Servizi Ecologici","datePublished":"2019-08-09T12:17:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/","name":"AMBIENTE: Diodoro Ecologia - Gestione Servizi Ecologici - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW.png","datePublished":"2019-08-09T12:17:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_ambiente_Diodoro_TW.png","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/09\/ambiente-diodoro-ecologia-gestione-servizi-ecologici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AMBIENTE: Diodoro Ecologia &#8211; Gestione Servizi Ecologici"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/766\/revisions"}],"predecessor-version":[{"id":768,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/766\/revisions\/768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/767"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}