{"id":786,"date":"2019-08-26T10:31:20","date_gmt":"2019-08-26T08:31:20","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=786"},"modified":"2019-08-26T10:34:41","modified_gmt":"2019-08-26T08:34:41","slug":"avviso-acea-disservizio-rete-idrica-del-26-03-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/","title":{"rendered":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019"},"content":{"rendered":"<p>Si comunica che a seguito di un guasto sulla condotta di Fonte Mamprella si \u00e8 verificata una diminuzione della portata d&#8217;acqua nei bottini: &#8220;Marcellina Alto e Marcellina Basso&#8221;, che alimentano le abitazioni.<br \/>\nI lavori di riparazione sono in corso d&#8217;opera. Il ripristino \u00e8 previsto nella giornata di domani marted\u00ec 27.08.2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che a seguito di un guasto sulla condotta di Fonte Mamprella si \u00e8 verificata una diminuzione della portata d&#8217;acqua nei bottini: &#8220;Marcellina Alto e Marcellina Basso&#8221;, che alimentano [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che a seguito di un guasto sulla condotta di Fonte Mamprella si \u00e8 verificata una diminuzione della portata d&#8217;acqua nei bottini: &#8220;Marcellina Alto e Marcellina Basso&#8221;, che alimentano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-26T08:31:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-26T08:34:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW-1024x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AVVISO: ACEA, disservizio rete idrica del 26.08.2019\",\"datePublished\":\"2019-08-26T08:31:20+00:00\",\"dateModified\":\"2019-08-26T08:34:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/\"},\"wordCount\":53,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/03\\\/SPLASH_NEWS_acea_guasto2_TW.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/\",\"name\":\"AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/03\\\/SPLASH_NEWS_acea_guasto2_TW.png\",\"datePublished\":\"2019-08-26T08:31:20+00:00\",\"dateModified\":\"2019-08-26T08:34:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/03\\\/SPLASH_NEWS_acea_guasto2_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/03\\\/SPLASH_NEWS_acea_guasto2_TW.png\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/08\\\/26\\\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO: ACEA, disservizio rete idrica del 26.08.2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina","og_description":"Si comunica che a seguito di un guasto sulla condotta di Fonte Mamprella si \u00e8 verificata una diminuzione della portata d&#8217;acqua nei bottini: &#8220;Marcellina Alto e Marcellina Basso&#8221;, che alimentano [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-26T08:31:20+00:00","article_modified_time":"2019-08-26T08:34:41+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW-1024x768.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019","datePublished":"2019-08-26T08:31:20+00:00","dateModified":"2019-08-26T08:34:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/"},"wordCount":53,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/","name":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW.png","datePublished":"2019-08-26T08:31:20+00:00","dateModified":"2019-08-26T08:34:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/03\/SPLASH_NEWS_acea_guasto2_TW.png","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/08\/26\/avviso-acea-disservizio-rete-idrica-del-26-03-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AVVISO: ACEA, disservizio rete idrica del 26.08.2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=786"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/786\/revisions"}],"predecessor-version":[{"id":788,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/786\/revisions\/788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/403"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}