{"id":943,"date":"2019-11-23T21:12:27","date_gmt":"2019-11-23T20:12:27","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=943"},"modified":"2019-11-23T21:12:27","modified_gmt":"2019-11-23T20:12:27","slug":"territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/","title":{"rendered":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Il Centro Funzionale Regionale ha emesso un Avviso di Criticit\u00e0 idrogeologica ed idraulica regionale, valido dalla sera del 23 novembre 2019 e per le successive 18-24 ore, valutando il\u00a0livello di criticit\u00e0 arancione.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">A causa della criticit\u00e0 \u00e8 stato istituito il C.O.C.<\/span><\/p>\n<p>Per informazioni \u00e8 attivo il Numero Verde del <strong>CFR:\u00a0 800.276570<\/strong>.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Centro Funzionale Regionale ha emesso un Avviso di Criticit\u00e0 idrogeologica ed idraulica regionale, valido dalla sera del 23 novembre 2019 e per le successive 18-24 ore, valutando il\u00a0livello di [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Il Centro Funzionale Regionale ha emesso un Avviso di Criticit\u00e0 idrogeologica ed idraulica regionale, valido dalla sera del 23 novembre 2019 e per le successive 18-24 ore, valutando il\u00a0livello di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-23T20:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW-768x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019\",\"datePublished\":\"2019-11-23T20:12:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/\"},\"wordCount\":54,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_AllertaMeteo_TW.png\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/\",\"name\":\"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_AllertaMeteo_TW.png\",\"datePublished\":\"2019-11-23T20:12:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_AllertaMeteo_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_AllertaMeteo_TW.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2019\\\/11\\\/23\\\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/","og_locale":"it_IT","og_type":"article","og_title":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina","og_description":"Il Centro Funzionale Regionale ha emesso un Avviso di Criticit\u00e0 idrogeologica ed idraulica regionale, valido dalla sera del 23 novembre 2019 e per le successive 18-24 ore, valutando il\u00a0livello di [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-11-23T20:12:27+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW-768x576.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019","datePublished":"2019-11-23T20:12:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/"},"wordCount":54,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW.png","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/","url":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/","name":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW.png","datePublished":"2019-11-23T20:12:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_AllertaMeteo_TW.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2019\/11\/23\/territorio-allerta-meteo-gialla-ordinaria-del-22-08-2019-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"TERRITORIO: ALLERTA METEO (ARANCIONE) DEL 23.11.2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/943\/revisions"}],"predecessor-version":[{"id":944,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/943\/revisions\/944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/379"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}