{"id":2194,"date":"2026-07-13T08:57:12","date_gmt":"2026-07-13T06:57:12","guid":{"rendered":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/"},"modified":"2026-07-13T08:57:12","modified_gmt":"2026-07-13T06:57:12","slug":"settimana-della-sicurezza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/","title":{"rendered":"Settimana della Sicurezza"},"content":{"rendered":"<div style=\"margin-bottom: 20px;font-family: Arial, sans-serif\">\n<p style=\"margin-bottom: 7px;padding-bottom:0px\"><b style=\"font-size: 18px;margin-bottom: 0px;padding-bottom:0px;display: block\">Date e orari dell&#8217;evento:<\/b><\/p>\n<p><em>Settimana della Sicurezza<br \/>\nPrevenire e contrastare le truffe ai soggetti pi\u00f9 vulnerabili<br \/>\nGli Operatori Volontari del Progetto di Servizio Civile Universale &#8220;UP 2024&#8221; invitano la cittadinanza all&#8217;incontro di sensibilizzazione<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Settimana della Sicurezza<br \/>\nPrevenire e contrastare le truffe ai soggetti pi\u00f9 vulnerabili<br \/>\nGli Operatori Volontari del Progetto di Servizio Civile Universale &#8220;UP 2024&#8221; invitano la cittadinanza all&#8217;incontro di sensibilizzazione<\/p>\n<p>Marted\u00ec 14 luglio 2026 &#8211; ore 10:00 &#8211; presso Aula Sala Consiliare<\/p>\n<p style=\"font-size: 16px;color: #2E3A46\"><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style=\"font-size: 16px;color: #555\">Tutti<\/span><\/p>\n<p style=\"font-size: 16px;color: #2E3A46\"><b>Costi:<\/b><\/p>\n<ul style=\"list-style-type: disc;padding-left: 20px;margin-top: 0px!important\">\n<li style=\"margin-bottom: 3px\"><span style=\"font-size: 16px\">Ingresso libero: Gratuito<\/span><\/li>\n<\/ul>\n<p><\/p>\n<p style=\"font-size: 16px;color: #2E3A46\"><b>Contatti:<\/b><\/p>\n<ul style=\"list-style-type: disc;padding-left: 20px;margin-top: 0px!important\">\n<li style=\"margin-bottom: 5px\"><span>Ufficio Relazioni con il Pubblico (U.R.P.)<\/span><\/li>\n<p><span style=\"font-size: 15px\"><b>Telefono<\/b>: 0836891063<\/span><br \/><span style=\"font-size: 15px\"><b>Email<\/b>: protocollo@comune.minervino.le.it<\/span><br \/><span style=\"font-size: 15px\"><b>PEC<\/b>: protocollo.comuneminervino.le@pec.rupar.puglia.it<\/span><\/ul>\n<p>&nbsp;<\/p>\n<p><b>Immagini<\/b><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/comune.minervino.le.it\/wp-content\/uploads\/2026\/07\/Settimana-della-Sicurezza-2026.jpeg\"><\/img><\/p>\n<p>\n\t\t\t<h4>Inizio<\/h4>\n<p>14\/07\/2026 10:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>13\/07\/2026 06:57<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Date e orari dell&#8217;evento: Settimana della Sicurezza Prevenire e contrastare le truffe ai soggetti pi\u00f9 vulnerabili Gli Operatori Volontari del Progetto di Servizio Civile Universale &#8220;UP 2024&#8221; invitano la cittadinanza [&hellip;]<\/p>\n","protected":false},"author":406,"featured_media":2197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Settimana della Sicurezza - Minervino di Lecce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settimana della Sicurezza - Minervino di Lecce\" \/>\n<meta property=\"og:description\" content=\"Date e orari dell&#8217;evento: Settimana della Sicurezza Prevenire e contrastare le truffe ai soggetti pi\u00f9 vulnerabili Gli Operatori Volontari del Progetto di Servizio Civile Universale &#8220;UP 2024&#8221; invitano la cittadinanza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Minervino di Lecce\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T06:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"minervino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"minervino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/\"},\"author\":{\"name\":\"minervino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#\\\/schema\\\/person\\\/2dde168657a8eda6dc7a6d613f3924a9\"},\"headline\":\"Settimana della Sicurezza\",\"datePublished\":\"2026-07-13T06:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/\"},\"wordCount\":109,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/wp-content\\\/uploads\\\/sites\\\/212\\\/2026\\\/07\\\/Settimana-della-Sicurezza-2026-1.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/\",\"name\":\"Settimana della Sicurezza - Minervino di Lecce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/wp-content\\\/uploads\\\/sites\\\/212\\\/2026\\\/07\\\/Settimana-della-Sicurezza-2026-1.jpeg\",\"datePublished\":\"2026-07-13T06:57:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/wp-content\\\/uploads\\\/sites\\\/212\\\/2026\\\/07\\\/Settimana-della-Sicurezza-2026-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/wp-content\\\/uploads\\\/sites\\\/212\\\/2026\\\/07\\\/Settimana-della-Sicurezza-2026-1.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/2026\\\/07\\\/13\\\/settimana-della-sicurezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Settimana della Sicurezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/minervino\\\/#\\\/schema\\\/person\\\/2dde168657a8eda6dc7a6d613f3924a9\",\"name\":\"minervino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g\",\"caption\":\"minervino\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Settimana della Sicurezza - Minervino di Lecce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/","og_locale":"it_IT","og_type":"article","og_title":"Settimana della Sicurezza - Minervino di Lecce","og_description":"Date e orari dell&#8217;evento: Settimana della Sicurezza Prevenire e contrastare le truffe ai soggetti pi\u00f9 vulnerabili Gli Operatori Volontari del Progetto di Servizio Civile Universale &#8220;UP 2024&#8221; invitano la cittadinanza [&hellip;]","og_url":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/","og_site_name":"Minervino di Lecce","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-07-13T06:57:12+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg","type":"image\/jpeg"}],"author":"minervino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"minervino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/"},"author":{"name":"minervino","@id":"https:\/\/comunicacity.net\/minervino\/#\/schema\/person\/2dde168657a8eda6dc7a6d613f3924a9"},"headline":"Settimana della Sicurezza","datePublished":"2026-07-13T06:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/"},"wordCount":109,"publisher":{"@id":"https:\/\/comunicacity.net\/minervino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/","url":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/","name":"Settimana della Sicurezza - Minervino di Lecce","isPartOf":{"@id":"https:\/\/comunicacity.net\/minervino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg","datePublished":"2026-07-13T06:57:12+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#primaryimage","url":"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/minervino\/wp-content\/uploads\/sites\/212\/2026\/07\/Settimana-della-Sicurezza-2026-1.jpeg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/minervino\/2026\/07\/13\/settimana-della-sicurezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/minervino\/"},{"@type":"ListItem","position":2,"name":"Settimana della Sicurezza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/minervino\/#website","url":"https:\/\/comunicacity.net\/minervino\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/minervino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/minervino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/minervino\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/minervino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/minervino\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/minervino\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/minervino\/#\/schema\/person\/2dde168657a8eda6dc7a6d613f3924a9","name":"minervino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b14338f83975ceed662f35457578d2c5046f5d3bd78c20ee94a0764b75a853b?s=96&d=mm&r=g","caption":"minervino"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"14\/07\/2026 10:00","cc4_eve_data_fine":"13\/07\/2026 06:57","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003912"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/posts\/2194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/users\/406"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/comments?post=2194"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/posts\/2194\/revisions"}],"predecessor-version":[{"id":2196,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/posts\/2194\/revisions\/2196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/media?parent=2194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/categories?post=2194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/minervino\/wp-json\/wp\/v2\/tags?post=2194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}