{"id":28,"date":"2021-04-13T15:38:43","date_gmt":"2021-04-13T13:38:43","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/?post_type=info&#038;p=28"},"modified":"2021-04-13T15:44:52","modified_gmt":"2021-04-13T13:44:52","slug":"info-generali","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/","title":{"rendered":"Info generali"},"content":{"rendered":"<div class=\"list\">\n<div class=\"item\">\n<p>Provincia<\/p>\n<h2 class=\"ccBold\">Salerno<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Regione<\/p>\n<h2 class=\"ccBold\">Campania<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Popolazione Residente<\/p>\n<h2 class=\"ccBold\">6.432<\/h2>\n<\/div>\n<div class=\"item\">\n<p>CAP<\/p>\n<h2 class=\"ccBold\">84033<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Prefisso Telefonico<\/p>\n<h2 class=\"ccBold\">0975<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Denominazione Abitanti<\/p>\n<h2 class=\"ccBold\">Montesanesi<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Santo Patrono<\/p>\n<h2 class=\"ccBold\">San Nicola<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Festa Patronale<\/p>\n<h2 class=\"ccBold\">6 dicembre<\/h2>\n<\/div>\n<div class=\"item\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Provincia Salerno Regione Campania Popolazione Residente 6.432 CAP 84033 Prefisso Telefonico 0975 Denominazione Abitanti Montesanesi Santo Patrono San Nicola Festa Patronale 6 dicembre<\/p>\n","protected":false},"featured_media":5,"parent":0,"menu_order":0,"template":"","meta":[],"class_list":["post-28","info","type-info","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Info generali - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Info generali - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"Provincia Salerno Regione Campania Popolazione Residente 6.432 CAP 84033 Prefisso Telefonico 0975 Denominazione Abitanti Montesanesi Santo Patrono San Nicola Festa Patronale 6 dicembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T13:44:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/\",\"name\":\"Info generali - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/montesano.jpg\",\"datePublished\":\"2021-04-13T13:38:43+00:00\",\"dateModified\":\"2021-04-13T13:44:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/montesano.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/montesano.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/info\\\/info-generali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info generali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Info generali - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/","og_locale":"it_IT","og_type":"article","og_title":"Info generali - Montesano sulla Marcellana","og_description":"Provincia Salerno Regione Campania Popolazione Residente 6.432 CAP 84033 Prefisso Telefonico 0975 Denominazione Abitanti Montesanesi Santo Patrono San Nicola Festa Patronale 6 dicembre","og_url":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-04-13T13:44:52+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/","url":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/","name":"Info generali - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg","datePublished":"2021-04-13T13:38:43+00:00","dateModified":"2021-04-13T13:44:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/info\/info-generali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/#primaryimage","url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg","contentUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/info\/info-generali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"Info generali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/info\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/info"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media\/5"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}