{"id":17773,"date":"2022-09-15T13:20:23","date_gmt":"2022-09-15T11:20:23","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/"},"modified":"2022-09-15T13:23:41","modified_gmt":"2022-09-15T11:23:41","slug":"lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/","title":{"rendered":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19"},"content":{"rendered":"<p style=\"text-align: center\"><strong>IL SINDACO<\/strong><\/p>\n<p style=\"text-align: center\">RENDE NOTO<\/p>\n<p>Che limitatamente alle consultazioni elettorali dell\u2019anno 2022, gli elettori sottoposti a trattamento domiciliare o in condizioni di isolamento per COVID-19 sono ammessi ad esprimere il voto presso il proprio domicilio nel comune di residenza.<\/p>\n<p>A tal fine, tra il 10\u00b0 e il 5\u00b0 giorno antecedente quello della votazione cio\u00e8 tra gioved\u00ec 15 settembre e marted\u00ec 20 settembre 2022 l\u2019elettore deve far pervenire al Comune nelle cui liste \u00e8 iscritto, i seguenti documenti:<\/p>\n<p>1. una dichiarazione in cui si attesta la volont\u00e0 di esprimere il voto presso il proprio domicilio indicando con precisione l\u2019indirizzo completo del domicilio stesso;<\/p>\n<p>2. un certificato, rilasciato dal funzionario medico designato dai competenti organi dell\u2019azienda sanitaria locale, in data non anteriore al 11 settembre 2022 (14\u00b0 giorno antecedente la data della votazione), che attesti l\u2019esistenza delle condizioni di cui all\u2019articolo 3, comma 1, del decreto-legge in oggetto (sottoposti a trattamento domiciliare o in condizioni di isolamento per COVID-19).<\/p>\n<p>L\u2019ufficio elettorale comunale \u00e8 a disposizione per ulteriori chiarimenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL SINDACO RENDE NOTO Che limitatamente alle consultazioni elettorali dell\u2019anno 2022, gli elettori sottoposti a trattamento domiciliare o in condizioni di isolamento per COVID-19 sono ammessi ad esprimere il voto [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":17776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-17773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"IL SINDACO RENDE NOTO Che limitatamente alle consultazioni elettorali dell\u2019anno 2022, gli elettori sottoposti a trattamento domiciliare o in condizioni di isolamento per COVID-19 sono ammessi ad esprimere il voto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T11:20:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T11:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19\",\"datePublished\":\"2022-09-15T11:20:23+00:00\",\"dateModified\":\"2022-09-15T11:23:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/\"},\"wordCount\":185,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/09\\\/Notizie-ed-informazioni-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/\",\"name\":\"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/09\\\/Notizie-ed-informazioni-2.png\",\"datePublished\":\"2022-09-15T11:20:23+00:00\",\"dateModified\":\"2022-09-15T11:23:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/09\\\/Notizie-ed-informazioni-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/09\\\/Notizie-ed-informazioni-2.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/09\\\/15\\\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/","og_locale":"it_IT","og_type":"article","og_title":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana","og_description":"IL SINDACO RENDE NOTO Che limitatamente alle consultazioni elettorali dell\u2019anno 2022, gli elettori sottoposti a trattamento domiciliare o in condizioni di isolamento per COVID-19 sono ammessi ad esprimere il voto [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-09-15T11:20:23+00:00","article_modified_time":"2022-09-15T11:23:41+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png","type":"image\/png"}],"author":"gestoreyic","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19","datePublished":"2022-09-15T11:20:23+00:00","dateModified":"2022-09-15T11:23:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/"},"wordCount":185,"publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/","url":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/","name":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19 - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png","datePublished":"2022-09-15T11:20:23+00:00","dateModified":"2022-09-15T11:23:41+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#primaryimage","url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png","contentUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/09\/Notizie-ed-informazioni-2.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/2022\/09\/15\/lezioni-politiche-del-25-settembre-2022-esercizio-domiciliare-del-diritto-di-voto-da-parte-degli-elettori-sottoposti-a-trattamento-domiciliare-o-in-condizioni-di-quarantena-o-isolamento-fidu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"ELEZIONI POLITICHE del 25 SETTEMBRE 2022 \u2013 Esercizio domiciliare del diritto di voto da parte degli elettori sottoposti a trattamento domiciliare o in condizioni di quarantena o isolamento fiduciario per Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/montesano\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"17903"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts\/17773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/comments?post=17773"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts\/17773\/revisions"}],"predecessor-version":[{"id":17775,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts\/17773\/revisions\/17775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media\/17776"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=17773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/categories?post=17773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/tags?post=17773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}