{"id":17799,"date":"2022-10-20T10:46:12","date_gmt":"2022-10-20T08:46:12","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/"},"modified":"2022-10-20T10:46:12","modified_gmt":"2022-10-20T08:46:12","slug":"voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/","title":{"rendered":"Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">La Regione Campania mette a disposizione un importante strumento per le famiglie. Ecco i dettagli:<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Con decreto dirigenziale della DG Politiche sociali e socio-sanitarie n. 330 del 23\/09\/2022 \u00e8 stato approvato l&#8217;avviso pubblico:<\/div>\n<div dir=\"auto\">&#8220;Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta&#8221;.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">I destinatari del presente Avviso sono le famiglie, anche monogenitoriali, residenti nella Regione Campania, con minori a carico di et\u00e0 compresa tra 0 e 36 mesi.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Dal giorno 12\/10\/2022 sar\u00e0 possibile presentare le domande per la richiesta del voucher nidi attraverso il servizio digitale raggiungibile al seguente link:<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><a class=\"x1i10hfl xjbqb8w x6umtig x1b1mbwd xaqea5y xav7gou x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1fey0fg\" role=\"link\" href=\"https:\/\/servizi-digitali.regione.campania.it\/VoucherAsili?fbclid=IwAR0XOnlRlX6UfBIu4y4jpa57FhMv-abJR_d7AZv8q2_meqGDLprEGxacj_M\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/servizi-digitali.regione.campania.it\/VoucherAsili<\/a><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Il termine per la presentazione delle domande \u00e8 il 30\/11\/2022.<\/div>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17801\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/avviso-voucher-accesso-nidi-230922.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/avviso-voucher-accesso-nidi-230922.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso-voucher-accesso-nidi-230922<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Campania mette a disposizione un importante strumento per le famiglie. Ecco i dettagli: Con decreto dirigenziale della DG Politiche sociali e socio-sanitarie n. 330 del 23\/09\/2022 \u00e8 stato [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":17800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-17799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voucher per l&#039;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#039;abbattimento della retta - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voucher per l&#039;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#039;abbattimento della retta - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"La Regione Campania mette a disposizione un importante strumento per le famiglie. Ecco i dettagli: Con decreto dirigenziale della DG Politiche sociali e socio-sanitarie n. 330 del 23\/09\/2022 \u00e8 stato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-20T08:46:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta\",\"datePublished\":\"2022-10-20T08:46:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/\"},\"wordCount\":119,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/10\\\/SCUOLA.png\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/\",\"name\":\"Voucher per l'accesso ai nidi destinati a famiglie aventi requisiti ISEE per l'abbattimento della retta - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/10\\\/SCUOLA.png\",\"datePublished\":\"2022-10-20T08:46:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/10\\\/SCUOLA.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2022\\\/10\\\/SCUOLA.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/2022\\\/10\\\/20\\\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voucher per l'accesso ai nidi destinati a famiglie aventi requisiti ISEE per l'abbattimento della retta - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/","og_locale":"it_IT","og_type":"article","og_title":"Voucher per l'accesso ai nidi destinati a famiglie aventi requisiti ISEE per l'abbattimento della retta - Montesano sulla Marcellana","og_description":"La Regione Campania mette a disposizione un importante strumento per le famiglie. Ecco i dettagli: Con decreto dirigenziale della DG Politiche sociali e socio-sanitarie n. 330 del 23\/09\/2022 \u00e8 stato [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-10-20T08:46:12+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png","type":"image\/png"}],"author":"gestoreyic","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta","datePublished":"2022-10-20T08:46:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/"},"wordCount":119,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/","url":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/","name":"Voucher per l'accesso ai nidi destinati a famiglie aventi requisiti ISEE per l'abbattimento della retta - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png","datePublished":"2022-10-20T08:46:12+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#primaryimage","url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png","contentUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2022\/10\/SCUOLA.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/2022\/10\/20\/voucher-per-laccesso-ai-nidi-destinati-a-famiglie-aventi-requisiti-isee-per-labbattimento-della-retta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"Voucher per l&#8217;accesso ai nidi destinati a famiglie aventi requisiti ISEE per l&#8217;abbattimento della retta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/montesano\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"17934"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts\/17799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/comments?post=17799"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/posts\/17799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media\/17800"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=17799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/categories?post=17799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/tags?post=17799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}