{"id":37,"date":"2021-04-13T15:49:59","date_gmt":"2021-04-13T13:49:59","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/?post_type=turismo&#038;p=37"},"modified":"2021-04-13T15:50:45","modified_gmt":"2021-04-13T13:50:45","slug":"come-arrivare-a-montesano","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/","title":{"rendered":"Come arrivare a Montesano"},"content":{"rendered":"<p>Situato al confine con la Lucania, sui Monti della Maddalena, si trova in prossimit\u00e0 della gola che conduce dal Vallo di Diano alla Val d\u2019Agri. La storia locale narra che gli abitanti di Marcellinum, in seguito ad epidemie di peste ed all\u2019aria malsana dovuta ai luoghi paludosi, si siano rifugiati in collina dove fu fondato, intorno all\u2019anno Mille, il nuovo paese. Proprio per la salubrit\u00e0 dell\u2019aria e delle sue numerose sorgenti oligominerali, che oggi la rendono un rinomato centro termale, fu denominata Montesano. Il toponimo \u201csulla Marcellana\u201d deriva dal luogo di origine Marcellinum e dalla strada Marcellana che lo attraversava.<\/p>\n<hr \/>\n<h4>IN AUTO<\/h4>\n<p>Il comune si trova a 12 km dall\u2019autostrada A3 Salerno-Reggio Calabria, con uscita al casello di Padula-Buonabitacolo, oppure \u00e8 raggiungibile mediante la nazionale S.S. 103<\/p>\n<hr \/>\n<h4>IN TRENO<\/h4>\n<p>La stazione FS \u00e8 quella di Montesano Sulla Marcellana sulla linea Lagonegro-Sicignano degli Alburni. Vi sono collegamenti giornalieri per Battipaglia, per Lagonegro<\/p>\n<hr \/>\n<h4>IN AUTOBUS<\/h4>\n<p>Il comune \u00e8 raggiungibile anche mediante autobus di autolinee private sulla linea S.S. 103-S.S. 19, con collegamenti per Moliterno, per Sala Consilina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situato al confine con la Lucania, sui Monti della Maddalena, si trova in prossimit\u00e0 della gola che conduce dal Vallo di Diano alla Val d\u2019Agri. La storia locale narra che [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":2,"template":"","meta":[],"class_list":["post-37","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come arrivare a Montesano - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come arrivare a Montesano - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"Situato al confine con la Lucania, sui Monti della Maddalena, si trova in prossimit\u00e0 della gola che conduce dal Vallo di Diano alla Val d\u2019Agri. La storia locale narra che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T13:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/come-arrivare-a-montesano\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/come-arrivare-a-montesano\\\/\",\"name\":\"Come arrivare a Montesano - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"datePublished\":\"2021-04-13T13:49:59+00:00\",\"dateModified\":\"2021-04-13T13:50:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/come-arrivare-a-montesano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/come-arrivare-a-montesano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/come-arrivare-a-montesano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come arrivare a Montesano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come arrivare a Montesano - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/","og_locale":"it_IT","og_type":"article","og_title":"Come arrivare a Montesano - Montesano sulla Marcellana","og_description":"Situato al confine con la Lucania, sui Monti della Maddalena, si trova in prossimit\u00e0 della gola che conduce dal Vallo di Diano alla Val d\u2019Agri. La storia locale narra che [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-04-13T13:50:45+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/montesano.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/","url":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/","name":"Come arrivare a Montesano - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"datePublished":"2021-04-13T13:49:59+00:00","dateModified":"2021-04-13T13:50:45+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/come-arrivare-a-montesano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"Come arrivare a Montesano"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/turismo"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}