{"id":41,"date":"2021-04-13T15:55:13","date_gmt":"2021-04-13T13:55:13","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/?post_type=turismo&#038;p=41"},"modified":"2021-04-13T15:55:13","modified_gmt":"2021-04-13T13:55:13","slug":"chiesa-ed-ex-convento-cappuccini","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/","title":{"rendered":"Chiesa ed ex Convento Cappuccini"},"content":{"rendered":"<p>Il cenobio dei cappuccini \u00e8 ubicato in aperta campagna nella localit\u00e0 omonima a sud di Montesano.<\/p>\n<p>Dalla relazione sui conventi della Provincia Monastica di Basilicata del 1650 si rileva che chiesa e convento furono fondati nell\u2019anno 1590 per volere dell\u2019 \u201cUniversit\u00e0\u201d e col consenso del vescovo di Capaccio, alla cui Diocesi apparteneva, allora, Montesano.<\/p>\n<p>I lavori di costruzione procedettero con impegno ed alacrit\u00e0, tanto che nel 1596 il complesso era gi\u00e0 ultimato e pot\u00e9 accogliere la prima comunit\u00e0 religiosa.<br \/>\nLa struttura era circondata da mura, di cui restano tracce, che perimetravano gli orti annessi.<br \/>\nDi particolare importanza era la presenza di una \u201cgualchiera\u201d, alimentata da una copiosa sorgente che sgorgava nell\u2019orto, e, dal 1815, anche di un lanificio; motivo che ne evit\u00f2 la chiusura durante il decennio di dominazione francese.<\/p>\n<p>L\u2019edificio era composto da due ali conventuali con interposta chiesetta dedicata, in principio, a S. Francesco e, in seguito, a S. Matteo. Del convento, l\u2019ala destra, da tempo fatiscente, fu definitivamente demolita alcuni anni or sono per far posto ad un campanile in cemento armato con piazzetta antistante; l\u2019ala sinistra, ancora esistente ma in stato di avanzato degrado, presenta un impianto a corte, con chiostro a piano terra, sul quale si aprono ambienti per uso comune: refettorio, cucina, dispensa e forno.<\/p>\n<p>Il chiostro, di armoniose proporzioni, \u00e8 delimitato da archi in muratura a tutto sesto e corridoi con volta a botte. Al primo livello si accede per mezzo di una scala a due rampe con gradini realizzati in pietra locale, con soffitto a volta rampante, la cui imposta \u00e8 sormontata da affresco raffigurante lo stemma francescano.<\/p>\n<p>L\u2019ambiente accoglie su tre lati diciassette celle per i frati ed una riservata al P. Provinciale; il quarto lato, contiguo alla chiesa, funge da loggiato con affaccio sul chiostro. Il livello superiore, di epoca posteriore, presumibilmente inizio \u2018800, presenta la medesima impostazione di quello sottostante e venne elevato per ospitare lo \u201cStudentato\u201d per la formazione dei futuri sacerdoti.<br \/>\nDurante la sua attivit\u00e0, protrattasi per oltre due secoli e mezzo, il convento fu sede di ben sei Capitoli provinciali, l\u2019ultimo dei quali celebrato nel 1846. Nel 1866, in virt\u00f9, della legge eversiva del 7 luglio, venne inesorabilmente soppresso ed acquistato dalle famiglie Cestari e Gerbasio di Montesano. Tra il 1886 e il 1888 il vescovo di Teggiano del tempo mons. Vincenzo Addessi, vista la disponibilit\u00e0 dei proprietari, pens\u00f2 ad un suo riutilizzo per affidarlo ai PP. Passionisti, senza, per\u00f2, riuscirvi a causa di una \u201cvertenza\u201d sulla chiesa. Una proposta analoga fu avanzata nel 1942, ai PP. Missionari di Sacri Cuori, dal Vescovo mons. Oronzo Caldarola; essi, pur inviando sul posto il P.<\/p>\n<p>Giuseppe Bottiglieri che, durante la sua permanenza, si adoper\u00f2 per il completamento della \u201cfabbrica\u201d sulla navata laterale, non ritennero opportuno accettare l\u2019invito. L\u2019ultima utilizzazione meritevole di nota, quale convitto per giovani studenti, avvenne negli anni 1944 \u2013 \u201945 ad opera dei PP. Vocazionisti. Abbandonato anche da questi, venne adibito ad annessi agricoli con ovile. Dopo la recente donazione dello stabile da parte della proprietaria dott.ssa Cestari al Comune di Montesano, sono state intraprese le necessarie pratiche per il suo completo recupero.<\/p>\n<p>La chiesa ebbe, in origine, una sola navata, separata dall\u2019abside da un magnifico arco trionfale. Quattro archi a pieno centro, aperti nella parete laterale di destra, immettono nella navata minore, aggiunta al corpo principale verosimilmente intorno alla seconda met\u00e0 del XVII secolo. Essa accoglie le cappelle con altari e icone di S. Francesco, S. Rosa da Viterbo, S. Antonio e S. Felice. Nel pavimento trovano posto due sepolture, una dei Frati e l\u2019altra della famiglia Cestari.<\/p>\n<p>Le pareti di quest\u2019ultima sono prive di qualsiasi ornamento, a differenza dell\u2019aula maggiore, che \u00e8 ricoperta di stucchi, lesene e decorazioni di gusto barocco. Il pregevole altare maggiore, in marmo policromo, fu fatto edificare nel 1863 dalla Pubblica Amministrazione di Montesano. Una tela raffigurante l\u2019Immacolata circondata da simboli e con ai piedi gli apostoli S. Giovanni e S. Matteo, che un tempo campeggiava sulla parete di fondo dell\u2019abside, \u00e8 stata recentemente restaurata e sistemata sulla parete sinistra del presbiterio.<\/p>\n<p>La poca luce proveniente dai due finestroni di sinistra lasciano l\u2019ambiente in una mistica penombra che predispone al raccoglimento.<\/p>\n<p>Prof. Gennaro Arteca<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42 aligncenter\" src=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png\" alt=\"\" width=\"283\" height=\"222\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-43 aligncenter\" src=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-1.png\" alt=\"\" width=\"283\" height=\"189\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cenobio dei cappuccini \u00e8 ubicato in aperta campagna nella localit\u00e0 omonima a sud di Montesano. Dalla relazione sui conventi della Provincia Monastica di Basilicata del 1650 si rileva che [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":38,"menu_order":2,"template":"","meta":[],"class_list":["post-41","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"Il cenobio dei cappuccini \u00e8 ubicato in aperta campagna nella localit\u00e0 omonima a sud di Montesano. Dalla relazione sui conventi della Provincia Monastica di Basilicata del 1650 si rileva che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/\",\"name\":\"Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png\",\"datePublished\":\"2021-04-13T13:55:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/chiesa-ed-ex-convento-cappuccini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I monumenti\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa ed ex Convento Cappuccini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana","og_description":"Il cenobio dei cappuccini \u00e8 ubicato in aperta campagna nella localit\u00e0 omonima a sud di Montesano. Dalla relazione sui conventi della Provincia Monastica di Basilicata del 1650 si rileva che [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/","url":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/","name":"Chiesa ed ex Convento Cappuccini - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png","datePublished":"2021-04-13T13:55:13+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/#primaryimage","url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png","contentUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Chiesa-ed-Convento-degli-ex-Cappuccini-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/chiesa-ed-ex-convento-cappuccini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"I monumenti","item":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/"},{"@type":"ListItem","position":3,"name":"Chiesa ed ex Convento Cappuccini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo\/38"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}