{"id":48,"date":"2021-04-13T15:59:42","date_gmt":"2021-04-13T13:59:42","guid":{"rendered":"https:\/\/comunicacity.net\/montesano\/?post_type=turismo&#038;p=48"},"modified":"2021-04-13T15:59:42","modified_gmt":"2021-04-13T13:59:42","slug":"cappella-di-s-antonio-abate","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/","title":{"rendered":"Cappella di S. Antonio Abate"},"content":{"rendered":"<p>La chiesetta, detta comunemente di S. Antonio, ha origini molto antiche, legate al culto per il Santo Eremita, introdotto nell\u2019Italia Meridionale dagli Antoniani di Vienne, nel Delfinato, verosimilmente nella prima met\u00e0 del Sec. XIII. La data del 1617 riportata sulla piccola campana potrebbe testimoniare un restauro avvenuto in quell\u2019anno o piuttosto un cambiamento di titolo; infatti nella relazione della Visita pastorale fatta dal Commissario apostolico Lelio Ferro il 18 settembre 1687, \u00e8 menzionata sotto il Titolo di \u201cS. Maria dei Martiri\u201d, notizia confermata anche dall\u2019iscrizione impressa sulla stessa campana.<\/p>\n<p>Il citato documento ci informa, inoltre, che, annesso alla Cappella, si trovava l\u2019\u201dospedale\u201d, edificio di ridotte dimensioni adibito all\u2019accoglienza e alla cura degli infermi. In un successivo documento del 1800 appare intitolata a S. Antonio e S. Lucia, di diritto di Patronato della famiglia Cestari: \u201cha pesi di messe n\u00b0 quaranta; due delle quali solamente sono cantate, una \u00e0 17 gennaio, e l\u2019altra \u00e0 13 dicembre, giorni di S. Antonio e S. Lucia, e le altre lette per ciascun anno\u201d.<\/p>\n<p>L\u2019edificio si presenta a pianta rettangolare ad aula unica; il soffitto \u00e8 a botte, intersecato da otto velette laterali; sull\u2019altare maggiore si pu\u00f2 ammirare una pregevole tela raffigurante S. Antonio in mezzo a due martiri: S. Lucia e S. Agnese (?).<\/p>\n<p>La facciata, rimessa a nuovo di recente, \u00e8 decorata con lesene laterali a stucco, sormontate da timpano abbellito con mensole e rosette, con foro semicircolare centrale.<br \/>\nAlla sommit\u00e0 del tetto si erge un piccolo campanile a vela.<\/p>\n<p>Per quanto concerne la tradizione locale, fino a qualche anno addietro, il 17 gennaio, nella piazzetta antistante si portavano gli animali per la benedizione, che avveniva dopo la celebrazione della Messa; persiste ancora, invece, quella dell\u2019accensione dei \u201cfuochi\u201d, che si tiene la sera del 16 gennaio, previa \u201ccerca\u201d della legna nei giorni precedenti.<\/p>\n<p>Prof. Gennaro Arteca<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49 aligncenter\" src=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png\" alt=\"\" width=\"283\" height=\"304\" srcset=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png 283w, https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S-279x300.png 279w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chiesetta, detta comunemente di S. Antonio, ha origini molto antiche, legate al culto per il Santo Eremita, introdotto nell\u2019Italia Meridionale dagli Antoniani di Vienne, nel Delfinato, verosimilmente nella prima [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":38,"menu_order":4,"template":"","meta":[],"class_list":["post-48","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cappella di S. Antonio Abate - Montesano sulla Marcellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cappella di S. Antonio Abate - Montesano sulla Marcellana\" \/>\n<meta property=\"og:description\" content=\"La chiesetta, detta comunemente di S. Antonio, ha origini molto antiche, legate al culto per il Santo Eremita, introdotto nell\u2019Italia Meridionale dagli Antoniani di Vienne, nel Delfinato, verosimilmente nella prima [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesano sulla Marcellana\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/\",\"name\":\"Cappella di S. Antonio Abate - Montesano sulla Marcellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Cappella-di-S.png\",\"datePublished\":\"2021-04-13T13:59:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Cappella-di-S.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/montesano\\\/wp-content\\\/uploads\\\/sites\\\/198\\\/2021\\\/04\\\/Cappella-di-S.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/cappella-di-s-antonio-abate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I monumenti\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/turismo\\\/i-monumenti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cappella di S. Antonio Abate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"name\":\"Montesano sulla Marcellana\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cappella di S. Antonio Abate - Montesano sulla Marcellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/","og_locale":"it_IT","og_type":"article","og_title":"Cappella di S. Antonio Abate - Montesano sulla Marcellana","og_description":"La chiesetta, detta comunemente di S. Antonio, ha origini molto antiche, legate al culto per il Santo Eremita, introdotto nell\u2019Italia Meridionale dagli Antoniani di Vienne, nel Delfinato, verosimilmente nella prima [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/","og_site_name":"Montesano sulla Marcellana","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/","url":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/","name":"Cappella di S. Antonio Abate - Montesano sulla Marcellana","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png","datePublished":"2021-04-13T13:59:42+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/#primaryimage","url":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png","contentUrl":"https:\/\/comunicacity.net\/montesano\/wp-content\/uploads\/sites\/198\/2021\/04\/Cappella-di-S.png"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/cappella-di-s-antonio-abate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesano\/"},{"@type":"ListItem","position":2,"name":"I monumenti","item":"https:\/\/comunicacity.net\/montesano\/turismo\/i-monumenti\/"},{"@type":"ListItem","position":3,"name":"Cappella di S. Antonio Abate"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesano\/#website","url":"https:\/\/comunicacity.net\/montesano\/","name":"Montesano sulla Marcellana","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/montesano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/montesano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/montesano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/montesano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/turismo\/38"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesano\/wp-json\/wp\/v2\/media?parent=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}