{"id":509,"date":"2016-07-15T15:28:21","date_gmt":"2016-07-15T13:28:21","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?post_type=info&#038;p=509"},"modified":"2016-07-15T15:28:21","modified_gmt":"2016-07-15T13:28:21","slug":"relazioni-al-pubblico","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/","title":{"rendered":"Relazioni al Pubblico"},"content":{"rendered":"<h3 class=\"ccGrey\">Responsabile<\/h3>\n<h3 class=\"cBlack\"><i class=\"user icon\"><\/i>Donata Giani<\/h3>\n<h3 class=\"ccGrey\">Addetti<\/h3>\n<h3 class=\"cBlack\"><i class=\"user icon\"><\/i>Alessandra Chiesa<\/h3>\n<p><i class=\"fa fa-envelope\"><\/i><a href=\"mailto:montesegale@libero.it\">montesegale@libero.it<\/a><\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:0383 99030\">0383 99030<\/a><\/p>\n<p><i class=\"fa fa-print\"><\/i>0383 99191<\/p>\n<p><i class=\"map marker icon\"><\/i>Piazza del Municipio Eroi di Nassiriya n.1<\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Dal luned\u00ec al venerd\u00ec<span class=\"ccGrey\"> 09:00 \u2013 12:00<\/span><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Dal luned\u00ec al mercoled\u00ec<span class=\"ccGrey\"> 15:00 \u2013 18:00<\/span><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Sabato<span class=\"ccGrey\"> 09:00 \u2013 12:00<\/span><\/p>\n<div class=\"ui divider\"><strong>\u00a0<\/strong><\/div>\n<p><strong>Competenze dell\u2019Ufficio:<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">L&#8217;Ufficio Relazioni con il Pubblico \u00e8 la struttura preposta all&#8217;attivit\u00e0 di comunicazione, sia esterna, rivolta ai cittadini, alla collettivit\u00e0 ed agli altri \u00a0Enti, sia interna, diretta nell&#8217;ambito dell&#8217;Ente. In questo ambito l&#8217;attivit\u00e0 dell&#8217;U.R.P. comprende:<\/li>\n<li style=\"text-align: justify;\">Informazioni al cittadino sui servizi offerti dall\u2019Ente;<\/li>\n<li style=\"text-align: justify;\">Assistenza nell\u2019avvio di pratiche di varia natura e consegna della relativa modulistica;<\/li>\n<li style=\"text-align: justify;\">Accoglienza di suggerimenti e reclami;<\/li>\n<li style=\"text-align: justify;\">Aggiornamento e gestione sito internet istituzionale;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Responsabile Donata Giani Addetti Alessandra Chiesa montesegale@libero.it 0383 99030 0383 99191 Piazza del Municipio Eroi di Nassiriya n.1 Dal luned\u00ec al venerd\u00ec 09:00 \u2013 12:00 Dal luned\u00ec al mercoled\u00ec 15:00 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":505,"menu_order":4,"template":"","meta":[],"class_list":["post-509","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Relazioni al Pubblico - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relazioni al Pubblico - Montesegale\" \/>\n<meta property=\"og:description\" content=\"Responsabile Donata Giani Addetti Alessandra Chiesa montesegale@libero.it 0383 99030 0383 99191 Piazza del Municipio Eroi di Nassiriya n.1 Dal luned\u00ec al venerd\u00ec 09:00 \u2013 12:00 Dal luned\u00ec al mercoled\u00ec 15:00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/montesegale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/relazioni-al-pubblico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/relazioni-al-pubblico\\\/\",\"name\":\"Relazioni al Pubblico - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"datePublished\":\"2016-07-15T13:28:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/relazioni-al-pubblico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/relazioni-al-pubblico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/relazioni-al-pubblico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uffici Comunali\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/info\\\/uffici-comunali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Relazioni al Pubblico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Relazioni al Pubblico - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/","og_locale":"it_IT","og_type":"article","og_title":"Relazioni al Pubblico - Montesegale","og_description":"Responsabile Donata Giani Addetti Alessandra Chiesa montesegale@libero.it 0383 99030 0383 99191 Piazza del Municipio Eroi di Nassiriya n.1 Dal luned\u00ec al venerd\u00ec 09:00 \u2013 12:00 Dal luned\u00ec al mercoled\u00ec 15:00 [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/","og_site_name":"Montesegale","og_image":[{"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/montesegale.jpg","height":50,"width":50,"type":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/","url":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/","name":"Relazioni al Pubblico - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"datePublished":"2016-07-15T13:28:21+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/relazioni-al-pubblico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"Uffici Comunali","item":"https:\/\/comunicacity.net\/montesegale\/info\/uffici-comunali\/"},{"@type":"ListItem","position":3,"name":"Relazioni al Pubblico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/info\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/info\/505"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}