{"id":400,"date":"2015-10-07T21:59:09","date_gmt":"2015-10-07T19:59:09","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?p=400"},"modified":"2015-10-07T21:59:27","modified_gmt":"2015-10-07T19:59:27","slug":"strada-comunale-di-poggio-rajone","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/","title":{"rendered":"Strada comunale di Poggio Rajone"},"content":{"rendered":"<p>La strada comunale di Poggio Rajone rimarr\u00e0 chiusa al traffico nella giornata di domani 8 ottobre 2015 dalle ore 9,30 alle ore 12,00 per lavori di asfaltatura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La strada comunale di Poggio Rajone rimarr\u00e0 chiusa al traffico nella giornata di domani 8 ottobre 2015 dalle ore 9,30 alle ore 12,00 per lavori di asfaltatura.<\/p>\n","protected":false},"author":49,"featured_media":292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strada comunale di Poggio Rajone - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strada comunale di Poggio Rajone - Montesegale\" \/>\n<meta property=\"og:description\" content=\"La strada comunale di Poggio Rajone rimarr\u00e0 chiusa al traffico nella giornata di domani 8 ottobre 2015 dalle ore 9,30 alle ore 12,00 per lavori di asfaltatura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunemontesegale\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-07T19:59:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-07T19:59:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"169\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"montesegale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"montesegale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/\"},\"author\":{\"name\":\"montesegale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"headline\":\"Strada comunale di Poggio Rajone\",\"datePublished\":\"2015-10-07T19:59:09+00:00\",\"dateModified\":\"2015-10-07T19:59:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/\"},\"wordCount\":28,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/04\\\/lavori-in-corso-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/\",\"name\":\"Strada comunale di Poggio Rajone - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/04\\\/lavori-in-corso-1.jpg\",\"datePublished\":\"2015-10-07T19:59:09+00:00\",\"dateModified\":\"2015-10-07T19:59:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/04\\\/lavori-in-corso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/04\\\/lavori-in-corso-1.jpg\",\"width\":169,\"height\":98},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2015\\\/10\\\/07\\\/strada-comunale-di-poggio-rajone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strada comunale di Poggio Rajone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\",\"name\":\"montesegale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"caption\":\"montesegale\"},\"sameAs\":[\"http:\\\/\\\/www.comune.montesegale.pv.it\",\"https:\\\/\\\/www.facebook.com\\\/comunemontesegale\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/author\\\/montesegale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strada comunale di Poggio Rajone - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/","og_locale":"it_IT","og_type":"article","og_title":"Strada comunale di Poggio Rajone - Montesegale","og_description":"La strada comunale di Poggio Rajone rimarr\u00e0 chiusa al traffico nella giornata di domani 8 ottobre 2015 dalle ore 9,30 alle ore 12,00 per lavori di asfaltatura.","og_url":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/","og_site_name":"Montesegale","article_author":"https:\/\/www.facebook.com\/comunemontesegale","article_published_time":"2015-10-07T19:59:09+00:00","article_modified_time":"2015-10-07T19:59:27+00:00","og_image":[{"width":169,"height":98,"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg","type":"image\/jpeg"}],"author":"montesegale","twitter_misc":{"Scritto da":"montesegale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/"},"author":{"name":"montesegale","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"headline":"Strada comunale di Poggio Rajone","datePublished":"2015-10-07T19:59:09+00:00","dateModified":"2015-10-07T19:59:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/"},"wordCount":28,"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/","url":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/","name":"Strada comunale di Poggio Rajone - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg","datePublished":"2015-10-07T19:59:09+00:00","dateModified":"2015-10-07T19:59:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#primaryimage","url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/04\/lavori-in-corso-1.jpg","width":169,"height":98},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/2015\/10\/07\/strada-comunale-di-poggio-rajone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"Strada comunale di Poggio Rajone"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad","name":"montesegale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","caption":"montesegale"},"sameAs":["http:\/\/www.comune.montesegale.pv.it","https:\/\/www.facebook.com\/comunemontesegale"],"url":"https:\/\/comunicacity.net\/montesegale\/author\/montesegale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/400\/revisions\/401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media\/292"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}