{"id":524,"date":"2016-08-12T00:28:55","date_gmt":"2016-08-11T22:28:55","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?p=524"},"modified":"2016-08-12T00:28:55","modified_gmt":"2016-08-11T22:28:55","slug":"per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/","title":{"rendered":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie"},"content":{"rendered":"<div><\/div>\n<div><strong>Ripopolamento e nuova capacit\u00e0 di attrazione<\/strong><br \/>\nIl tema del ripopolamento dei piccoli comuni non pu\u00f2 limitarsi a proposte di interventi occasionali e frammentati, solitamente finalizzati a forme di sostegno economico a fasce deboli della popolazione (anziani, categorie disagiate, ecc.) o di incentivo ad iniziative economiche (ospitalit\u00e0 diffusa, valorizzazione produzioni tipiche artigianali e agro-alimentari, cooperazione e terzo settore) il cui \u201cmercato\u201d in queste aree \u00e8 una sfida che merita un maggiore approfondimento. E&#8217; necessario che si ripensi al tema nell&#8217;ambito di una pi\u00f9 complessiva e integrata strategia di sviluppo e di una diversa capacit\u00e0 di questi territori di attrarre nuovi residenti (oltre che di trattenere quelli che gi\u00e0 li abitano).<\/div>\n<div>Dall\u2019esperienza passata traiamo come insegnamento la necessit\u00e0 di rompere gli equilibri precostituiti. Le politiche e le iniziative per lo sviluppo locale, sin qui, spesso sono fallite (dai comuni piccoli si continua ad andar via) perch\u00e8 si \u00e8 pensato che (nei migliori dei casi) gli interventi per provare a costruire nuove e diverse economie potessero da soli creare nuovi servizi per i cittadini. E\u2019, invece, a monte di ogni efficace intervento che deve esserci \u201csviluppo e creazione\u201d dei servizi per la residenzialit\u00e0 (sanit\u00e0, scuola, trasporti) e lo si pu\u00f2 fare anche attraverso forme innovative che includano la partecipazione dei cittadini stessi. Da questa considerazione consegue che, piuttosto che puntare su fasce di popolazione in disagio (a cui destinare opportune e necessarie iniziative per la lotta alla povert\u00e0 e per il potenziamento delle politiche socio-assistenziali) si devono attrarre soggetti forti dal punto di vista delle competenze e del know-how, incentivando\/migliorando il contesto socio-economico locale (nuovo welfare, innovazione e creativit\u00e0, tecnologia e comunicazione). In questa direzione, interlocutori privilegiati per conseguire risultati efficaci e ricadute durature sono le giovani coppie &#8220;attive&#8221; e l'&#8221;aspirazione&#8221; di futuro che esse rappresentano.<\/div>\n<div>\n<strong>Piccoli comuni, Comunit\u00e0 per giovani coppie<\/strong><br \/>\nI piccoli comuni devono essere innanzitutto una scelta di vita. Perch\u00e8 questa scelta possa essere compiuta serenamente e consapevolmente, i piccoli comuni devono, quindi, costituire la risposta al bisogno di comunit\u00e0 inteso come tensione a conciliare cura, crescita e sicurezza e offrire soluzioni (diverse, compatibili e coerenti a livello locale) alle questioni della residenza, del lavoro e dei servizi. Un comune che ambisce a divenire &#8220;destinazione&#8221; per le giovani coppie \u00e8 un comune che pu\u00f2 definirsi user-friendly, orientato al cittadino\/ospite, caratterizzato dall&#8217;applicazione di criteri di accessibilit\u00e0 nei servizi offerti e di semplificazione burocratica nei rapporti con l&#8217;amministrazione. Non \u00e8 da considerare meno importante l'&#8221;asset comunitario&#8221; che questi luoghi devono saper e poter spendere per attrarre e divenire luoghi di futuro. Una delle scommesse \u00e8, infatti, quella sull&#8217;investimento in termini di relazioni e integrazione che le giovani coppie sono in animo di fare. Le giovani coppie sono in prospettiva famiglie che dovranno garantirsi (anche per i propri figli): una dimensione accogliente e ospitale; una realt\u00e0 sociale sicura e, nello stesso tempo, capace di aprirsi (anche attraverso gli strumenti dell&#8217;information and communications technology ma non solo) ad un mondo globale; una comunit\u00e0 che si poggia su radici solide ma capace di reinventarsi grazie all&#8217;innovazione sociale e culturale. Interessate a questa prospettiva sono quelle coppie che vogliono &#8220;alimentarsi&#8221; a tale asset ma che sono disposte a concorrere alla sua piena realizzazione, collaborando attivamente sia a livello di comportamenti individuali (presidio del territorio, raccolta differenziata, consumi ambientalmente e socialmente sostenibili, altro) sia di iniziative collettive (partecipazione alle scelte di sviluppo e responsabilit\u00e0 verso le istituzioni e i governi locali dei territori).<\/div>\n<div><\/div>\n<div>\n<strong>Un&#8217;ospitalit\u00e0 dinamica e aperta a nuove prospettive<\/strong><br \/>\nPerche i piccoli comuni siano in grado di farsi trovare pronti e preparati a questa scelta, \u00e8 necessario che le Amministrazioni individuino e mettano in campo strumenti, procedure e iniziative che siano in grado di generare dinamismo e aprire la comunit\u00e0 locale a nuove prospettive.<br \/>\n<strong>Pi\u00f9 vantaggi di cittadinanza<\/strong><br \/>\nFavorire la cittadinanza significa creare le condizioni di vantaggio per una nuova residenzialit\u00e0: semplificazioni amministrative e priorit\u00e0 nell&#8217;assegnazione di servizi (di assistenza socio-assistenziale, scolastici, volti all&#8217;infanzia\u00a0e\u00a0la conciliazione dei tempi e altro); e-governement e superamento del divario digitale; erogazione di buoni spesa da spendere solo sul territorio comunale (con evidenti ricadute economiche sull&#8217;economia locale); defiscalizzazioni in cambio di comportamenti virtuosi come ad esempio nell&#8217;adempimento dei servizi ambientali e d&#8217;igiene urbana. E&#8217; importante a tal proposito, sottolineare che, nell&#8217;attuale condizione di risorse sempre pi\u00f9 scarse, i piccoli Comuni, nel tentativo di compensare le risorse utilizzate per tali iniziative, si trovano, a differenza delle realt\u00e0 pi\u00f9 grandi, nelle condizioni migliori per sperimentare meccanismi che fanno leva sulla disponibilit\u00e0 dei nuovi ospiti alla compartecipazione nella realizzazione dei servizi alla collettivit\u00e0 (cittadinanza attiva).<br \/>\n<strong>\u00a0Pi\u00f9 opportunit\u00e0 d&#8217;abitare<\/strong><br \/>\nAl centro del tema, il costo degli alloggi e l&#8217;opportunit\u00e0 per le giovani coppie di avere una casa. Tra le soluzioni da adottare (oltre le forme di sostegno sia per l&#8217;affitto sia per l&#8217;acquisto e di disincentivo per quei residenti che mantengono gli alloggi sfitti e inutilizzati), si evidenzia il ricorso all&#8217;housing sociale e a percorsi di cooperazione fra proprietari e cittadini con la possibilit\u00e0 dell\u2019intervento pubblico a favore del privato (costruttori, proprietari e istituzioni finanziarie): residenza condivisa o cohousing, autocostruzione e autorecupero, attivazione di fondi Immobiliari ad apporto pubblico e privato.<br \/>\n<strong>Pi\u00f9 occasioni di socialit\u00e0<\/strong><br \/>\nLa presenza di spazi pubblici come luoghi d&#8217;incontro e di eventi \u00e8 la risposta alla ricerca di nuova vitalit\u00e0 espressa dalle giovani coppie e di una volont\u00e0 di radicamento nell\u2019espressione fisica e territoriale in cui si vive. Recupero e riqualificazione degli spazi urbani e proposte innovative per il &#8220;tempo libero&#8221; sono, quindi, i motori di un percorso aggregativo che ha effetti cogenti sul tessuto locale, anche considerando la necessit\u00e0 di ricercare nuove identit\u00e0 per i luoghi. Si tratta di progettare azioni e attivit\u00e0 come nuove occasioni di aggregazione che non entrano in concorrenza con quelle dei centri urbani ma vogliono essere alternative o semplicemente diverse, basandosi sull\u2019incontro di persone, sulle peculiarit\u00e0 locali e sul recupero della cultura territoriale.<\/div>\n<div><\/div>\n<div><strong>Patto di residenza tra &#8220;piccoli comuni&#8221; e &#8220;giovani coppie&#8221;<\/strong><br \/>\nI piccoli comuni (le amministrazioni e le comunit\u00e0) e le giovani coppie ospiti stringono un&#8217;alleanza, un &#8220;patto di residenza&#8221; che impegna ciascuno a intraprendere un &#8220;percorso virtuoso di convivenza&#8221;.<br \/>\nServizi, facilitazioni, incentivi e inclusione sono i termini su cui costruire questo patto.<br \/>\nL&#8217;Amministrazione comunale di Montesegale sta preparando un &#8220;Avviso pubblico&#8221; avente come oggetto il &#8220;SOSTEGNO ALL&#8217;INSEDIAMENTO DI NUCLEI FAMILIARI FORMATI DA GIOVANI COPPIE ATTIVE&#8221;. A fronte di un impegno a mantenere la residenza per cinque anni \u00e8 possibile accedere ad alcune tipologie di sostegno: le facilitazioni inerenti l&#8217;acquisizione di una casa con la formula dell&#8217;affitto a riscatto o la possibilit\u00e0 di accedere ad uno sconto sugli oneri di urbanizzazione; le agevolazioni sui servizi comunali come buoni legati alle nuove nascite o all&#8217;acquisto di libri scolastici o, ancora, la gratuit\u00e0 dello scuolabus; la messa a disposizione di uno spazio comunale di coworking per il telelavoro; le opportunit\u00e0 derivanti dall&#8217;adozione e attuazione da parte dell&#8217;Amministrazione di regolamenti\u00a0 specifici come quello sulla cittadinanza attiva o progetti specifici finalizzati a favorire reciprocit\u00e0 nelle relazioni ed incentivare la solidariet\u00e0 tra le famiglie di Montesegale.<br \/>\nL&#8217;Avviso pubblico, in questa fase sperimentale, sar\u00e0 tenuto aperto per un anno e sar\u00e0 volto all&#8217;ospitalit\u00e0 di massimo cinque nuclei familiari a cui sar\u00e0 chiesto di mantenere la residenza per almeno cinque anni. L&#8217;accettazione del patto e i reciproci impegni si concretizzeranno all&#8217;atto dell&#8217;assegnazione della residenza nel Comune di Montesegale.<\/div>\n<div><\/div>\n<div>Per informazioni scrivi a :<\/div>\n<div><\/div>\n<div><strong>montesegale@libero.it<\/strong><\/div>\n<div><\/div>\n<div><strong>sindaco.montesegale@libero.it<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ripopolamento e nuova capacit\u00e0 di attrazione Il tema del ripopolamento dei piccoli comuni non pu\u00f2 limitarsi a proposte di interventi occasionali e frammentati, solitamente finalizzati a forme di sostegno economico [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale\" \/>\n<meta property=\"og:description\" content=\"Ripopolamento e nuova capacit\u00e0 di attrazione Il tema del ripopolamento dei piccoli comuni non pu\u00f2 limitarsi a proposte di interventi occasionali e frammentati, solitamente finalizzati a forme di sostegno economico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunemontesegale\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-11T22:28:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1472\" \/>\n\t<meta property=\"og:image:height\" content=\"978\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"montesegale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"montesegale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/\"},\"author\":{\"name\":\"montesegale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"headline\":\"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie\",\"datePublished\":\"2016-08-11T22:28:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/\"},\"wordCount\":1238,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2016\\\/08\\\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/\",\"name\":\"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2016\\\/08\\\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg\",\"datePublished\":\"2016-08-11T22:28:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2016\\\/08\\\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2016\\\/08\\\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg\",\"width\":1472,\"height\":978},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2016\\\/08\\\/12\\\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\",\"name\":\"montesegale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"caption\":\"montesegale\"},\"sameAs\":[\"http:\\\/\\\/www.comune.montesegale.pv.it\",\"https:\\\/\\\/www.facebook.com\\\/comunemontesegale\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/author\\\/montesegale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/","og_locale":"it_IT","og_type":"article","og_title":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale","og_description":"Ripopolamento e nuova capacit\u00e0 di attrazione Il tema del ripopolamento dei piccoli comuni non pu\u00f2 limitarsi a proposte di interventi occasionali e frammentati, solitamente finalizzati a forme di sostegno economico [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/","og_site_name":"Montesegale","article_author":"https:\/\/www.facebook.com\/comunemontesegale","article_published_time":"2016-08-11T22:28:55+00:00","og_image":[{"width":1472,"height":978,"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg","type":"image\/jpeg"}],"author":"montesegale","twitter_misc":{"Scritto da":"montesegale","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/"},"author":{"name":"montesegale","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"headline":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie","datePublished":"2016-08-11T22:28:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/"},"wordCount":1238,"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/","url":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/","name":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg","datePublished":"2016-08-11T22:28:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#primaryimage","url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg","contentUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2016\/08\/INCONTRO-DELLE-GIOVANI-COPPIE.jpg","width":1472,"height":978},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/2016\/08\/12\/per-una-strategia-di-ripopolamento-dei-piccoli-comuni-che-punti-su-una-nuova-capacita-di-ospitalita-delle-giovani-coppie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"Per una strategia di ripopolamento dei piccoli comuni che punti su una nuova capacit\u00e0 di ospitalit\u00e0 delle giovani coppie"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad","name":"montesegale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","caption":"montesegale"},"sameAs":["http:\/\/www.comune.montesegale.pv.it","https:\/\/www.facebook.com\/comunemontesegale"],"url":"https:\/\/comunicacity.net\/montesegale\/author\/montesegale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/524\/revisions"}],"predecessor-version":[{"id":526,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/524\/revisions\/526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media\/525"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/categories?post=524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/tags?post=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}