{"id":655,"date":"2018-03-17T00:58:14","date_gmt":"2018-03-16T22:58:14","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?p=655"},"modified":"2018-03-17T01:12:06","modified_gmt":"2018-03-16T23:12:06","slug":"fast-ricerca-contributi-per-la-tua-impresa","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/","title":{"rendered":"Fast: ricerca contributi per la tua impresa"},"content":{"rendered":"<p><strong>Al via la collaborazione con FAST!<\/strong><br \/>\nPer un\u2019impresa che intende realizzare investimenti e nuovi progetti non \u00e8 semplice conoscere quali sono le opportunit\u00e0 di finanziamento offerte dai bandi pubblici: ancora pi\u00f9 complesso conoscere le regole e i criteri per candidarsi e richiedere contributo.<br \/>\nDocumenti da produrre, procedure da seguire, tempistiche da rispettare: tutto questo, molto spesso, porta le imprese a desistere rispetto alla possibilit\u00e0 di presentare richieste di finanziamento, che potrebbero invece essere molto utili per sostenere le attivit\u00e0 aziendali.<br \/>\nPer questo l\u2019Unione Borghi e Valli dell\u2019Oltrep\u00f2 (Comune di Borgo Priolo, Comune di Borgoratto Mormorolo, <strong>Comune di MONTESEGALE,<\/strong> Comune di Rocca Susella) intende offrire una possibilit\u00e0 in pi\u00f9 alle proprie aziende, attraverso un nuovo servizio di informazione e di supporto per la partecipazione ai bandi regionali, nazionali ed europei.<br \/>\nFAST \u2013 Finanziamenti Agevolati per lo Sviluppo Territoriale \u2013 \u00e8 infatti la nuova piattaforma online che permette di risparmiare tempo e fatica a tutti quelli che intendono conoscere e partecipare alle opportunit\u00e0 di finanziamento.<br \/>\nFAST \u00e8 uno strumento online, facilmente consultabile e sempre aggiornato con le tutte le opportunit\u00e0 di contributo.<br \/>\nOltre a fornire informazioni utili e pratiche sintesi dei bandi aperti (cosa viene finanziato? Quali settori possono partecipare? Quale percentuale di contributo viene riconosciuta?&#8230;), FAST permette anche di valutare, gratuitamente e in totale autonomia, se la propria idea progetto \u00e8 in linea con i criteri del bando, tramite un rapido servizio di check- up.<br \/>\nL\u2019utilizzo \u00e8 semplice e, compilando correttamente pochi campi, \u00e8 subito possibile avere un riscontro.<br \/>\nSe l\u2019esito del check- up \u00e8 positivo, FAST permette di avere il supporto di un team specializzato per la candidatura della richiesta di contributo; diversamente FAST segnala altre opportunit\u00e0 che possono essere valutate.<br \/>\nLa registrazione e i servizi di informazione e di check- up sono totalmente gratuiti.<\/p>\n<p><a href=\"https:\/\/fast.eurca.com\/bandicustom\/BaseLombardiaImprese\">ACCEDI AL SERVIZIO<\/a><\/p>\n<p>&nbsp;<\/p>\n<h5><strong>Puoi accedere al servizio dal sito internet del Comune di Montesegale (www.comune.montesegale.pv.it)!<\/strong><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Al via la collaborazione con FAST! Per un\u2019impresa che intende realizzare investimenti e nuovi progetti non \u00e8 semplice conoscere quali sono le opportunit\u00e0 di finanziamento offerte dai bandi pubblici: ancora [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fast: ricerca contributi per la tua impresa - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fast: ricerca contributi per la tua impresa - Montesegale\" \/>\n<meta property=\"og:description\" content=\"Al via la collaborazione con FAST! Per un\u2019impresa che intende realizzare investimenti e nuovi progetti non \u00e8 semplice conoscere quali sono le opportunit\u00e0 di finanziamento offerte dai bandi pubblici: ancora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunemontesegale\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-16T22:58:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-16T23:12:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"197\" \/>\n\t<meta property=\"og:image:height\" content=\"64\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"montesegale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"montesegale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/\"},\"author\":{\"name\":\"montesegale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"headline\":\"Fast: ricerca contributi per la tua impresa\",\"datePublished\":\"2018-03-16T22:58:14+00:00\",\"dateModified\":\"2018-03-16T23:12:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/\"},\"wordCount\":318,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/banner-fast.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/\",\"name\":\"Fast: ricerca contributi per la tua impresa - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/banner-fast.jpg\",\"datePublished\":\"2018-03-16T22:58:14+00:00\",\"dateModified\":\"2018-03-16T23:12:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/banner-fast.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/03\\\/banner-fast.jpg\",\"width\":197,\"height\":64},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/03\\\/17\\\/fast-ricerca-contributi-per-la-tua-impresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fast: ricerca contributi per la tua impresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\",\"name\":\"montesegale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"caption\":\"montesegale\"},\"sameAs\":[\"http:\\\/\\\/www.comune.montesegale.pv.it\",\"https:\\\/\\\/www.facebook.com\\\/comunemontesegale\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/author\\\/montesegale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fast: ricerca contributi per la tua impresa - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/","og_locale":"it_IT","og_type":"article","og_title":"Fast: ricerca contributi per la tua impresa - Montesegale","og_description":"Al via la collaborazione con FAST! Per un\u2019impresa che intende realizzare investimenti e nuovi progetti non \u00e8 semplice conoscere quali sono le opportunit\u00e0 di finanziamento offerte dai bandi pubblici: ancora [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/","og_site_name":"Montesegale","article_author":"https:\/\/www.facebook.com\/comunemontesegale","article_published_time":"2018-03-16T22:58:14+00:00","article_modified_time":"2018-03-16T23:12:06+00:00","og_image":[{"width":197,"height":64,"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg","type":"image\/jpeg"}],"author":"montesegale","twitter_misc":{"Scritto da":"montesegale","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/"},"author":{"name":"montesegale","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"headline":"Fast: ricerca contributi per la tua impresa","datePublished":"2018-03-16T22:58:14+00:00","dateModified":"2018-03-16T23:12:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/"},"wordCount":318,"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/","url":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/","name":"Fast: ricerca contributi per la tua impresa - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg","datePublished":"2018-03-16T22:58:14+00:00","dateModified":"2018-03-16T23:12:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#primaryimage","url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg","contentUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/03\/banner-fast.jpg","width":197,"height":64},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/03\/17\/fast-ricerca-contributi-per-la-tua-impresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"Fast: ricerca contributi per la tua impresa"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad","name":"montesegale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","caption":"montesegale"},"sameAs":["http:\/\/www.comune.montesegale.pv.it","https:\/\/www.facebook.com\/comunemontesegale"],"url":"https:\/\/comunicacity.net\/montesegale\/author\/montesegale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/655\/revisions"}],"predecessor-version":[{"id":661,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/655\/revisions\/661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media\/658"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}