{"id":669,"date":"2018-06-16T10:04:28","date_gmt":"2018-06-16T08:04:28","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?p=669"},"modified":"2018-06-16T10:05:39","modified_gmt":"2018-06-16T08:05:39","slug":"presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/","title":{"rendered":"PRESENTAZIONE LIBRO: &#8221; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&#8221;"},"content":{"rendered":"<p><strong>Sabato 16 giugno 2018<\/strong><\/p>\n<p><strong>ore 18,00<\/strong><\/p>\n<p>Sala Convegni Castello di Montesegale<\/p>\n<p>Presentazione del libro <strong>&#8220;Il silenzio delle donne: il coraggio delle parole&#8221;<\/strong><\/p>\n<p>a cura dell&#8217;<strong>Associazione C.H.I.A.R.A.<\/strong><\/p>\n<p>Introduce <strong>Antonio Morra<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 16 giugno 2018 ore 18,00 Sala Convegni Castello di Montesegale Presentazione del libro &#8220;Il silenzio delle donne: il coraggio delle parole&#8221; a cura dell&#8217;Associazione C.H.I.A.R.A. Introduce Antonio Morra<\/p>\n","protected":false},"author":49,"featured_media":670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRESENTAZIONE LIBRO: &quot; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&quot; - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESENTAZIONE LIBRO: &quot; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&quot; - Montesegale\" \/>\n<meta property=\"og:description\" content=\"Sabato 16 giugno 2018 ore 18,00 Sala Convegni Castello di Montesegale Presentazione del libro &#8220;Il silenzio delle donne: il coraggio delle parole&#8221; a cura dell&#8217;Associazione C.H.I.A.R.A. Introduce Antonio Morra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunemontesegale\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-16T08:04:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-16T08:05:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"566\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"montesegale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"montesegale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/\"},\"author\":{\"name\":\"montesegale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"headline\":\"PRESENTAZIONE LIBRO: &#8221; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&#8221;\",\"datePublished\":\"2018-06-16T08:04:28+00:00\",\"dateModified\":\"2018-06-16T08:05:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/\"},\"wordCount\":41,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/06\\\/locandina.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/\",\"name\":\"PRESENTAZIONE LIBRO: \\\" IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE\\\" - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/06\\\/locandina.jpg\",\"datePublished\":\"2018-06-16T08:04:28+00:00\",\"dateModified\":\"2018-06-16T08:05:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/06\\\/locandina.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2018\\\/06\\\/locandina.jpg\",\"width\":566,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/2018\\\/06\\\/16\\\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESENTAZIONE LIBRO: &#8221; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#\\\/schema\\\/person\\\/693dfa3414df278b06a5cfe4e90778ad\",\"name\":\"montesegale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g\",\"caption\":\"montesegale\"},\"sameAs\":[\"http:\\\/\\\/www.comune.montesegale.pv.it\",\"https:\\\/\\\/www.facebook.com\\\/comunemontesegale\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/author\\\/montesegale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRESENTAZIONE LIBRO: \" IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE\" - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/","og_locale":"it_IT","og_type":"article","og_title":"PRESENTAZIONE LIBRO: \" IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE\" - Montesegale","og_description":"Sabato 16 giugno 2018 ore 18,00 Sala Convegni Castello di Montesegale Presentazione del libro &#8220;Il silenzio delle donne: il coraggio delle parole&#8221; a cura dell&#8217;Associazione C.H.I.A.R.A. Introduce Antonio Morra","og_url":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/","og_site_name":"Montesegale","article_author":"https:\/\/www.facebook.com\/comunemontesegale","article_published_time":"2018-06-16T08:04:28+00:00","article_modified_time":"2018-06-16T08:05:39+00:00","og_image":[{"width":566,"height":800,"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg","type":"image\/jpeg"}],"author":"montesegale","twitter_misc":{"Scritto da":"montesegale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/"},"author":{"name":"montesegale","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"headline":"PRESENTAZIONE LIBRO: &#8221; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&#8221;","datePublished":"2018-06-16T08:04:28+00:00","dateModified":"2018-06-16T08:05:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/"},"wordCount":41,"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/","url":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/","name":"PRESENTAZIONE LIBRO: \" IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE\" - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg","datePublished":"2018-06-16T08:04:28+00:00","dateModified":"2018-06-16T08:05:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#primaryimage","url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg","contentUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2018\/06\/locandina.jpg","width":566,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/2018\/06\/16\/presentazioen-libro-il-silenzio-delle-donne-il-coraggio-delle-parole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"PRESENTAZIONE LIBRO: &#8221; IL SILENZIO DELLE DONNE: IL CORAGGIO DELLE PAROLE&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/montesegale\/#\/schema\/person\/693dfa3414df278b06a5cfe4e90778ad","name":"montesegale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/047ebb61dd1c6fd902a651cea2a039fe092c89403ed2f7277c778a26ebd04cce?s=96&d=mm&r=g","caption":"montesegale"},"sameAs":["http:\/\/www.comune.montesegale.pv.it","https:\/\/www.facebook.com\/comunemontesegale"],"url":"https:\/\/comunicacity.net\/montesegale\/author\/montesegale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"predecessor-version":[{"id":673,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/posts\/669\/revisions\/673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media\/670"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}