{"id":493,"date":"2016-07-14T15:36:19","date_gmt":"2016-07-14T13:36:19","guid":{"rendered":"https:\/\/comunicacity.net\/montesegale\/?post_type=turismo&#038;p=493"},"modified":"2016-08-29T16:55:59","modified_gmt":"2016-08-29T14:55:59","slug":"prodotti-de-co","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/","title":{"rendered":"Prodotti De.Co."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Montesegale Dolceborgo<\/strong><\/p>\n<p style=\"text-align: justify;\">La Denominazione Comunale \u00e8 la carta d\u2019identit\u00e0 di un prodotto, un\u2019attestazione che lega in maniera anagrafica un prodotto al luogo storico di origine. In altri termini, \u00e8 un certificato notarile contrassegnato dal Sindaco, il primo cittadino, a seguito di una delibera comunale, che certifica, con pochi e semplici parametri, il luogo di nascita e di crescita di un prodotto e che ha un forte e significativo valore identitario per una Comunit\u00e0\u201d<\/p>\n<p style=\"text-align: justify;\">(Denominazioni Comunali, Roberto de Donno).<\/p>\n<p style=\"text-align: justify;\">Montesegale \u00e8 stato il Comune pi\u00f9 attivo dell&#8217;Oltrep\u00f2 Pavese in questo ambito, non solo deliberando un regolamento e attribuendo il marchio alle sue migliori espressioni enogastronomiche, ma impegnandosi a mettere in campo le grandi possibilit\u00e0 di conservazione e promozione che la Denominazione Comunale offre.<br \/>\nProprio all&#8217;insegna di questo sforzo di approfondimento e sostegno alla produzione tipica locale, il Comune, con la collaborazione di numerose associazioni e istituzioni, ha organizzato un grande convegno, Paesaggio e prodotti De.Co. a Montesegale: il binomio paesaggio e prodotti De.Co. nel governo del territorio, esperienze di pianificazione locale, che il 24 settembre 2011 ha riunito amministratori, accademici, esperti e semplici cittadini interessati a rilanciare un territorio ricco di tradizioni ed eccellenze con l\u2019ausilio della De.Co.\u00a0Ecco allora gli autentici sapori di Montesegale, i quattro prodotti dell\u2019artigianato agroalimentare tradizionale che oggi si fregiano della De.Co.: il Pansegale, la Tr\u00easa, la Mundi\u00f6la e il Sal\u00e0am da c\u00f6ta. Quattro specialit\u00e0 che sintetizzano le due realt\u00e0 fondamentali della storia produttiva del comune: la panificazione e la produzione di insaccati da carne di maiale.<br \/>\nIl Pansegale \u00e8 un pane ottenuto dall\u2019impasto di farina di segale e comune farina di frumento, con l\u2019aggiunta di uva sultanina, fichi e noci. La lievitazione \u00e8 ottenuta esclusivamente con l\u2019uso di lievito madre, ovvero una porzione di pasta di pane preparata in precedenza, che ha accolto una colonia di lieviti, senza l\u2019ausilio di sostanze addizionate. Dal colore bruno, con una crosta irregolare e croccante, il Pansegale viene elaborato completamente a mano, grazie all\u2019esperienza maturata in anni di pratica dai sapienti fornai che rendono Montesegale una delle principali citt\u00e0 del pane italiane.<br \/>\nLa Tr\u00easa \u00e8 la lettura tipica della tradizionale micca oltrepadana. Si tratta di una pane di pasta dura, ottenuto attraverso una lavorazione manuale e una lievitazione lenta su assi di legno. Per ottenere la classica crosta croccante e una mollica bianca e morbida, la Tr\u00easa viene cotta in forni particolari di terracotta, nei quali viene inserita a fuoco spento, sfruttando il calore precedentemente immagazzinato dai mattoni refrattari. \u00c8 il classico pane da gustare con il salame di Varzi e i tanti altri insaccati tipici della Valle Ardivestra e dell\u2019Oltrep\u00f2 Pavese.\u00a0Un nome dell\u2019antica tradizione contadina per un grande salume della storia della Valle Ardivestra: la Mundi\u00f6la. Si ottiene dalla lavorazione dei muscoli cervicali del suino; il taglio di carne viene rifilato per dargli la consueta forma cilindrica, quindi \u00e8 sottoposto a salatura e speziatura per un periodo di due settimane durante le quali sono massaggiate, affinch\u00e9 gli aromi entrino nella carne. Le Mundi\u00f6le sono successivamente insaccate in budello suino e legate, asciugate per sette giorni (a temperatura e umidit\u00e0 controllate) e infine stagionate per almeno 6 mesi. Il risultato sar\u00e0 un salume gustoso e delicato, dal colore rosso vivo, attraversato da venature di grasso bianco-rosate, da abbinare ad un bonarda vivace dell\u2019Oltrep\u00f2.<br \/>\nUn classico della cucina tradizionale invernale, il Sal\u00e0am da c\u00f6ta \u00e8 un insaccato di suino prodotto artigianalmente nei laboratori di Montesegale. \u00c8 ottenuto dalla miscelazione manuale di parti magre e grasse di suino precedentemente macinate, con l\u2019aggiunta di cotenne, sale e spezie. L\u2019impasto viene insaccato in budello bovino, legato e fatto asciugare per una settimana. Il Sal\u00e0am da c\u00f6ta viene cotto lentamente in acqua non salata, sino a che le carni saranno perfettamente cotte e rese \u201cmostose\u201d, come si dice in Oltrep\u00f2, dalla parte grassa e dalle cotenne semisciolte. L\u2019autentico protagonista del prodotto finito \u00e8 il suino, grazie ad una nota aromatica, data dalle spezie, equilibrata e poco invasiva.<br \/>\nL&#8217; utima De.Co., ma non in termini di importanza, la Torta di Mandorle di Montesegale: una ricetta di circa 100 anni fa recuperata da Bertelegni Alberto \u2013 Pasticceria Pini di Godiasco. Questa torta veniva preparata per la festa patronale della Fraz. Languzzano di Montesegale dalla sua bisnonna<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montesegale Dolceborgo La Denominazione Comunale \u00e8 la carta d\u2019identit\u00e0 di un prodotto, un\u2019attestazione che lega in maniera anagrafica un prodotto al luogo storico di origine. In altri termini, \u00e8 un [&hellip;]<\/p>\n","protected":false},"featured_media":94,"parent":0,"menu_order":10,"template":"","meta":[],"class_list":["post-493","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prodotti De.Co. - Montesegale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prodotti De.Co. - Montesegale\" \/>\n<meta property=\"og:description\" content=\"Montesegale Dolceborgo La Denominazione Comunale \u00e8 la carta d\u2019identit\u00e0 di un prodotto, un\u2019attestazione che lega in maniera anagrafica un prodotto al luogo storico di origine. In altri termini, \u00e8 un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/\" \/>\n<meta property=\"og:site_name\" content=\"Montesegale\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-29T14:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/de.co_..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/\",\"name\":\"Prodotti De.Co. - Montesegale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/03\\\/de.co_..jpg\",\"datePublished\":\"2016-07-14T13:36:19+00:00\",\"dateModified\":\"2016-08-29T14:55:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/03\\\/de.co_..jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/03\\\/de.co_..jpg\",\"width\":600,\"height\":170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/turismo\\\/prodotti-de-co\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti De.Co.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/\",\"name\":\"Montesegale\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/montesegale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prodotti De.Co. - Montesegale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/","og_locale":"it_IT","og_type":"article","og_title":"Prodotti De.Co. - Montesegale","og_description":"Montesegale Dolceborgo La Denominazione Comunale \u00e8 la carta d\u2019identit\u00e0 di un prodotto, un\u2019attestazione che lega in maniera anagrafica un prodotto al luogo storico di origine. In altri termini, \u00e8 un [&hellip;]","og_url":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/","og_site_name":"Montesegale","article_modified_time":"2016-08-29T14:55:59+00:00","og_image":[{"width":600,"height":170,"url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/de.co_..jpg","type":"image\/jpeg"}],"twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/","url":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/","name":"Prodotti De.Co. - Montesegale","isPartOf":{"@id":"https:\/\/comunicacity.net\/montesegale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/de.co_..jpg","datePublished":"2016-07-14T13:36:19+00:00","dateModified":"2016-08-29T14:55:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/#primaryimage","url":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/de.co_..jpg","contentUrl":"https:\/\/comunicacity.net\/montesegale\/wp-content\/uploads\/sites\/26\/2015\/03\/de.co_..jpg","width":600,"height":170},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/montesegale\/turismo\/prodotti-de-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/montesegale\/"},{"@type":"ListItem","position":2,"name":"Prodotti De.Co."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/montesegale\/#website","url":"https:\/\/comunicacity.net\/montesegale\/","name":"Montesegale","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/montesegale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/turismo\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/types\/turismo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media\/94"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/montesegale\/wp-json\/wp\/v2\/media?parent=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}