{"id":228,"date":"2020-05-17T11:19:51","date_gmt":"2020-05-17T09:19:51","guid":{"rendered":"https:\/\/comunicacity.net\/moruzzo\/?p=228"},"modified":"2020-05-17T11:19:51","modified_gmt":"2020-05-17T09:19:51","slug":"aggiornamento-della-situazione-a-moruzzo-17-maggio-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/","title":{"rendered":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020"},"content":{"rendered":"<p>Alla data odierna, nel nostro Comune, una sola persona si trova in quarantena (contumacia) preventiva.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Alla data odierna, nel nostro Comune, una sola persona si trova in quarantena (contumacia) preventiva.<\/p>\n","protected":false},"author":312,"featured_media":149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo\" \/>\n<meta property=\"og:description\" content=\"Alla data odierna, nel nostro Comune, una sola persona si trova in quarantena (contumacia) preventiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Moruzzo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-17T09:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sindacomoruzzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacomoruzzo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/\"},\"author\":{\"name\":\"sindacomoruzzo\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/person\\\/128a2201ff08bbd0c0ce6ca052e0b065\"},\"headline\":\"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020\",\"datePublished\":\"2020-05-17T09:19:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2020\\\/04\\\/Moruzzo-Stemma.png\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/\",\"name\":\"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2020\\\/04\\\/Moruzzo-Stemma.png\",\"datePublished\":\"2020-05-17T09:19:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2020\\\/04\\\/Moruzzo-Stemma.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2020\\\/04\\\/Moruzzo-Stemma.png\",\"width\":400,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2020\\\/05\\\/17\\\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\",\"name\":\"Moruzzo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/person\\\/128a2201ff08bbd0c0ce6ca052e0b065\",\"name\":\"sindacomoruzzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"caption\":\"sindacomoruzzo\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/author\\\/sindacomoruzzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo","og_description":"Alla data odierna, nel nostro Comune, una sola persona si trova in quarantena (contumacia) preventiva.","og_url":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/","og_site_name":"Moruzzo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-17T09:19:51+00:00","og_image":[{"width":400,"height":500,"url":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png","type":"image\/png"}],"author":"sindacomoruzzo","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacomoruzzo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/"},"author":{"name":"sindacomoruzzo","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/person\/128a2201ff08bbd0c0ce6ca052e0b065"},"headline":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020","datePublished":"2020-05-17T09:19:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/"},"wordCount":21,"publisher":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/","url":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/","name":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020 - Moruzzo","isPartOf":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png","datePublished":"2020-05-17T09:19:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png","contentUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2020\/04\/Moruzzo-Stemma.png","width":400,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/moruzzo\/2020\/05\/17\/aggiornamento-della-situazione-a-moruzzo-17-maggio-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/moruzzo\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento della Situazione a Moruzzo, 17 Maggio 2020"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/moruzzo\/#website","url":"https:\/\/comunicacity.net\/moruzzo\/","name":"Moruzzo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/moruzzo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/moruzzo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/moruzzo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/person\/128a2201ff08bbd0c0ce6ca052e0b065","name":"sindacomoruzzo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","caption":"sindacomoruzzo"},"url":"https:\/\/comunicacity.net\/moruzzo\/author\/sindacomoruzzo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/comments?post=228"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/228\/revisions"}],"predecessor-version":[{"id":229,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/228\/revisions\/229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/media\/149"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/media?parent=228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/categories?post=228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/tags?post=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}