{"id":482,"date":"2021-10-19T13:22:47","date_gmt":"2021-10-19T11:22:47","guid":{"rendered":"https:\/\/comunicacity.net\/moruzzo\/?p=482"},"modified":"2021-10-19T13:22:47","modified_gmt":"2021-10-19T11:22:47","slug":"marcia-della-pace-e-della-fraternita-domenica-24-ottobre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/","title":{"rendered":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 &#8211; Domenica 24 Ottobre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-483 alignright\" src=\"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg\" alt=\"\" width=\"640\" height=\"833\" srcset=\"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg 787w, https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-230x300.jpeg 230w, https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-768x1000.jpeg 768w, https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD.jpeg 1110w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":312,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-482","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Moruzzo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-19T11:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg\" \/>\n<meta name=\"author\" content=\"sindacomoruzzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacomoruzzo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/\"},\"author\":{\"name\":\"sindacomoruzzo\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/person\\\/128a2201ff08bbd0c0ce6ca052e0b065\"},\"headline\":\"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 &#8211; Domenica 24 Ottobre\",\"datePublished\":\"2021-10-19T11:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2021\\\/10\\\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/\",\"name\":\"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2021\\\/10\\\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg\",\"datePublished\":\"2021-10-19T11:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2021\\\/10\\\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/wp-content\\\/uploads\\\/sites\\\/175\\\/2021\\\/10\\\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD.jpeg\",\"width\":1110,\"height\":1445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/2021\\\/10\\\/19\\\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 &#8211; Domenica 24 Ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\",\"name\":\"Moruzzo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/#\\\/schema\\\/person\\\/128a2201ff08bbd0c0ce6ca052e0b065\",\"name\":\"sindacomoruzzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g\",\"caption\":\"sindacomoruzzo\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/moruzzo\\\/author\\\/sindacomoruzzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo","og_url":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/","og_site_name":"Moruzzo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-19T11:22:47+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg","type":"","width":"","height":""}],"author":"sindacomoruzzo","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacomoruzzo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/"},"author":{"name":"sindacomoruzzo","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/person\/128a2201ff08bbd0c0ce6ca052e0b065"},"headline":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 &#8211; Domenica 24 Ottobre","datePublished":"2021-10-19T11:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/"},"wordCount":9,"publisher":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/","url":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/","name":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 - Domenica 24 Ottobre - Moruzzo","isPartOf":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD-787x1024.jpeg","datePublished":"2021-10-19T11:22:47+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#primaryimage","url":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD.jpeg","contentUrl":"https:\/\/comunicacity.net\/moruzzo\/wp-content\/uploads\/sites\/175\/2021\/10\/14E13626-8C3B-44CC-AC1B-AA04DA0ECDAD.jpeg","width":1110,"height":1445},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/moruzzo\/2021\/10\/19\/marcia-della-pace-e-della-fraternita-domenica-24-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/moruzzo\/"},{"@type":"ListItem","position":2,"name":"MARCIA DELLA PACE E DELLA FRATERNIT\u00c0 &#8211; Domenica 24 Ottobre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/moruzzo\/#website","url":"https:\/\/comunicacity.net\/moruzzo\/","name":"Moruzzo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/moruzzo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/moruzzo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/moruzzo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/moruzzo\/#\/schema\/person\/128a2201ff08bbd0c0ce6ca052e0b065","name":"sindacomoruzzo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/651b68331a2a527e6e30de6b9e645a4ecf183490a02dd270edc8d1c849ca37d7?s=96&d=mm&r=g","caption":"sindacomoruzzo"},"url":"https:\/\/comunicacity.net\/moruzzo\/author\/sindacomoruzzo\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/comments?post=482"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/482\/revisions"}],"predecessor-version":[{"id":484,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/posts\/482\/revisions\/484"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/media?parent=482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/categories?post=482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/moruzzo\/wp-json\/wp\/v2\/tags?post=482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}