{"id":1138,"date":"2025-07-04T09:15:52","date_gmt":"2025-07-04T07:15:52","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=1138"},"modified":"2025-07-04T11:43:17","modified_gmt":"2025-07-04T09:43:17","slug":"misure-di-contrasto-allo-spopolamento-regione-sardegna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/","title":{"rendered":"Misure di contrasto allo spopolamento Regione Sardegna"},"content":{"rendered":"<p><em>Bonus beb\u00e8 anno 2025. Avvio procedura<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Responsabile Dell\u2019Area Socio Culturale<\/p>\n<p>rende noto che<\/p>\n<p>a partire da luned\u00ec 7 luglio 2025 si potranno presentare le domande di riconoscimento del beneficio di cui alla Legge Regionale 9 marzo 2022, n. 3, art. 13, comma 2, lett. a)\u201d e Legge Regionale 5 febbraio 2024 n. 1, art. 3, comma 3, per la concessione a favore di nuclei familiari che risiedono o trasferiscono la residenza nei Comuni della Sardegna che, al 31.12.2022, abbiano popolazione compresa fra 3.000 e 5.000 abitanti di contributi per ogni figlio nato, adottato o in affido preadottivo a decorrere dal 2024.<\/p>\n<p>I requisiti per accedere al contributo per i nati nel 2025 e le modalit\u00e0 di presentazione delle istanze sono specificati nel Bando Pubblico allegato. Il Bando ed il modulo di domanda sono disponibili anche in forma cartacea presso la sede Comunale e sul sito istituzionale del Comune di Olmedo.<\/p>\n<p>Tutti i nuclei famigliari beneficiari della misura nell\u2019anno 2024 dovranno comunicare la persistenza dei requisiti di accesso anche per l\u2019anno 2025 tramite l\u2019apposito modulo di rinnovo.<\/p>\n<p>La domanda, debitamente compilata in tutte le sue parti e firmata da entrambi i genitori, corredata degli allegati richiesti, dovr\u00e0 essere presentata utilizzando esclusivamente l\u2019apposito modulo fornito dal Comune secondo una delle seguenti modalit\u00e0:<\/p>\n<ul>\n<li>via pec all\u2019indirizzo: <a href=\"mailto:protocollo@pec.comune.olmedo.ss.it\">protocollo@pec.comune.olmedo.ss.it<\/a> (scansione in un unico file pdf del modulo e di tutti gli allegati)<\/li>\n<li>consegnata a mano presso l\u2019Ufficio Protocollo dell\u2019Ente durante gli orari di apertura al pubblico.<\/li>\n<\/ul>\n<p>Le istanze si potranno presentare dal 7 luglio 2025 e fino al 10 gennaio 2026.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Comune di Olmedo proceder\u00e0 alla liquidazione del beneficio con cadenza bimestrale non appena la Regione Sardegna metter\u00e0 a disposizione le somme previste.<\/p>\n<p>&nbsp;<\/p>\n<p>Per informazioni:<\/p>\n<p>Dott.ssa Loredana Marongiu \u2013 tel. 079\/9019003 marted\u00ec e gioved\u00ec dalle 08:00 alle 14:00 e via mail all\u2019indirizzo: <a href=\"mailto:marongiu.loredana@comune.olmedo.ss.it\">marongiu.loredana@comune.olmedo.ss.it<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Il Responsabile dell\u2019Area Socio-Culturale<\/p>\n<p>Dott. Salvatore Deriu<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1164\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Informativa-privacy-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Informativa-privacy-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Informativa privacy<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1163\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Modulo-rinnovo-nati-2024-Olmedo.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Modulo-rinnovo-nati-2024-Olmedo.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo rinnovo nati 2024 Olmedo<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1165\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Modulo-nati-2025-Olmedo-1-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Modulo-nati-2025-Olmedo-1-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo nati 2025 Olmedo<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1162\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Avviso-Pubblico-Olmedo-Assegno-di-natalita-2025-signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Avviso-Pubblico-Olmedo-Assegno-di-natalita-2025-signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso Pubblico Olmedo &#8211; Assegno di natalit\u00e0 2025-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bonus beb\u00e8 anno 2025. Avvio procedura&nbsp; Descrizione&nbsp; Il Responsabile Dell\u2019Area Socio Culturale rende noto che a partire da luned\u00ec 7 luglio 2025 si potranno presentare le domande di riconoscimento del [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":1161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Misure di contrasto allo spopolamento Regione Sardegna - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misure di contrasto allo spopolamento Regione Sardegna - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Bonus beb\u00e8 anno 2025. Avvio procedura&nbsp; Descrizione&nbsp; Il Responsabile Dell\u2019Area Socio Culturale rende noto che a partire da luned\u00ec 7 luglio 2025 si potranno presentare le domande di riconoscimento del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T07:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T09:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"321\" \/>\n\t<meta property=\"og:image:height\" content=\"157\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Misure di contrasto allo spopolamento Regione Sardegna\",\"datePublished\":\"2025-07-04T07:15:52+00:00\",\"dateModified\":\"2025-07-04T09:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/\"},\"wordCount\":313,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/07\\\/Senza-titolo-2.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/\",\"name\":\"Misure di contrasto allo spopolamento Regione Sardegna - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/07\\\/Senza-titolo-2.jpeg\",\"datePublished\":\"2025-07-04T07:15:52+00:00\",\"dateModified\":\"2025-07-04T09:43:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/07\\\/Senza-titolo-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/07\\\/Senza-titolo-2.jpeg\",\"width\":321,\"height\":157},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/04\\\/misure-di-contrasto-allo-spopolamento-regione-sardegna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Misure di contrasto allo spopolamento Regione Sardegna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Misure di contrasto allo spopolamento Regione Sardegna - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/","og_locale":"it_IT","og_type":"article","og_title":"Misure di contrasto allo spopolamento Regione Sardegna - Olmedo","og_description":"Bonus beb\u00e8 anno 2025. Avvio procedura&nbsp; Descrizione&nbsp; Il Responsabile Dell\u2019Area Socio Culturale rende noto che a partire da luned\u00ec 7 luglio 2025 si potranno presentare le domande di riconoscimento del [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-04T07:15:52+00:00","article_modified_time":"2025-07-04T09:43:17+00:00","og_image":[{"width":321,"height":157,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo.jpeg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Misure di contrasto allo spopolamento Regione Sardegna","datePublished":"2025-07-04T07:15:52+00:00","dateModified":"2025-07-04T09:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/"},"wordCount":313,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo-2.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/","url":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/","name":"Misure di contrasto allo spopolamento Regione Sardegna - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo-2.jpeg","datePublished":"2025-07-04T07:15:52+00:00","dateModified":"2025-07-04T09:43:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo-2.jpeg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Senza-titolo-2.jpeg","width":321,"height":157},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/04\/misure-di-contrasto-allo-spopolamento-regione-sardegna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Misure di contrasto allo spopolamento Regione Sardegna"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002381"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=1138"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1138\/revisions"}],"predecessor-version":[{"id":1155,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1138\/revisions\/1155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/1161"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=1138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=1138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=1138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}