{"id":1174,"date":"2025-07-10T18:33:30","date_gmt":"2025-07-10T16:33:30","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=1174"},"modified":"2025-07-10T18:33:37","modified_gmt":"2025-07-10T16:33:37","slug":"bonus-idrico-integrativo-anno-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/","title":{"rendered":"Bonus Idrico Integrativo Anno 2025."},"content":{"rendered":"<p><em>E.G.A.S. (Autorit\u00e0 di gestione ambito della Sardegna) recepimento delibera del comitato istituzionale d&#8217;ambito n. 38 del 27 novembre 2020 per l&#8217;ottenimento delle agevolazioni tariffarie a carattere sociale per i titolari di utenze idriche domestiche<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Responsabile dell\u2019Area Socio Culturale<\/p>\n<p>rende noto che<\/p>\n<p>con propria Determinazione n. 491 del 10\/07\/2025 sono stati approvati gli elenchi degli idonei beneficiari, degli idonei non beneficiari e degli esclusi per l\u2019ottenimento delle agevolazioni tariffarie a carattere sociale (bonus idrico integrativo) annualit\u00e0 2025.<\/p>\n<p>L\u2019elenco dei beneficiari \u00e8 pubblicato in forma <em>omissis <\/em>al fine di salvaguardare il diritto alla riservatezza degli interessati, ai sensi del GDPR \u2013 Regolamento UE 2016\/679. I beneficiari, pertanto, dovranno fare riferimento al numero di protocollo della propria domanda.<\/p>\n<p>Avverso il citato elenco \u00e8 ammesso il ricorso scritto entro le ore 10:00 del 17\/07\/2025.<\/p>\n<p>L\u2019eventuale ricorso dovr\u00e0 essere redatto in forma scritta ed inoltrato all\u2019Ufficio del Protocollo secondo le seguenti modalit\u00e0:<\/p>\n<ul>\n<li>Raccomandata con ricevuta di ritorno, tenendo presente che &#8211; ai fini dell\u2019accoglimento &#8211; far\u00e0 fede la data di arrivo e non la data del timbro di partenza;<\/li>\n<li>Presentata a mano presso l\u2019Ufficio Protocollo dell\u2019Ente;<\/li>\n<li>Via Pec all\u2019indirizzo: <a href=\"mailto:protocollo@pec.comune.olmedo.ss.it\">protocollo@pec.comune.olmedo.ss.it<\/a>;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Per qualsiasi informazione e chiarimento:<\/p>\n<p>Dott.ssa Loredana Marongiu \u2013 079\/9019003 \u2013 Marted\u00ec e Gioved\u00ec dalle 08:00 \u2013 14:00 \u2013 <a href=\"mailto:marongiu.loredana@comune.olmedo.ss.it\">marongiu.loredana@comune.olmedo.ss.it<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Responsabile dell&#8217;AREA SOCIO CULTURALE<\/p>\n<p>Dott. Salvatore Deriu<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1179\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Graduatoria-idonei-beneficiari-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Graduatoria-idonei-beneficiari-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Graduatoria idonei beneficiari-signed<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1180\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Graduatoria-idonei-non-beneficiari-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Graduatoria-idonei-non-beneficiari-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Graduatoria idonei non beneficiari-signed<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1181\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Elenco-esclusi-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/07\/Elenco-esclusi-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Elenco esclusi-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>E.G.A.S. (Autorit\u00e0 di gestione ambito della Sardegna) recepimento delibera del comitato istituzionale d&#8217;ambito n. 38 del 27 novembre 2020 per l&#8217;ottenimento delle agevolazioni tariffarie a carattere sociale per i titolari [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1174","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bonus Idrico Integrativo Anno 2025. - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonus Idrico Integrativo Anno 2025. - Olmedo\" \/>\n<meta property=\"og:description\" content=\"E.G.A.S. (Autorit\u00e0 di gestione ambito della Sardegna) recepimento delibera del comitato istituzionale d&#8217;ambito n. 38 del 27 novembre 2020 per l&#8217;ottenimento delle agevolazioni tariffarie a carattere sociale per i titolari [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T16:33:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T16:33:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Bonus Idrico Integrativo Anno 2025.\",\"datePublished\":\"2025-07-10T16:33:30+00:00\",\"dateModified\":\"2025-07-10T16:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/\",\"name\":\"Bonus Idrico Integrativo Anno 2025. - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"datePublished\":\"2025-07-10T16:33:30+00:00\",\"dateModified\":\"2025-07-10T16:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/07\\\/10\\\/bonus-idrico-integrativo-anno-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonus Idrico Integrativo Anno 2025.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonus Idrico Integrativo Anno 2025. - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Bonus Idrico Integrativo Anno 2025. - Olmedo","og_description":"E.G.A.S. (Autorit\u00e0 di gestione ambito della Sardegna) recepimento delibera del comitato istituzionale d&#8217;ambito n. 38 del 27 novembre 2020 per l&#8217;ottenimento delle agevolazioni tariffarie a carattere sociale per i titolari [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-10T16:33:30+00:00","article_modified_time":"2025-07-10T16:33:37+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Bonus Idrico Integrativo Anno 2025.","datePublished":"2025-07-10T16:33:30+00:00","dateModified":"2025-07-10T16:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/"},"wordCount":227,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/","url":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/","name":"Bonus Idrico Integrativo Anno 2025. - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"datePublished":"2025-07-10T16:33:30+00:00","dateModified":"2025-07-10T16:33:37+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/07\/10\/bonus-idrico-integrativo-anno-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Bonus Idrico Integrativo Anno 2025."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002394"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1174\/revisions"}],"predecessor-version":[{"id":1178,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/1174\/revisions\/1178"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=1174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}