{"id":16,"date":"2024-04-24T09:45:12","date_gmt":"2024-04-24T07:45:12","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/"},"modified":"2024-04-24T09:45:12","modified_gmt":"2024-04-24T07:45:12","slug":"elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/","title":{"rendered":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024"},"content":{"rendered":"<p><em>Orari di apertura al pubblico dell\u2019Ufficio Elettorale per la sottoscrizione delle liste dei candidatie per il ritiro delle tessere elettorali<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In occasione delle prossime consultazioni elettorali per l&#8217;elezione dei membri del Parlamento Europeo spettanti all&#8217;Italia, l&#8217;Ufficio Elettorale sar\u00e0 aperto al pubblico nei giorni e negli orari indicati nel documento allegato.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/ORARI-DI-APERTURA-AL-PUBBLICO-PER-SOTTOSCRIVERE-LE-LISTE-DEI-CANDIDATI.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/ORARI-DI-APERTURA-AL-PUBBLICO-PER-SOTTOSCRIVERE-LE-LISTE-DEI-CANDIDATI.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORARI DI APERTURA AL PUBBLICO PER SOTTOSCRIVERE LE LISTE DEI CANDIDATI<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Orari di apertura al pubblico dell\u2019Ufficio Elettorale per la sottoscrizione delle liste dei candidatie per il ritiro delle tessere elettorali&nbsp; Descrizione&nbsp; In occasione delle prossime consultazioni elettorali per l&#8217;elezione dei [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":17,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-16","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Orari di apertura al pubblico dell\u2019Ufficio Elettorale per la sottoscrizione delle liste dei candidatie per il ritiro delle tessere elettorali&nbsp; Descrizione&nbsp; In occasione delle prossime consultazioni elettorali per l&#8217;elezione dei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T07:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024\",\"datePublished\":\"2024-04-24T07:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/04\\\/Senza-titolo-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/\",\"name\":\"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/04\\\/Senza-titolo-1.png\",\"datePublished\":\"2024-04-24T07:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/04\\\/Senza-titolo-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/04\\\/Senza-titolo-1.png\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/04\\\/24\\\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo","og_description":"Orari di apertura al pubblico dell\u2019Ufficio Elettorale per la sottoscrizione delle liste dei candidatie per il ritiro delle tessere elettorali&nbsp; Descrizione&nbsp; In occasione delle prossime consultazioni elettorali per l&#8217;elezione dei [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-04-24T07:45:12+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024","datePublished":"2024-04-24T07:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/","url":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/","name":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024 - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png","datePublished":"2024-04-24T07:45:12+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/04\/Senza-titolo-1.png","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/04\/24\/elezioni-dei-membri-del-parlamento-europeo-spettanti-allitalia-dell-8-e-9-giugno-2024-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Elezioni dei Membri del Parlamento Europeo spettanti all\u2019Italia dell\u2019 8 E 9 Giugno 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001751"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/17"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}