{"id":2048,"date":"2026-02-13T18:39:45","date_gmt":"2026-02-13T17:39:45","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=2048"},"modified":"2026-02-13T18:39:51","modified_gmt":"2026-02-13T17:39:51","slug":"chiusura-parziale-degli-uffici-comunali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/","title":{"rendered":"Chiusura parziale degli uffici comunali"},"content":{"rendered":"<p><em>Avviso di chiusura di alcuni uffici comunali mercoled\u00ec 18 febbraio 2025<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si informa la cittadinanza che mercoled\u00ec 18 febbraio p.v. i seguenti Uffici Comunali:<\/p>\n<p>Anagrafe Stato Civile Elettorale;<\/p>\n<p>Polizia Locale Ambiente Promozione Sportiva e Protocollo;<\/p>\n<p>Ufficio Tecnico;<\/p>\n<p>rimarranno chiusi tutto il giorno per permettere ai dipendenti di partecipare ad un corso di aggiornamento professionale obbligatorio.<\/p>\n<p>Restano aperti per eventuali necessit\u00e0 l&#8217;Ufficio Ragioneria Tributi e l&#8217;Ufficio Servizi Sociali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avviso di chiusura di alcuni uffici comunali mercoled\u00ec 18 febbraio 2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che mercoled\u00ec 18 febbraio p.v. i seguenti Uffici Comunali: Anagrafe Stato Civile Elettorale; Polizia [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":2051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiusura parziale degli uffici comunali - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiusura parziale degli uffici comunali - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Avviso di chiusura di alcuni uffici comunali mercoled\u00ec 18 febbraio 2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che mercoled\u00ec 18 febbraio p.v. i seguenti Uffici Comunali: Anagrafe Stato Civile Elettorale; Polizia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T17:39:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T17:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Chiusura parziale degli uffici comunali\",\"datePublished\":\"2026-02-13T17:39:45+00:00\",\"dateModified\":\"2026-02-13T17:39:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/\"},\"wordCount\":73,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/02\\\/avviso-chiusura-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/\",\"name\":\"Chiusura parziale degli uffici comunali - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/02\\\/avviso-chiusura-1.jpg\",\"datePublished\":\"2026-02-13T17:39:45+00:00\",\"dateModified\":\"2026-02-13T17:39:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/02\\\/avviso-chiusura-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/02\\\/avviso-chiusura-1.jpg\",\"width\":240,\"height\":252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/02\\\/13\\\/chiusura-parziale-degli-uffici-comunali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiusura parziale degli uffici comunali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiusura parziale degli uffici comunali - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/","og_locale":"it_IT","og_type":"article","og_title":"Chiusura parziale degli uffici comunali - Olmedo","og_description":"Avviso di chiusura di alcuni uffici comunali mercoled\u00ec 18 febbraio 2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che mercoled\u00ec 18 febbraio p.v. i seguenti Uffici Comunali: Anagrafe Stato Civile Elettorale; Polizia [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-13T17:39:45+00:00","article_modified_time":"2026-02-13T17:39:51+00:00","og_image":[{"width":240,"height":252,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Chiusura parziale degli uffici comunali","datePublished":"2026-02-13T17:39:45+00:00","dateModified":"2026-02-13T17:39:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/"},"wordCount":73,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/","url":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/","name":"Chiusura parziale degli uffici comunali - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg","datePublished":"2026-02-13T17:39:45+00:00","dateModified":"2026-02-13T17:39:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/02\/avviso-chiusura-1.jpg","width":240,"height":252},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/02\/13\/chiusura-parziale-degli-uffici-comunali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Chiusura parziale degli uffici comunali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002732"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=2048"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2048\/revisions"}],"predecessor-version":[{"id":2050,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2048\/revisions\/2050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/2051"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=2048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=2048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=2048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}