{"id":2229,"date":"2026-04-23T09:38:44","date_gmt":"2026-04-23T07:38:44","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=2229"},"modified":"2026-04-23T09:38:47","modified_gmt":"2026-04-23T07:38:47","slug":"festa-di-nostra-signora-di-talia-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/","title":{"rendered":"Festa di Nostra Signora di Talia 2026"},"content":{"rendered":"<p><em>Modifica della viabilit\u00e0 in occasione dei festeggiamenti di Nostra Signora di Talia ed ordinanza sindacale in merito a chiusura pomeridiana esercizi commerciali divieto di utilizzo vetro lattine regole per musica e rumori<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p class=\"isSelectedEnd\">Ci siamo! Dal <strong>30 aprile al 3 maggio<\/strong> il nostro paese si prepara a vivere uno dei momenti pi\u00f9 sentiti dell\u2019anno.<\/p>\n<p class=\"isSelectedEnd\">Per permettere a tutti di godersi la festa in sicurezza e serenit\u00e0, l\u2019Amministrazione Comunale ha adottato alcune disposizioni temporanee<\/p>\n<p class=\"isSelectedEnd\"><strong>Viabilit\u00e0<\/strong><br \/>\nSono previste modifiche alla circolazione e chiusure al traffico in alcune vie e piazze interessate dagli eventi. Invitiamo tutti a prestare attenzione alla segnaletica.<\/p>\n<p class=\"isSelectedEnd\"><strong>Attivit\u00e0 commerciali<\/strong><br \/>\nIl <strong>1 e 2 maggio<\/strong> i negozi (esclusi bar, ristoranti e attivit\u00e0 simili) saranno aperti <strong>dalle 7:30 alle 14:00<\/strong>.<\/p>\n<p class=\"isSelectedEnd\"><strong>Somministrazione alcolici<\/strong><br \/>\nNei giorni <strong>30 aprile, 1 e 2 maggio<\/strong> sar\u00e0 consentita fino alle <strong>03:00<\/strong>.<br \/>\nDopo tale orario non sar\u00e0 pi\u00f9 possibile vendere o somministrare alcolici.<\/p>\n<p class=\"isSelectedEnd\"><strong>Musica<\/strong><\/p>\n<ul data-spread=\"false\">\n<li>dalle <strong>02:00<\/strong> volume ridotto<\/li>\n<li>alle <strong>03:00<\/strong> stop alla musica<\/li>\n<\/ul>\n<p class=\"isSelectedEnd\"><strong>No vetro e lattine<\/strong><br \/>\nDalle <strong>14:00 del 30 aprile<\/strong> vietati vetro e lattine per il consumo in strada.<br \/>\nUsiamo contenitori sicuri e rispettiamo l\u2019ambiente<\/p>\n<p class=\"isSelectedEnd\"><strong>Stop ambulanti non autorizzati<\/strong><br \/>\nPer tutta la durata della festa \u00e8 vietata la vendita itinerante non autorizzata.<\/p>\n<p class=\"isSelectedEnd\"><strong>Controlli<\/strong><br \/>\nLa Polizia Locale e le Forze dell\u2019Ordine saranno presenti per garantire il rispetto delle regole.<\/p>\n<p class=\"isSelectedEnd\">\u00a0Tutti i dettagli nelle ordinanze allegate.<\/p>\n<p class=\"isSelectedEnd\"><strong>Collaboriamo tutti<\/strong> per vivere insieme una festa bella, sicura e rispettosa del nostro paese.<\/p>\n<p>Buona festa a tutti!<\/p>\n<p>L&#8217;Amministrazione Comunale<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2263\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/OR_2026_13.rtf-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/OR_2026_13.rtf-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>OR_2026_13.rtf-1<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2262\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/OR_2026_12.rtf_signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/OR_2026_12.rtf_signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>OR_2026_12.rtf_signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Modifica della viabilit\u00e0 in occasione dei festeggiamenti di Nostra Signora di Talia ed ordinanza sindacale in merito a chiusura pomeridiana esercizi commerciali divieto di utilizzo vetro lattine regole per musica [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":2261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festa di Nostra Signora di Talia 2026 - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa di Nostra Signora di Talia 2026 - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Modifica della viabilit\u00e0 in occasione dei festeggiamenti di Nostra Signora di Talia ed ordinanza sindacale in merito a chiusura pomeridiana esercizi commerciali divieto di utilizzo vetro lattine regole per musica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T07:38:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T07:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"201\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Festa di Nostra Signora di Talia 2026\",\"datePublished\":\"2026-04-23T07:38:44+00:00\",\"dateModified\":\"2026-04-23T07:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/04\\\/z-2-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/\",\"name\":\"Festa di Nostra Signora di Talia 2026 - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/04\\\/z-2-1.jpg\",\"datePublished\":\"2026-04-23T07:38:44+00:00\",\"dateModified\":\"2026-04-23T07:38:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/04\\\/z-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/04\\\/z-2-1.jpg\",\"width\":201,\"height\":251},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/04\\\/23\\\/festa-di-nostra-signora-di-talia-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa di Nostra Signora di Talia 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festa di Nostra Signora di Talia 2026 - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Festa di Nostra Signora di Talia 2026 - Olmedo","og_description":"Modifica della viabilit\u00e0 in occasione dei festeggiamenti di Nostra Signora di Talia ed ordinanza sindacale in merito a chiusura pomeridiana esercizi commerciali divieto di utilizzo vetro lattine regole per musica [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-04-23T07:38:44+00:00","article_modified_time":"2026-04-23T07:38:47+00:00","og_image":[{"width":201,"height":251,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Festa di Nostra Signora di Talia 2026","datePublished":"2026-04-23T07:38:44+00:00","dateModified":"2026-04-23T07:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/"},"wordCount":235,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/","url":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/","name":"Festa di Nostra Signora di Talia 2026 - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg","datePublished":"2026-04-23T07:38:44+00:00","dateModified":"2026-04-23T07:38:47+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/04\/z-2-1.jpg","width":201,"height":251},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/04\/23\/festa-di-nostra-signora-di-talia-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Festa di Nostra Signora di Talia 2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002839"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=2229"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2229\/revisions"}],"predecessor-version":[{"id":2233,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2229\/revisions\/2233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/2261"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=2229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=2229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}