{"id":2342,"date":"2026-05-13T13:33:48","date_gmt":"2026-05-13T11:33:48","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=2342"},"modified":"2026-05-13T13:33:52","modified_gmt":"2026-05-13T11:33:52","slug":"legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/","title":{"rendered":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026."},"content":{"rendered":"<p><em>Comunicazione importi periodo Maggio\/Dicembre 2026.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si informa che la Regione Sardegna ha autorizzato l\u2019avvio dei Piani Personalizzati ai sensi della L. 162\/98 con decorrenza dal 1\u00b0 maggio 2026. I beneficiari possono consultare l\u2019importo del finanziamento\u00a0spettante per il periodo maggio-dicembre 2026 nel file allegato; le domande sono identificate mediante il numero di protocollo attribuito in fase di presentazione dell\u2019istanza online, nella \u201c<strong><u>Ricevuta di inoltro domanda on-line\u201d<\/u><\/strong> che viene generata a fine procedura.<\/p>\n<p>Si comunica altres\u00ec che gli interessati verranno contattati telefonicamente per fissare un colloquio di monitoraggio presso gli Uffici del Servizio Sociale professionale e sottoscrizione della comunicazione del finanziamento del piano.<\/p>\n<p>Per quanto riguarda le pratiche di attivazione dei nuovi piani non presenti nel file allegato, questi verranno avviati qualora il Comune disponga della sufficiente copertura economica, seguendo l&#8217;ordine cronologico del numero di protocollo, come da disposizione della RAS.<\/p>\n<p>Pertanto, verr\u00e0 comunicato successivamente ai beneficiari in attesa di finanziamento, l\u2019eventuale data di avvio del Piano e l\u2019importo attribuito.<\/p>\n<p>Per maggiori informazioni in merito:<\/p>\n<ul>\n<li>Pedagogista Dott.ssa Maria Agostina Pinna \u2013 0799019011<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Il Responsabile dell\u2019Area Socio Culturale<\/strong><br \/>\nDott. Salvatore Deriu<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2347\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/Comunicazione-importi-L.-168-98-maggio-dicembre-2026-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/Comunicazione-importi-L.-168-98-maggio-dicembre-2026-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Comunicazione importi L. 168-98 maggio-dicembre 2026-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comunicazione importi periodo Maggio\/Dicembre 2026.&nbsp; Descrizione&nbsp; Si informa che la Regione Sardegna ha autorizzato l\u2019avvio dei Piani Personalizzati ai sensi della L. 162\/98 con decorrenza dal 1\u00b0 maggio 2026. I [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":2346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Comunicazione importi periodo Maggio\/Dicembre 2026.&nbsp; Descrizione&nbsp; Si informa che la Regione Sardegna ha autorizzato l\u2019avvio dei Piani Personalizzati ai sensi della L. 162\/98 con decorrenza dal 1\u00b0 maggio 2026. I [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:33:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T11:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"249\" \/>\n\t<meta property=\"og:image:height\" content=\"203\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Legge 162\\\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026.\",\"datePublished\":\"2026-05-13T11:33:48+00:00\",\"dateModified\":\"2026-05-13T11:33:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/\"},\"wordCount\":197,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/05\\\/index-foto-L.-162-98-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/\",\"name\":\"Legge 162\\\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/05\\\/index-foto-L.-162-98-1.jpg\",\"datePublished\":\"2026-05-13T11:33:48+00:00\",\"dateModified\":\"2026-05-13T11:33:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/05\\\/index-foto-L.-162-98-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2026\\\/05\\\/index-foto-L.-162-98-1.jpg\",\"width\":249,\"height\":203},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2026\\\/05\\\/13\\\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legge 162\\\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo","og_description":"Comunicazione importi periodo Maggio\/Dicembre 2026.&nbsp; Descrizione&nbsp; Si informa che la Regione Sardegna ha autorizzato l\u2019avvio dei Piani Personalizzati ai sensi della L. 162\/98 con decorrenza dal 1\u00b0 maggio 2026. I [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-05-13T11:33:48+00:00","article_modified_time":"2026-05-13T11:33:52+00:00","og_image":[{"width":249,"height":203,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026.","datePublished":"2026-05-13T11:33:48+00:00","dateModified":"2026-05-13T11:33:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/"},"wordCount":197,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/","url":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/","name":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026. - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg","datePublished":"2026-05-13T11:33:48+00:00","dateModified":"2026-05-13T11:33:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2026\/05\/index-foto-L.-162-98-1.jpg","width":249,"height":203},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2026\/05\/13\/legge-162-1998-piani-personalizzati-di-sostegno-a-favore-di-persone-con-disabilita-grave-programma-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Legge 162\/1998 \u2013 Piani personalizzati di sostegno a favore di persone con disabilit\u00e0 grave \u2013 Programma 2026."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002890"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=2342"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2342\/revisions"}],"predecessor-version":[{"id":2345,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/2342\/revisions\/2345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/2346"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=2342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=2342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=2342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}