{"id":321,"date":"2024-09-26T15:52:21","date_gmt":"2024-09-26T13:52:21","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=321"},"modified":"2024-09-26T15:52:22","modified_gmt":"2024-09-26T13:52:22","slug":"carta-dedicata-a-te-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/","title":{"rendered":"Carta dedicata a te 2024"},"content":{"rendered":"<p><em>elenco dei beneficiari<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Di seguito si pubblica la lista trasmessa dall\u2019Inps dei beneficiari della \u201cCarta Dedicata a Te\u201d 2024 &#8211; fondo istituito per l\u2019acquisto di beni alimentari di prima necessit\u00e0.<\/p>\n<p>Al fine di garantire il diritto alla riservatezza dei cittadini beneficiari della misura, i suddetti dovranno riconoscersi in base al proprio identificativo Isee-Dsu. Si comunica che i beneficiari del 2023 e presenti anche nella lista 2024, riceveranno direttamente l\u2019accredito sulla vecchia carta di Poste Italiane.<\/p>\n<p>Tutti i beneficiari riceveranno una comunicazione da parte dell&#8217;Ufficio Servizi Sociali presso il proprio indirizzo di residenza; i nuovi beneficiari dovranno presentarsi muniti di tale comunicazione presso l\u2019Ufficio Postale per il ritiro della carta in oggetto.<\/p>\n<p>Qualora i beneficiari del 2023 e presenti anche nella lista 2024 non siano pi\u00f9 in possesso della Carta Dedicata a Te ne potranno richiedere la sostituzione presso l\u2019Ufficio Postale presentando allo sportello:<\/p>\n<ul>\n<li>un documento di identit\u00e0 in corso di validit\u00e0;<\/li>\n<li>il Codice Fiscale\/Tessera Sanitaria;<\/li>\n<li>la denuncia presentata all\u2019Autorit\u00e0 Giudiziaria o di Pubblica Sicurezza.<\/li>\n<\/ul>\n<p>Si precisa che per ogni ulteriore informazione in merito all&#8217;esclusione dal suddetto beneficio andr\u00e0 chiesta ad Inps.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_328\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/Lista-DSU-beneficiari-selezionati.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/Lista-DSU-beneficiari-selezionati.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Lista DSU beneficiari selezionati<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>elenco dei beneficiari&nbsp; Descrizione&nbsp; Di seguito si pubblica la lista trasmessa dall\u2019Inps dei beneficiari della \u201cCarta Dedicata a Te\u201d 2024 &#8211; fondo istituito per l\u2019acquisto di beni alimentari di prima [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":327,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta dedicata a te 2024 - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta dedicata a te 2024 - Olmedo\" \/>\n<meta property=\"og:description\" content=\"elenco dei beneficiari&nbsp; Descrizione&nbsp; Di seguito si pubblica la lista trasmessa dall\u2019Inps dei beneficiari della \u201cCarta Dedicata a Te\u201d 2024 &#8211; fondo istituito per l\u2019acquisto di beni alimentari di prima [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T13:52:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T13:52:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Carta dedicata a te 2024\",\"datePublished\":\"2024-09-26T13:52:21+00:00\",\"dateModified\":\"2024-09-26T13:52:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/\"},\"wordCount\":190,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/09\\\/carta-dedicata-a-te.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/\",\"name\":\"Carta dedicata a te 2024 - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/09\\\/carta-dedicata-a-te.jpg\",\"datePublished\":\"2024-09-26T13:52:21+00:00\",\"dateModified\":\"2024-09-26T13:52:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/09\\\/carta-dedicata-a-te.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2024\\\/09\\\/carta-dedicata-a-te.jpg\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/09\\\/26\\\/carta-dedicata-a-te-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta dedicata a te 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta dedicata a te 2024 - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Carta dedicata a te 2024 - Olmedo","og_description":"elenco dei beneficiari&nbsp; Descrizione&nbsp; Di seguito si pubblica la lista trasmessa dall\u2019Inps dei beneficiari della \u201cCarta Dedicata a Te\u201d 2024 &#8211; fondo istituito per l\u2019acquisto di beni alimentari di prima [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-26T13:52:21+00:00","article_modified_time":"2024-09-26T13:52:22+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Carta dedicata a te 2024","datePublished":"2024-09-26T13:52:21+00:00","dateModified":"2024-09-26T13:52:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/"},"wordCount":190,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/","url":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/","name":"Carta dedicata a te 2024 - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg","datePublished":"2024-09-26T13:52:21+00:00","dateModified":"2024-09-26T13:52:22+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/09\/carta-dedicata-a-te.jpg","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/09\/26\/carta-dedicata-a-te-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Carta dedicata a te 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001966"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/321\/revisions"}],"predecessor-version":[{"id":324,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/321\/revisions\/324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/327"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}