{"id":37,"date":"2024-05-14T17:29:29","date_gmt":"2024-05-14T15:29:29","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=37"},"modified":"2025-01-17T11:56:33","modified_gmt":"2025-01-17T10:56:33","slug":"bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/","title":{"rendered":"Bando concessione in uso impianti sportivi stagione 2024 &#8211; 2025"},"content":{"rendered":"<p><em>Avviso per la presentazione delle domande per l\u2019uso degli impianti sportivi comunali Stagione Agonistica 2024\/2025<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<article id=\"descrizione\" class=\"it-page-section anchor-offset\">\n<div class=\"richtext-wrapper titillium\">\n<h3>La responsabile dell\u2019area Ambiente Vigilanza e Promozione Sportiva<\/h3>\n<p>rende noto che con determinazione n\u00b0 316 del 14\/05\/2024 \u00e8 stato approvato il bando per la concessione degli impianti sportivi comunali a gestione diretta del Comune, secondo le disposizioni del vigente Regolamento Comunale di gestione degli impianti sportivi comunali, approvato con deliberazione del Consiglio Comunale n. 38 del 30.12.2005. La durata della concessione in uso delle strutture sportive sar\u00e0 di un (1) anno.<\/p>\n<p>Gli impianti sportivi comunali oggetto di concessione sono i seguenti:<\/p>\n<ol>\n<li>Campo Sportivo Prolungamento Corso Kennedy \u201cCaddeo Pintore\u201d\n<ul>\n<li>Campo da Calcio;<\/li>\n<li>Palestre coperte A e B;<\/li>\n<li>Campo da tennis al coperto;<\/li>\n<li>Tensostruttura polivalente;<\/li>\n<li>Annesso terreno per mountain-bike;<\/li>\n<\/ul>\n<\/li>\n<li>Palestra Scuole Medie Via Emilio Lussu;\n<ul>\n<li>Attivit\u00e0 pomeridiane di pallavolo;<\/li>\n<li>Basket;<\/li>\n<li>Ginnastica ritmica;<\/li>\n<li>Altre attivit\u00e0;<\/li>\n<\/ul>\n<\/li>\n<li>Campo sportivo \u201cLuigi Deriu\u201d;\n<ul>\n<li>Campo da Baseball;<\/li>\n<li>Annesso circuito mountain-bike;<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p>Le domande regolarmente compilate nell\u2019apposito modulo predisposto dall\u2019Ufficio, potranno essere presentate direttamente all\u2019ufficio protocollo o per posta certificata all\u2019indirizzo: protocollo@pec.comune.olmedo.ss.it entro il giorno 15 luglio 2024.<\/p>\n<p>In regime transitorio restano validi gli orari precedentemente stabiliti.<\/p>\n<p><strong>Le istanze presentate in altra modalit\u00e0 non saranno prese in considerazione.<\/strong><\/p>\n<p>La Responsabile dell&#8217;Area<\/p>\n<p>Vigilanza, Ambiente e Promozione Sportiva<\/p>\n<p>dott.ssa Edvige Strada<\/p>\n<\/div>\n<\/article>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_703\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/BANDO-CONCESSIONE-IMPIANTI-SPORTIVI-COMUNALI-2024.2025-signed-signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/BANDO-CONCESSIONE-IMPIANTI-SPORTIVI-COMUNALI-2024.2025-signed-signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>BANDO-CONCESSIONE-IMPIANTI-SPORTIVI-COMUNALI-2024.2025-signed-signed<\/a><\/li>\n<li><a id=\"wpba_attachment_list_704\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/ALL.3-DICHIARAZIONE-ASSUNZIONE-RESPONSABILITA.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/ALL.3-DICHIARAZIONE-ASSUNZIONE-RESPONSABILITA.docx', '_system'); return false;\"><i class='icon attachment'><\/i>ALL.3-DICHIARAZIONE-ASSUNZIONE-RESPONSABILITA&#8217;<\/a><\/li>\n<li><a id=\"wpba_attachment_list_705\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/ALL.-2-ISTANZA.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/ALL.-2-ISTANZA.docx', '_system'); return false;\"><i class='icon attachment'><\/i>ALL.-2-ISTANZA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso per la presentazione delle domande per l\u2019uso degli impianti sportivi comunali Stagione Agonistica 2024\/2025&nbsp; Descrizione&nbsp; La responsabile dell\u2019area Ambiente Vigilanza e Promozione Sportiva rende noto che con determinazione n\u00b0 [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-37","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Avviso per la presentazione delle domande per l\u2019uso degli impianti sportivi comunali Stagione Agonistica 2024\/2025&nbsp; Descrizione&nbsp; La responsabile dell\u2019area Ambiente Vigilanza e Promozione Sportiva rende noto che con determinazione n\u00b0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-14T15:29:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T10:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/05\/images.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Bando concessione in uso impianti sportivi stagione 2024 &#8211; 2025\",\"datePublished\":\"2024-05-14T15:29:29+00:00\",\"dateModified\":\"2025-01-17T10:56:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/\"},\"wordCount\":218,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/images.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/\",\"name\":\"Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/images.jpeg\",\"datePublished\":\"2024-05-14T15:29:29+00:00\",\"dateModified\":\"2025-01-17T10:56:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/images.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/images.jpeg\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/05\\\/14\\\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANDO CONCESSIONE IN USO IMPIANTI SPORTIVI STAGIONE 2024 &#8211; 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo","og_description":"Avviso per la presentazione delle domande per l\u2019uso degli impianti sportivi comunali Stagione Agonistica 2024\/2025&nbsp; Descrizione&nbsp; La responsabile dell\u2019area Ambiente Vigilanza e Promozione Sportiva rende noto che con determinazione n\u00b0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-05-14T15:29:29+00:00","article_modified_time":"2025-01-17T10:56:33+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/05\/images.jpeg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Bando concessione in uso impianti sportivi stagione 2024 &#8211; 2025","datePublished":"2024-05-14T15:29:29+00:00","dateModified":"2025-01-17T10:56:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/"},"wordCount":218,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/images.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/","url":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/","name":"Bando concessione in uso impianti sportivi stagione 2024 - 2025 - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/images.jpeg","datePublished":"2024-05-14T15:29:29+00:00","dateModified":"2025-01-17T10:56:33+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/images.jpeg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/images.jpeg","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/05\/14\/bando-concessione-in-uso-impianti-sportivi-stagione-2024-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"BANDO CONCESSIONE IN USO IMPIANTI SPORTIVI STAGIONE 2024 &#8211; 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001792"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":701,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/37\/revisions\/701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/702"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}