{"id":546,"date":"2024-12-11T09:01:03","date_gmt":"2024-12-11T08:01:03","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=546"},"modified":"2025-01-17T11:41:45","modified_gmt":"2025-01-17T10:41:45","slug":"borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/","title":{"rendered":"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico).  approvazione graduatoria"},"content":{"rendered":"<p><em>comunicazione<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Responsabile dell\u2019Area Socio Culturale<\/p>\n<p>informa<\/p>\n<p>che con propria determinazione n. 814 del 10.12.2024 \u00e8 stata approvata la graduatoria degli ammessi e degli esclusi alla misura borse di studio di merito per diplomati nell\u2019A.S. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati nell\u2019anno 2023 (laurea ii livello o a ciclo unico), in favore degli studenti residenti presso il comune di Olmedo.<\/p>\n<p>la graduatoria, allegata al presente avviso, viene pubblicata in forma <em>omissis<\/em> al fine di salvaguardare il diritto alla riservatezza degli interessati, ai sensi del GDPR &#8211; regolamento UE 2016\/679. i beneficiari, pertanto, dovranno fare riferimento al numero di protocollo della propria domanda.<\/p>\n<p>avverso la citata graduatoria \u00e8 ammesso il ricorso scritto entro le ore 10:00 del 13\/12\/2024. in assenza di ricorsi, la graduatoria diverr\u00e0 esecutiva alle ore 10:01 del 13\/12\/2024.<\/p>\n<p>l\u2019eventuale ricorso dovr\u00e0 essere redatto in forma scritta ed inoltrato all\u2019ufficio protocollo dell\u2019ente secondo le seguenti modalit\u00e0:<br \/>\n&#8211; raccomandata con ricevuta di ritorno, tenendo presente che &#8211; ai fini dell\u2019accoglimento &#8211; far\u00e0 fede la data di arrivo e non la data del timbro di partenza;<br \/>\n&#8211; a mano presso l\u2019ufficio protocollo dell\u2019ente;<br \/>\n&#8211; via pec all\u2019indirizzo: <a href=\"mailto:protocollo@pec.comune.olmedo.ss.it\">protocollo@pec.comune.olmedo.ss.it<\/a>.<\/p>\n<p>per informazioni:<br \/>\nResponsabile dell&#8217;Area Socio Culturale Dott. Salvatore Deriu 079\/9019017<\/p>\n<p>referente Pubblica Istruzione Dott.ssa Antonella Gallo 079\/9019009<\/p>\n<p>Il Responsabile dell\u2019Area Socio Culturale<br \/>\nDott. Salvatore Deriu<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_631\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/Allegato-A-per-pubblicazione-signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/Allegato-A-per-pubblicazione-signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Allegato A per pubblicazione-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>comunicazione&nbsp; Descrizione&nbsp; Il Responsabile dell\u2019Area Socio Culturale informa che con propria determinazione n. 814 del 10.12.2024 \u00e8 stata approvata la graduatoria degli ammessi e degli esclusi alla misura borse di [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo\" \/>\n<meta property=\"og:description\" content=\"comunicazione&nbsp; Descrizione&nbsp; Il Responsabile dell\u2019Area Socio Culturale informa che con propria determinazione n. 814 del 10.12.2024 \u00e8 stata approvata la graduatoria degli ammessi e degli esclusi alla misura borse di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T08:01:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T10:41:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/12\/borse-di-studio-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Borse di studio di merito per diplomati nell\u2019a.s. 2023\\\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria\",\"datePublished\":\"2024-12-11T08:01:03+00:00\",\"dateModified\":\"2025-01-17T10:41:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/\"},\"wordCount\":254,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/borse-di-studio-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/\",\"name\":\"Borse di studio di merito per diplomati nell\u2019a.s. 2023\\\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/borse-di-studio-1.jpg\",\"datePublished\":\"2024-12-11T08:01:03+00:00\",\"dateModified\":\"2025-01-17T10:41:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/borse-di-studio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/borse-di-studio-1.jpg\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2024\\\/12\\\/11\\\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BORSE DI STUDIO DI MERITO PER DIPLOMATI NELL\u2019A.S. 2023\\\/2024 (SCUOLA SECONDARIA DI PRIMO E SECONDO GRADO) E LAUREATI ANNO 2023 (LAUREA II LIVELLO O A CICLO UNICO). APPROVAZIONE GRADUATORIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/","og_locale":"it_IT","og_type":"article","og_title":"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo","og_description":"comunicazione&nbsp; Descrizione&nbsp; Il Responsabile dell\u2019Area Socio Culturale informa che con propria determinazione n. 814 del 10.12.2024 \u00e8 stata approvata la graduatoria degli ammessi e degli esclusi alla misura borse di [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-11T08:01:03+00:00","article_modified_time":"2025-01-17T10:41:45+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2024\/12\/borse-di-studio-1-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria","datePublished":"2024-12-11T08:01:03+00:00","dateModified":"2025-01-17T10:41:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/"},"wordCount":254,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/borse-di-studio-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/","url":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/","name":"Borse di studio di merito per diplomati nell\u2019a.s. 2023\/2024 (scuola secondaria di primo e secondo grado) e laureati anno 2023 (laurea ii livello o a ciclo unico). approvazione graduatoria - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/borse-di-studio-1.jpg","datePublished":"2024-12-11T08:01:03+00:00","dateModified":"2025-01-17T10:41:45+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/borse-di-studio-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/borse-di-studio-1.jpg","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2024\/12\/11\/borse-di-studio-di-merito-per-diplomati-nella-s-2023-2024-scuola-secondaria-di-primo-e-secondo-grado-e-laureati-anno-2023-laurea-ii-livello-o-a-ciclo-unico-approvazione-graduatoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"BORSE DI STUDIO DI MERITO PER DIPLOMATI NELL\u2019A.S. 2023\/2024 (SCUOLA SECONDARIA DI PRIMO E SECONDO GRADO) E LAUREATI ANNO 2023 (LAUREA II LIVELLO O A CICLO UNICO). APPROVAZIONE GRADUATORIA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002124"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=546"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/546\/revisions"}],"predecessor-version":[{"id":549,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/546\/revisions\/549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/630"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}