{"id":600,"date":"2025-01-07T08:06:54","date_gmt":"2025-01-07T07:06:54","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/"},"modified":"2025-01-07T09:49:00","modified_gmt":"2025-01-07T08:49:00","slug":"albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/","title":{"rendered":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni"},"content":{"rendered":"<p><em>\u00c8 in pubblicazione il nuovo modulo da utilizzare per la prima iscrizione delle associazione\/societ\u00e0 sportive all\u2019Albo Comunale.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Le domande devono essere presentate entro il 28.02.2024.<\/p>\n<p><strong>N.B. Al fine di riorganizzare l\u2019area Promozione Sportiva si chiede cortesemente anche alle associazioni che hanno gi\u00e0 presentato istanza negli anni precedenti con diversa modulistica e che non hanno in corso variazioni societarie, di presentarla ex novo mediante l\u2019utilizzo dell\u2019attuale modulo, predisposto per le nuove iscrizioni.<\/strong><\/p>\n<p>L\u2019iscrizione delle nuove societ\u00e0 e associazioni all\u2019Albo, oltre a consentire la formazione dell\u2019Anagrafe delle Associazioni e Societ\u00e0 sportive presenti sul territorio comunale,\u00a0<strong>costituisce requisito indispensabile<\/strong>\u00a0per poter:<\/p>\n<ul>\n<li>utilizzare gli Impianti sportivi comunali;<\/li>\n<li>beneficiare di eventuali contributi finanziari concessi dal Comune di Olmedo o di altre analoghe sovvenzioni o agevolazioni;<\/li>\n<li>accedere al Patrocinio del Comune per manifestazioni e\/o iniziative promosse dall\u2019Associazione\/Societ\u00e0 sportiva<\/li>\n<\/ul>\n<p>Possono presentare domanda di iscrizione, le societ\u00e0 e associazioni sportive che possiedono i seguenti requisiti:<\/p>\n<ul>\n<li>Sede legale nel Comune di Olmedo o comuni limitrofi, come da regolamento comunale;<\/li>\n<li>essere affiliate alle Federazioni sportive del Coni o agli Enti di promozione sportiva da essi riconosciuti;<\/li>\n<li>non perseguire scopi di lucro;<\/li>\n<li>essere regolarmente iscritte registro nazionale delle Societ\u00e0 sportive, di cui al D. lgs.39\/2021.<\/li>\n<\/ul>\n<p>Il Servizio Vigilanza Ambiente e Promozione Sportiva \u00a0provveder\u00e0 a inserire le nuove istanze di iscrizione presentate e verificare le eventuali segnalazioni di integrazioni o modifiche intervenute nelle Associazioni\/ Societ\u00e0 sportive ed aggiornare con cadenza semestrale l\u2019Albo Comunale delle Societ\u00e0 sportive.<\/p>\n<p><strong>Allegati:<\/strong><\/p>\n<p><strong>Societ\u00e0 sportive Modulo istanza<\/strong><\/p>\n<p><strong>Modulo Trattamento dei dati<\/strong><\/p>\n<p><strong>Avviso<\/strong>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.olmedo.ss.it\/wp-content\/uploads\/2025\/01\/sport-1.jpg' alt='image'><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_607\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/INFORMATIVA-PRIVACY-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/INFORMATIVA-PRIVACY-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>INFORMATIVA PRIVACY<\/a><\/li>\n<li><a id=\"wpba_attachment_list_608\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/Avviso-apertura-termini-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/Avviso-apertura-termini-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso apertura termini<\/a><\/li>\n<li><a id=\"wpba_attachment_list_609\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/modulo-iscrizione-albo-comunale-delle-associazioni-sportive-1.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/modulo-iscrizione-albo-comunale-delle-associazioni-sportive-1.doc', '_system'); return false;\"><i class='icon attachment'><\/i>modulo iscrizione albo comunale delle associazioni sportive<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 in pubblicazione il nuovo modulo da utilizzare per la prima iscrizione delle associazione\/societ\u00e0 sportive all\u2019Albo Comunale.&nbsp; Descrizione&nbsp; Le domande devono essere presentate entro il 28.02.2024. N.B. Al fine di [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":606,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo\" \/>\n<meta property=\"og:description\" content=\"\u00c8 in pubblicazione il nuovo modulo da utilizzare per la prima iscrizione delle associazione\/societ\u00e0 sportive all\u2019Albo Comunale.&nbsp; Descrizione&nbsp; Le domande devono essere presentate entro il 28.02.2024. N.B. Al fine di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T07:06:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-07T08:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni\",\"datePublished\":\"2025-01-07T07:06:54+00:00\",\"dateModified\":\"2025-01-07T08:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/\"},\"wordCount\":274,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/sport-1-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/\",\"name\":\"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/sport-1-1.jpg\",\"datePublished\":\"2025-01-07T07:06:54+00:00\",\"dateModified\":\"2025-01-07T08:49:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/sport-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/01\\\/sport-1-1.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/01\\\/07\\\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/","og_locale":"it_IT","og_type":"article","og_title":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo","og_description":"\u00c8 in pubblicazione il nuovo modulo da utilizzare per la prima iscrizione delle associazione\/societ\u00e0 sportive all\u2019Albo Comunale.&nbsp; Descrizione&nbsp; Le domande devono essere presentate entro il 28.02.2024. N.B. Al fine di [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-01-07T07:06:54+00:00","article_modified_time":"2025-01-07T08:49:00+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni","datePublished":"2025-01-07T07:06:54+00:00","dateModified":"2025-01-07T08:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/"},"wordCount":274,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/","url":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/","name":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg","datePublished":"2025-01-07T07:06:54+00:00","dateModified":"2025-01-07T08:49:00+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/01\/sport-1-1.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/01\/07\/albo-comunale-delle-societa-e-associazioni-sportive-modulo-per-nuove-iscrizioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Albo Comunale delle societ\u00e0 e associazioni sportive: modulo per nuove iscrizioni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002155"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":605,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/600\/revisions\/605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/606"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}