{"id":771,"date":"2025-02-19T10:23:51","date_gmt":"2025-02-19T09:23:51","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=771"},"modified":"2025-02-19T10:25:14","modified_gmt":"2025-02-19T09:25:14","slug":"barriere-architettoniche","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/","title":{"rendered":"Barriere architettoniche"},"content":{"rendered":"<p><em>Aggiornamento del bando permanente relativo alla \u201cConcessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati  &#8211; Annualit\u00e0 2025\u201d. <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>IL RESPONSABILE DELL\u2019AREA TECNICA<br \/>\nVista la Legge 9 gennaio 1989, n. 13, e la legge regionale 30 agosto 1991, n. 32. Concessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati.<br \/>\nInforma che l&#8217;Assessorato dei Lavori Pubblici della Regione Sardegna, con propria Determinazione n\u00b01605\/2024, ha pubblicato l&#8217;aggiornamento del bando permanente relativo alla \u201cConcessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati  &#8211; Annualit\u00e0 2025\u201d. L\u2019aggiornamento, annuale, rettifica gli importi relativi all&#8217;indicatore ISEE ai fini dell&#8217;inserimento nella graduatoria C.<br \/>\nAl fine di poter trasmettere alla Regione Sardegna la richiesta di partecipazione alla ripartizione del fondo, per l\u2019anno 2025, invita tutti gli interessati, portatori di handicap, con l&#8217;esigenza di provvedere nelle proprie abitazioni all\u2019abbattimento di barriere architettoniche, a presentare domanda di contributo, corredata della documentazione necessaria, al protocollo del Comune di Olmedo  entro e non oltre la data del 03.03.2025.<\/p>\n<p>Il bando ed i suoi allegati sono consultabili e scaricabili ai seguenti link:<br \/>\nhttps:\/\/www.regione.sardegna.it\/atti-bandi-archivi\/atti-amministrativi\/bandi\/170619047596083<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aggiornamento del bando permanente relativo alla \u201cConcessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati &#8211; Annualit\u00e0 2025\u201d. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barriere architettoniche - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barriere architettoniche - Olmedo\" \/>\n<meta property=\"og:description\" content=\"Aggiornamento del bando permanente relativo alla \u201cConcessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati &#8211; Annualit\u00e0 2025\u201d. &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-19T09:23:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T09:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"314\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Barriere architettoniche\",\"datePublished\":\"2025-02-19T09:23:51+00:00\",\"dateModified\":\"2025-02-19T09:25:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/\"},\"wordCount\":208,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/02\\\/Barriere-architettoniche.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/\",\"name\":\"Barriere architettoniche - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/02\\\/Barriere-architettoniche.jpg\",\"datePublished\":\"2025-02-19T09:23:51+00:00\",\"dateModified\":\"2025-02-19T09:25:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/02\\\/Barriere-architettoniche.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/02\\\/Barriere-architettoniche.jpg\",\"width\":314,\"height\":161},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/02\\\/19\\\/barriere-architettoniche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barriere architettoniche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barriere architettoniche - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/","og_locale":"it_IT","og_type":"article","og_title":"Barriere architettoniche - Olmedo","og_description":"Aggiornamento del bando permanente relativo alla \u201cConcessione di contributi per la realizzazione di opere direttamente finalizzate al superamento e all&#8217;eliminazione di barriere architettoniche negli edifici privati &#8211; Annualit\u00e0 2025\u201d. &nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-19T09:23:51+00:00","article_modified_time":"2025-02-19T09:25:14+00:00","og_image":[{"width":314,"height":161,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Barriere architettoniche","datePublished":"2025-02-19T09:23:51+00:00","dateModified":"2025-02-19T09:25:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/"},"wordCount":208,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/","url":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/","name":"Barriere architettoniche - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg","datePublished":"2025-02-19T09:23:51+00:00","dateModified":"2025-02-19T09:25:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/02\/Barriere-architettoniche.jpg","width":314,"height":161},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/02\/19\/barriere-architettoniche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"Barriere architettoniche"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002208"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/771\/revisions"}],"predecessor-version":[{"id":774,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/771\/revisions\/774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/776"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}