{"id":847,"date":"2025-03-28T10:46:15","date_gmt":"2025-03-28T09:46:15","guid":{"rendered":"https:\/\/comunicacity.net\/olmedo\/?p=847"},"modified":"2025-03-28T10:46:19","modified_gmt":"2025-03-28T09:46:19","slug":"indennita-regionale-fibromialgia-irf-annualita-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/","title":{"rendered":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2025"},"content":{"rendered":"<p><em>INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2024<br \/>\nL.R. n. 5 del 18\/01\/2019 e n. 18 del 21\/11\/2024<br \/>\nD.G.R. n. 9\/22 del 12.02.2025<br \/>\nAVVISO PUBBLICO<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>IL RESPONSABILE DELL\u2019AREA SOCIO CULTURALE<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>RENDE NOTO CHE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>che con propria Determinazione n. 217 del 28\/03\/2025 \u00e8 stato approvato l\u2019avviso pubblico per l\u2019ottenimento dell\u2019<strong>Indennit\u00e0 Regionale Fibromialgia (IRF) <\/strong>disposta dalla Regione Sardegna con DGR n. 9\/22 del 12.02.2025, finalizzato a facilitare sotto l\u2019aspetto economico il miglioramento della qualit\u00e0 della vita dei cittadini residenti in Sardegna affetti da Fibromialgia.<\/p>\n<p>&nbsp;<\/p>\n<p>I requisiti per accedere al contributo e le modalit\u00e0 di presentazione dell\u2019istanza sono specificati nell\u2019Avviso Pubblico allegato.<\/p>\n<p>&nbsp;<\/p>\n<p>La documentazione di spesa dell\u2019anno deve essere presentata al Comune di Olmedo, che provveder\u00e0 ad erogare il beneficio economico a seguito della verifica della stessa e nei limiti delle risorse assegnate dalla Regione.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Avviso pubblico e la modulistica sono disponibili anche in forma cartacea presso la sede Comunale.<\/p>\n<p>&nbsp;<\/p>\n<p>Per informazioni:<\/p>\n<p>Dott.ssa Pinna Maria Agostina \u2013 079\/9019011 \u2013 <a href=\"mailto:pinna.mariaagostina@comune.olmedo.ss.it\">pinna.mariaagostina@comune.olmedo.ss.it<\/a><\/p>\n<p>Dott. Salvatore Deriu &#8211; 079\/9019017 \u2013 <a href=\"mailto:deriu.salvatore@comune.olmedo.ss.it\">deriu.salvatore@comune.olmedo.ss.it<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>TERMINI PER LA PRESENTAZIONE DELLE DOMANDE<\/strong><\/p>\n<p><strong><u>DAL 28 MARZO AL 30 APRILE 2025<\/u><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>AREA SOCIO-CULTURALE<\/strong><\/p>\n<p>Il Responsabile<\/p>\n<p>Dott. Salvatore Deriu<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_854\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/AVVISO-PUBBLICO-fibromialgia-ANNO-2025-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/AVVISO-PUBBLICO-fibromialgia-ANNO-2025-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO PUBBLICO fibromialgia ANNO 2025-signed<\/a><\/li>\n<li><a id=\"wpba_attachment_list_855\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Modulo-domanda-rinnovo-Fibromialgia-anno-2025-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Modulo-domanda-rinnovo-Fibromialgia-anno-2025-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo domanda rinnovo &#8211; Fibromialgia &#8211; anno 2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_856\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Modulo-nuova-domanda-Fibromialgia-anno-2025-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Modulo-nuova-domanda-Fibromialgia-anno-2025-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo nuova domanda &#8211; Fibromialgia &#8211; anno 2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2024 L.R. n. 5 del 18\/01\/2019 e n. 18 del 21\/11\/2024 D.G.R. n. 9\/22 del 12.02.2025 AVVISO PUBBLICO&nbsp; Descrizione&nbsp; IL RESPONSABILE DELL\u2019AREA SOCIO CULTURALE \u00a0 [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#039; 2025 - Olmedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#039; 2025 - Olmedo\" \/>\n<meta property=\"og:description\" content=\"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2024 L.R. n. 5 del 18\/01\/2019 e n. 18 del 21\/11\/2024 D.G.R. n. 9\/22 del 12.02.2025 AVVISO PUBBLICO&nbsp; Descrizione&nbsp; IL RESPONSABILE DELL\u2019AREA SOCIO CULTURALE \u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Olmedo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-28T09:46:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-28T09:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2025\",\"datePublished\":\"2025-03-28T09:46:15+00:00\",\"dateModified\":\"2025-03-28T09:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/\"},\"wordCount\":200,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/03\\\/Fibromialgia-holos-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/\",\"name\":\"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA' 2025 - Olmedo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/03\\\/Fibromialgia-holos-1.jpg\",\"datePublished\":\"2025-03-28T09:46:15+00:00\",\"dateModified\":\"2025-03-28T09:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/03\\\/Fibromialgia-holos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/wp-content\\\/uploads\\\/sites\\\/228\\\/2025\\\/03\\\/Fibromialgia-holos-1.jpg\",\"width\":960,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/2025\\\/03\\\/28\\\/indennita-regionale-fibromialgia-irf-annualita-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/olmedo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA' 2025 - Olmedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/","og_locale":"it_IT","og_type":"article","og_title":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA' 2025 - Olmedo","og_description":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2024 L.R. n. 5 del 18\/01\/2019 e n. 18 del 21\/11\/2024 D.G.R. n. 9\/22 del 12.02.2025 AVVISO PUBBLICO&nbsp; Descrizione&nbsp; IL RESPONSABILE DELL\u2019AREA SOCIO CULTURALE \u00a0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/","og_site_name":"Olmedo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-28T09:46:15+00:00","article_modified_time":"2025-03-28T09:46:19+00:00","og_image":[{"width":960,"height":500,"url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2025","datePublished":"2025-03-28T09:46:15+00:00","dateModified":"2025-03-28T09:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/"},"wordCount":200,"publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/","url":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/","name":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA' 2025 - Olmedo","isPartOf":{"@id":"https:\/\/comunicacity.net\/olmedo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg","datePublished":"2025-03-28T09:46:15+00:00","dateModified":"2025-03-28T09:46:19+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg","contentUrl":"https:\/\/comunicacity.net\/olmedo\/wp-content\/uploads\/sites\/228\/2025\/03\/Fibromialgia-holos-1.jpg","width":960,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/olmedo\/2025\/03\/28\/indennita-regionale-fibromialgia-irf-annualita-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/olmedo\/"},{"@type":"ListItem","position":2,"name":"INDENNIT\u00c0 REGIONALE FIBROMIALGIA (IRF) ANNUALITA&#8217; 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/olmedo\/#website","url":"https:\/\/comunicacity.net\/olmedo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/olmedo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/olmedo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/olmedo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/olmedo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/olmedo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002270"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/comments?post=847"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/847\/revisions"}],"predecessor-version":[{"id":852,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/posts\/847\/revisions\/852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media\/853"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/media?parent=847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/categories?post=847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/olmedo\/wp-json\/wp\/v2\/tags?post=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}