{"id":220,"date":"2020-07-10T13:37:22","date_gmt":"2020-07-10T11:37:22","guid":{"rendered":"https:\/\/comunicacity.net\/osoppo\/?p=220"},"modified":"2020-07-10T13:37:22","modified_gmt":"2020-07-10T11:37:22","slug":"convocazione-del-consiglio-comunale-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/","title":{"rendered":"Convocazione del Consiglio Comunale"},"content":{"rendered":"<p>Si informa che \u00e8 convocato il Consiglio comunale in seduta pubblica di sessione ordinaria di prima convocazione presso il Municipio \u2013 Sala Consiliare il giorno <strong>16.07.2020 alle ore 20.30,<\/strong> per discutere i punti all\u2019ordine del giorno riportati in allegato:<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_221\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2020\/07\/odg.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2020\/07\/odg.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>odg<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che \u00e8 convocato il Consiglio comunale in seduta pubblica di sessione ordinaria di prima convocazione presso il Municipio \u2013 Sala Consiliare il giorno 16.07.2020 alle ore 20.30, per [&hellip;]<\/p>\n","protected":false},"author":358,"featured_media":4,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione del Consiglio Comunale - Osoppo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione del Consiglio Comunale - Osoppo\" \/>\n<meta property=\"og:description\" content=\"Si informa che \u00e8 convocato il Consiglio comunale in seduta pubblica di sessione ordinaria di prima convocazione presso il Municipio \u2013 Sala Consiliare il giorno 16.07.2020 alle ore 20.30, per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Osoppo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T11:37:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"100\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Segreteria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Segreteria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/\"},\"author\":{\"name\":\"Segreteria\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/person\\\/cdc0d32e65caf67a53a65b65d775b8f1\"},\"headline\":\"Convocazione del Consiglio Comunale\",\"datePublished\":\"2020-07-10T11:37:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/\"},\"wordCount\":40,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/wp-content\\\/uploads\\\/sites\\\/176\\\/2019\\\/12\\\/osoppo100x100.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/\",\"name\":\"Convocazione del Consiglio Comunale - Osoppo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/wp-content\\\/uploads\\\/sites\\\/176\\\/2019\\\/12\\\/osoppo100x100.jpg\",\"datePublished\":\"2020-07-10T11:37:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/wp-content\\\/uploads\\\/sites\\\/176\\\/2019\\\/12\\\/osoppo100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/wp-content\\\/uploads\\\/sites\\\/176\\\/2019\\\/12\\\/osoppo100x100.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/07\\\/10\\\/convocazione-del-consiglio-comunale-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione del Consiglio Comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\",\"name\":\"Osoppo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/person\\\/cdc0d32e65caf67a53a65b65d775b8f1\",\"name\":\"Segreteria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"caption\":\"Segreteria\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/author\\\/dpolla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione del Consiglio Comunale - Osoppo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione del Consiglio Comunale - Osoppo","og_description":"Si informa che \u00e8 convocato il Consiglio comunale in seduta pubblica di sessione ordinaria di prima convocazione presso il Municipio \u2013 Sala Consiliare il giorno 16.07.2020 alle ore 20.30, per [&hellip;]","og_url":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/","og_site_name":"Osoppo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-10T11:37:22+00:00","og_image":[{"width":100,"height":100,"url":"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg","type":"image\/jpeg"}],"author":"Segreteria","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Segreteria"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/"},"author":{"name":"Segreteria","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/person\/cdc0d32e65caf67a53a65b65d775b8f1"},"headline":"Convocazione del Consiglio Comunale","datePublished":"2020-07-10T11:37:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/"},"wordCount":40,"publisher":{"@id":"https:\/\/comunicacity.net\/osoppo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/","url":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/","name":"Convocazione del Consiglio Comunale - Osoppo","isPartOf":{"@id":"https:\/\/comunicacity.net\/osoppo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg","datePublished":"2020-07-10T11:37:22+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#primaryimage","url":"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg","contentUrl":"https:\/\/comunicacity.net\/osoppo\/wp-content\/uploads\/sites\/176\/2019\/12\/osoppo100x100.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/07\/10\/convocazione-del-consiglio-comunale-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/osoppo\/"},{"@type":"ListItem","position":2,"name":"Convocazione del Consiglio Comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/osoppo\/#website","url":"https:\/\/comunicacity.net\/osoppo\/","name":"Osoppo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/osoppo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/osoppo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/osoppo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/osoppo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/person\/cdc0d32e65caf67a53a65b65d775b8f1","name":"Segreteria","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","caption":"Segreteria"},"url":"https:\/\/comunicacity.net\/osoppo\/author\/dpolla\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/users\/358"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/220\/revisions"}],"predecessor-version":[{"id":222,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/220\/revisions\/222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/media\/4"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/media?parent=220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/categories?post=220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/tags?post=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}