{"id":249,"date":"2020-09-04T09:39:05","date_gmt":"2020-09-04T07:39:05","guid":{"rendered":"https:\/\/comunicacity.net\/osoppo\/?p=249"},"modified":"2020-09-04T09:39:05","modified_gmt":"2020-09-04T07:39:05","slug":"beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/","title":{"rendered":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia"},"content":{"rendered":"<p class=\"align-justify\">Si informa che quest\u2019anno il beneficio regionale di riduzione dei costi per i servizi di fornitura di energia elettrica legato alla Carta famiglia non verr\u00e0 attivato.<\/p>\n<p class=\"align-justify\">Alla luce della sospensione dei servizi educativi e scolastici legati all&#8217;emergenza sanitaria covid 19 e alla forte richiesta di avviare servizi dedicati ai bambini per il periodo estivo la Regione per quest\u2019anno ha deciso di finanziare e sostenere le esigenze di conciliazione dei tempi di vita e di lavoro delle famiglie, attivando il beneficio di Carta famiglia relativo all\u2019accesso ai servizi socioeducativi e di sostegno alla genitorialit\u00e0.<\/p>\n<p class=\"align-justify\"><a href=\"http:\/\/www.regione.fvg.it\/rafvg\/comunicati\/comunicato.act?dir=\/rafvg\/cms\/RAFVG\/notiziedallagiunta\/&amp;nm=20200804122605002\">http:\/\/www.regione.fvg.it\/rafvg\/comunicati\/comunicato.act?dir=\/rafvg\/cms\/RAFVG\/notiziedallagiunta\/&amp;nm=20200804122605002<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che quest\u2019anno il beneficio regionale di riduzione dei costi per i servizi di fornitura di energia elettrica legato alla Carta famiglia non verr\u00e0 attivato. Alla luce della sospensione [&hellip;]<\/p>\n","protected":false},"author":358,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-249","post","type-post","status-publish","format-standard","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo\" \/>\n<meta property=\"og:description\" content=\"Si informa che quest\u2019anno il beneficio regionale di riduzione dei costi per i servizi di fornitura di energia elettrica legato alla Carta famiglia non verr\u00e0 attivato. Alla luce della sospensione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Osoppo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T07:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/osoppo\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Segreteria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Segreteria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/\"},\"author\":{\"name\":\"Segreteria\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/person\\\/cdc0d32e65caf67a53a65b65d775b8f1\"},\"headline\":\"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia\",\"datePublished\":\"2020-09-04T07:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\"},\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/\",\"name\":\"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#website\"},\"datePublished\":\"2020-09-04T07:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/2020\\\/09\\\/04\\\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\",\"name\":\"Osoppo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/#\\\/schema\\\/person\\\/cdc0d32e65caf67a53a65b65d775b8f1\",\"name\":\"Segreteria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g\",\"caption\":\"Segreteria\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/osoppo\\\/author\\\/dpolla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo","og_description":"Si informa che quest\u2019anno il beneficio regionale di riduzione dei costi per i servizi di fornitura di energia elettrica legato alla Carta famiglia non verr\u00e0 attivato. Alla luce della sospensione [&hellip;]","og_url":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/","og_site_name":"Osoppo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-09-04T07:39:05+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/osoppo\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png","height":600,"width":1200,"type":""}],"author":"Segreteria","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Segreteria","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/"},"author":{"name":"Segreteria","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/person\/cdc0d32e65caf67a53a65b65d775b8f1"},"headline":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia","datePublished":"2020-09-04T07:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/"},"wordCount":120,"publisher":{"@id":"https:\/\/comunicacity.net\/osoppo\/#organization"},"articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/","url":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/","name":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia - Osoppo","isPartOf":{"@id":"https:\/\/comunicacity.net\/osoppo\/#website"},"datePublished":"2020-09-04T07:39:05+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/osoppo\/2020\/09\/04\/beneficio-energia-elettrica-per-i-titolari-di-carta-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/osoppo\/"},{"@type":"ListItem","position":2,"name":"BENEFICIO ENERGIA ELETTRICA per i titolari di Carta famiglia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/osoppo\/#website","url":"https:\/\/comunicacity.net\/osoppo\/","name":"Osoppo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/osoppo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/osoppo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/osoppo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/osoppo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/osoppo\/#\/schema\/person\/cdc0d32e65caf67a53a65b65d775b8f1","name":"Segreteria","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19430428d1a2df6dae2e668b515c3243a29112f0688652f541e3e232c2f71ba9?s=96&d=mm&r=g","caption":"Segreteria"},"url":"https:\/\/comunicacity.net\/osoppo\/author\/dpolla\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/users\/358"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/249\/revisions"}],"predecessor-version":[{"id":250,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/posts\/249\/revisions\/250"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/media?parent=249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/categories?post=249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/osoppo\/wp-json\/wp\/v2\/tags?post=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}